{"id":31515,"date":"2022-06-15T07:28:01","date_gmt":"2022-06-15T05:28:01","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31515"},"modified":"2022-06-15T07:28:04","modified_gmt":"2022-06-15T05:28:04","slug":"macons-peintres-fossoyeursgardien","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/macons-peintres-fossoyeursgardien\/","title":{"rendered":"Ma\u00e7ons, Peintres, Fossoyeurs,Gardien"},"content":{"rendered":"\n<p>OFFRE D&rsquo;EMPLOI DANS LES R\u00c9GIONS DE L&rsquo;ADAMAOUA ET DE L&rsquo;EST.<\/p>\n\n\n\n<p>L\u2019Organisation pour la Lutte Contre la Clandestinit\u00e9 et pour l\u2019Epanouissement de la Jeunesse Africaine (ORLUCCEJA) a vu le jour en octobre 2015 \u00e0 Ouagadougou au Burkina Faso.<\/p>\n\n\n\n<p>Cette plateforme continentale t\u00e9moigne de la volont\u00e9 de la jeunesse africaine \u00e0 vouloir combattre efficacement contre l\u2019IMMIGRATION CLANDESTINE qui est devenue l\u2019ennemi mortel du d\u00e9veloppement de notre continent.<\/p>\n\n\n\n<p>En plus des obstacles et du retard qu\u2019elle cause au d\u00e9veloppement, elle reste jusqu\u2019\u00e0 preuve du contraire le facteur le plus favorable \u00e0 la perte en vies humaines.<\/p>\n\n\n\n<p>Cette organisation dont le si\u00e8ge est \u00e0 Cotonou au Benin se trouve dans plusieurs pays d\u2019Afrique notamment le Cameroun et \u00e9volue avec des projets de masse et des projets continus.<\/p>\n\n\n\n<p>Elle vise \u00e0 booster le processus de la croissance \u00e9conomique en appelant les jeunes \u00e0 la responsabilisation \u00e0 travers de larges campagnes de sensibilisation sur l\u2019inconv\u00e9nient de la Clandestinit\u00e9 en g\u00e9n\u00e9ral.<\/p>\n\n\n\n<p>Le Bureau National du Cameroun (BNC) existe depuis le 29 juin 2018 selon l\u2019arr\u00eat\u00e9 N\u00b000000009\/A\/MINAT\/SG\/DAP\/SDLP\/SAC du 29 juin 2018 du Ministre Camerounais de l\u2019Administration Territorial.<\/p>\n\n\n\n<p>En relatif \u00e0 l\u2019actualit\u00e9, l\u2019enqu\u00eate men\u00e9e sur le terrain au Cameroun par les \u00e9quipes d\u2019ORLUCCEJA a donn\u00e9 de constater que la sensibilisation sur l\u2019hygi\u00e8ne corporelle, nutritionnelle et environnementale et l\u2019accompagnement des populations par des produits et \u00e9l\u00e9ments de premi\u00e8re n\u00e9cessit\u00e9 (Eau potable, latrines modernes, savons, gel hydro-alcoolique\u2026) restent la seule arme efficace pour non seulement combattre la pand\u00e9mie de la COVID-19, mais aussi pour \u00e9loigner de nos populations une Autre Eventuelle Epid\u00e9mie (AEE) dans les jours \u00e0 venir.<br>Le projet \u00ab POZA \u00bb est une solution \u00e9vidente \u00e0 ces deux phases.<\/p>\n\n\n\n<p>PROJET PROPRETE OBLIGE ZERO PANDEMIE\u00ab POZA \u00bb vient en r\u00e9ponse \u00e0 la lutte contre la COVID-19 et m\u00eame \u00e0 d\u2019Autres Eventuelles Epid\u00e9mies (AEE) \u00e0 travers les \u00e9l\u00e9ments fondamentaux qui sont :<\/p>\n\n\n\n<ul><li>La sensibilisation des populations ;<\/li><li>La priorisation des centres de sant\u00e9 ;<\/li><li>La mise en place des forages et des latrines ;<\/li><li>L\u2019utilisation d\u2019outils digitaux.<\/li><\/ul>\n\n\n\n<p>Ainsi, la premi\u00e8re phase consiste \u00e0 la construction des forages et des latrines publiques dans certaines r\u00e9gions du Cameroun.<\/p>\n\n\n\n<p>Ainsi, le partenaire d&rsquo;ex\u00e9cution, SOCAMAT SARL recrute des: ma\u00e7ons, peintres, fossoyeurs, gardien et autres\u2026 r\u00e9sidants dans les localit\u00e9s de Meiganga, Kentzou et Batouri.<\/p>\n\n\n\n<p>si votre profil correspond \u00e0 cette offre, veuillez envoyer votre CV + photocopie CNI au Chef de mission au 691 903 264 ou \u00e0 contact.socamat.cm@gmail.com<\/p>\n\n\n\n<p>cordialement !<\/p>\n\n\n\n<p><em>N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE D&rsquo;EMPLOI DANS LES R\u00c9GIONS DE L&rsquo;ADAMAOUA ET DE L&rsquo;EST. L\u2019Organisation pour la Lutte Contre la Clandestinit\u00e9 et pour l\u2019Epanouissement de la Jeunesse Africaine (ORLUCCEJA)&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4018],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[156,164],"louma_meta":{"emploi_title":"Ma\u00e7ons, Peintres, Fossoyeurs,Gardien","emplois_employeur":3046,"emplois_date_publication":"2022-06-15","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"contact.socamat.cm@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31515"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31515"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31515"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31515"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31515"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}