{"id":31490,"date":"2022-06-15T04:49:30","date_gmt":"2022-06-15T02:49:30","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31490"},"modified":"2022-06-15T04:49:34","modified_gmt":"2022-06-15T02:49:34","slug":"5-profils-nocea-training-institute","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/5-profils-nocea-training-institute\/","title":{"rendered":"5 Profils-NOCEA Training Institute"},"content":{"rendered":"\n<p>Recrutement \u00e0 NOCEA Training Institute (centre de r\u00e9f\u00e9rence internationale de formation en langues et formations professionnelles)<br>\ud83d\udc49\ud83c\udffe3 secr\u00e9taires commerciales bilingues: Master en langues ou linguistique et au moins 1 an d&rsquo;exp\u00e9rience<br>\ud83d\udc49\ud83c\udffe 2 personnes en charge des relations publiques: pas besoin de dipl\u00f4mes seule l&rsquo;exp\u00e9rience compte, au moins 3 ans d&rsquo;exp\u00e9rience dans les n\u00e9gociations et le marketing<br>Dossier physique uniquement \u00e0 d\u00e9poser \u00e0 la direction g\u00e9n\u00e9rale siss \u00e0 la Shell Obili, immeuble Onana face IRIC ou contacter les num\u00e9ros suivants 679592150\/691555030.<br>Demande adress\u00e9e au DG, CV, photocopie CNI et dipl\u00f4mes et\/ attestations<\/p>\n\n\n\n<p>D\u00e9lai 20 juin \u00e0 10h<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recrutement \u00e0 NOCEA Training Institute (centre de r\u00e9f\u00e9rence internationale de formation en langues et formations professionnelles)\ud83d\udc49\ud83c\udffe3 secr\u00e9taires commerciales bilingues: Master en langues ou linguistique et&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"5 Profils-NOCEA Training Institute","emplois_employeur":3046,"emplois_date_publication":"2022-06-15","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"679592150\/691555030"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31490"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31490"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31490\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31490"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31490"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31490"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}