{"id":31230,"date":"2022-06-09T02:12:22","date_gmt":"2022-06-09T00:12:22","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31230"},"modified":"2022-06-09T02:12:25","modified_gmt":"2022-06-09T00:12:25","slug":"teleconseillers-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/teleconseillers-3\/","title":{"rendered":"TELECONSEILLERS"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : TELECONSEILLERS,\ndate d'expiration : 2022-06-03,\nentreprise  : KCS,\nPays : cameroun,\nvilles : DOUALA,\ncontact pour postuler : directionkcs@gmail.com\n\nUne entreprise situ\u00e9e \u00e0 Douala-LOGPOM (TOTAL - BASSONG) recherche des t\u00e9l\u00e9conseillers hommes et femmes.<br>Vous devez avoir:<br>Un fran\u00e7ais bien soign\u00e9 \u00e0 l'oral et \u00e0 l'\u00e9crit<br>\u00eatre assidu au travail<br>Aimer travailler en \u00e9quipe<br>\u00eatre ouvert d'esprit et avoir une fibre commerciale<br>\u00eatre passionner des outils informatique et de la digitalisation<br>Avoir au minimum 21 ans<br><br>Si cette offre vous parle envoyez votre cv par email \u00e0 l'adresse directionkcs@gmail.com <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[335],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"TELECONSEILLERS","emplois_employeur":3046,"emplois_date_publication":"2022-06-09","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"directionkcs@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31230"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31230"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31230\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31230"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31230"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31230"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}