{"id":31225,"date":"2022-06-09T02:09:21","date_gmt":"2022-06-09T00:09:21","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31225"},"modified":"2022-06-09T02:09:23","modified_gmt":"2022-06-09T00:09:23","slug":"assistante-administrative-5","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/assistante-administrative-5\/","title":{"rendered":"ASSISTANTE ADMINISTRATIVE"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : ASSISTANTE ADMINISTRATIVE,\ndate d'expiration : 2022-06-03,\nentreprise  : KCS,\nPays : cameroun,\nvilles : DOUALA,\ncontact pour postuler : directionkcs@gmail.com\n\n<p>Une entreprise de la place situ\u00e9 \u00e0 c\u00f4t\u00e9 de TOTAL-BASSONG-LOGPOM\/ DOUALA, recherche une assistante administrative pour s'occuper des t\u00e2ches suivantes:<\/p> <ul> <li>Gestion de l'agenda du DG<\/li> <li>Gestion des relations fournisseurs<\/li> <li>Gestion du courrier, accueil et orientation<\/li> <li>Organisation et plannification des r\u00e9unions<\/li> <li>R\u00e9daction des courriers administratifs<\/li> <li>R\u00e9daction des contrats partenaires<\/li> <li>Gestion des relations avec les organismes publics<\/li> <li>Suivie des factures et recouvrement<\/li> <li>Gestion des achats<\/li> <li>Organisation des formations internes<\/li> <li>Etc<\/li> <\/ul> <p>Nous attendons avoir une assistante Administrative ouverte d'esprit, agile, apte \u00e0 travailler avec des outils modernes de collaboration, cr\u00e9ative, passionn\u00e9es, polyvalente pouvant passer facilement d'un sujet \u00e0 un autre, une personne avec une bonne capacit\u00e9 d'adaptation et surtout assidue. Une personne avec des pr\u00e9r\u00e9quis solides dans l'utilisation de l'outil informatique, avec un fran\u00e7ais soign\u00e9 \u00e0 l'oral et \u00e0 l'\u00e9crit, si vous \u00eates bilingue ce sera un atout.<\/p> <p>Si cette offre vous parle, Envoyez uniquement votre CV par mail \u00e0 l'adresse directionkcs@gmail.com<\/p> <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"ASSISTANTE ADMINISTRATIVE","emplois_employeur":3046,"emplois_date_publication":"2022-06-09","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"directionkcs@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31225"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31225"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31225"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31225"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31225"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}