{"id":31140,"date":"2022-06-06T15:23:44","date_gmt":"2022-06-06T13:23:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=31140"},"modified":"2022-06-06T15:23:46","modified_gmt":"2022-06-06T13:23:46","slug":"expert-business-leasing-corporate","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/expert-business-leasing-corporate\/","title":{"rendered":"EXPERT BUSINESS LEASING &#8211; CORPORATE"},"content":{"rendered":"\n<p>SCB Cameroun Groupe Attijariwafa Bank<\/p>\n\n\n\n<p>Croire en vous<\/p>\n\n\n\n<p>MISSIONS PRINCIPALES<\/p>\n\n\n\n<p>Assister le Responsable des Services Financiers Sp\u00e9cialis\u00e9s (SFS) dans l&rsquo;\u00e9laboration et le suivi de la strat\u00e9gie leasing de la filiale;<\/p>\n\n\n\n<p>Concevoir les produits\/offres de leasing pour des op\u00e9rations sp\u00e9cifiques<\/p>\n\n\n\n<p>NOUS RECRUTONS<\/p>\n\n\n\n<p>et non standard; Effectuer les rendez-vous client\u00e8le et les actions de prospection;<\/p>\n\n\n\n<p>Structurer, n\u00e9gocier et pr\u00e9parer toutes les transactions commerciales leasing afin de r\u00e9duire\/\u00e9liminer le risque pour les op\u00e9rations;<\/p>\n\n\n\n<p>\u2022 Suivre les relations avec les prestataires et principaux fournisseurs<\/p>\n\n\n\n<p>d&rsquo;\u00e9quipements en vue de d\u00e9velopper les ventes sur le leasing: Analyser les demandes de financement leasing et les pr\u00e9senter pour<\/p>\n\n\n\n<p>avis aux personnes habilit\u00e9es;<\/p>\n\n\n\n<p>Formuler des analyses et avis destin\u00e9s \u00e0 faciliter la prise de d\u00e9cision<\/p>\n\n\n\n<p>des membres du Comit\u00e9 de Cr\u00e9dit en l&rsquo;absence du Responsable<\/p>\n\n\n\n<p>Cr\u00e9dit-Bail;<\/p>\n\n\n\n<p>Assurer l&rsquo;assistance aux utilisateurs par la r\u00e9solution rapide des r\u00e9clamations des clients et des partenaires en collaboration avec les services connexes et le SAV.<\/p>\n\n\n\n<p>EXPERT BUSINESS LEASING &#8211; CORPORATE<\/p>\n\n\n\n<p>Niveau Requis:<\/p>\n\n\n\n<p>BAC +4 en Gestion Banque et Finance, etc.<\/p>\n\n\n\n<p>Exp\u00e9rience: 4 ans minimum dans le Commercial<\/p>\n\n\n\n<p>Type de contrat: CDI<\/p>\n\n\n\n<p>Date limite de r\u00e9ception des candidatures<\/p>\n\n\n\n<p>COMP\u00c9TENCES:<\/p>\n\n\n\n<p>Produits financiers, produits de leasing:<\/p>\n\n\n\n<p>Pilotage des ventes;<\/p>\n\n\n\n<p>L&rsquo;Analyse financi\u00e8re;<\/p>\n\n\n\n<p>Loi sur le cr\u00e9dit-bail;<\/p>\n\n\n\n<p>Comptabilit\u00e9 et fiscalit\u00e9 du cr\u00e9dit-bail;<\/p>\n\n\n\n<p>Proc\u00e9dures, Conformit\u00e9, Contr\u00f4le Interne; Technique d&rsquo;entretien et de n\u00e9gociation client;<\/p>\n\n\n\n<p>March\u00e9 Corporate.<\/p>\n\n\n\n<p>PROFIL:<\/p>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes: Bac + 4 minimum en Gestion Banque Finance,<\/p>\n\n\n\n<p>Comptabilit\u00e9;<\/p>\n\n\n\n<p>Exp\u00e9rience: 04 ans minimum dans l&rsquo;exploitation commercial ou \u00e0 un poste similaire dans un \u00e9tablissement financier, entreprise de taille moyenne ou de grande taille:<\/p>\n\n\n\n<p>10\/06\/2022 \u00e0 17h00<\/p>\n\n\n\n<p>Maitrise du fran\u00e7ais et\/ou l&rsquo;anglais.<\/p>\n\n\n\n<p>MODALIT\u00c9S PRATIQUES:<\/p>\n\n\n\n<p>Pour postuler, adressez votre candidature (CV actualis\u00e9 + lettre de motivation) avec pour objet &lt;&lt; Expert Business Leasing &#8211; Corporate &gt;&gt; \u00e0 l&rsquo;adresse suivante: recrutementrh@scbcameroun.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCB Cameroun Groupe Attijariwafa Bank Croire en vous MISSIONS PRINCIPALES Assister le Responsable des Services Financiers Sp\u00e9cialis\u00e9s (SFS) dans l&rsquo;\u00e9laboration et le suivi de la&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"EXPERT BUSINESS LEASING - CORPORATE","emplois_employeur":6367,"emplois_date_publication":"2022-06-06","emplois_heure_publication":"","emplois_date_cloture":"2022-06-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutementrh@scbcameroun.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31140"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=31140"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/31140\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6368"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=31140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=31140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=31140"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=31140"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=31140"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=31140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}