{"id":30667,"date":"2022-05-22T18:52:44","date_gmt":"2022-05-22T16:52:44","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=30667"},"modified":"2022-05-22T18:52:47","modified_gmt":"2022-05-22T16:52:47","slug":"teleconseillers-debutant-francophone","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/teleconseillers-debutant-francophone\/","title":{"rendered":"T\u00e9l\u00e9conseillers D\u00e9butant Francophone"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code> Titre du poste : T\u00e9l\u00e9conseillers D\u00e9butant Francophone,\ndate d'expiration : 2022-06-11,\nentreprise (existante dans notre base de donn\u00e9es) : Leaders Business call,\nPays : cameroun,\nvilles : Yaound\u00e9,\ncontact pour postuler : newcallingservice@gmail.com\n####### description du poste ###### \n<div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">Centre d'appel recrute en masse :&nbsp; T\u00c9L\u00c9CONSEILLERS EN R\u00c9CEPTION D'APPELS&nbsp;<\/div> <div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">Rattach\u00e9 au responsable de l'\u00e9quipe, votre mission consiste \u00e0 :<\/div> <div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">Analyser les dossiers client et orienter les appels vers le service concern\u00e9.salaire 500 euro&nbsp;<\/div> <div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">Vos cv a&nbsp;<\/div> <div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">&nbsp;Op\u00e9rateurs Et Op\u00e9ratrices De Saisie :Type de contrat : CDI niveau d'\u00e9tudes : niveau bac ou plus Langues :bon niveau en Francais&nbsp;<\/div> <div style=\"color: #222222;background-color: #ffffff;font-family: Roboto, RobotoDraft, Helvetica, Arial, sans-serif\">avec la Possibilit\u00e9 de travailler a domicile salaire 500 euro.<\/div> \n####### fin description ####### \n\n\nContact de l'annonceur\nnom : Ginilson V. Gomes\nEmail : genilsonvg77@gmail.com\nNum\u00e9ro de t\u00e9l\u00e9phone : 00221772537259\n\nMerci,\nLouma Jobs\n\n\u00a9 2022 Louma Jobs. All rights reserved. <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[25,335],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"T\u00e9l\u00e9conseillers D\u00e9butant Francophone","emplois_employeur":3046,"emplois_date_publication":"2022-05-22","emplois_heure_publication":"","emplois_date_cloture":"2022-05-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/30667"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=30667"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/30667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=30667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=30667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=30667"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=30667"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=30667"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=30667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}