{"id":2994,"date":"2020-05-04T14:00:43","date_gmt":"2020-05-04T12:00:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cm\/?post_type=emplois&#038;p=2994"},"modified":"2020-05-04T14:00:44","modified_gmt":"2020-05-04T12:00:44","slug":"agent-de-soutien-aux-entreprises-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2020\/agent-de-soutien-aux-entreprises-h-f\/","title":{"rendered":"Agent de soutien aux entreprises H \/ F"},"content":{"rendered":"\n<p>Description du posteR\u00e9f\u00e9rence :JUR\/0320\/002467<\/p>\n\n\n\n<p>Type de contrat :&nbsp;CDI<\/p>\n\n\n\n<p>M\u00e9tier\/Sp\u00e9cialit\u00e9 :&nbsp;Industrie<\/p>\n\n\n\n<p>Localisation g\u00e9ographique :<br>Pays : Cameroun<br>Ville : Douala, R\u00e9gion du Littoral, CM<\/p>\n\n\n\n<p><strong>Notre soci\u00e9t\u00e9 :&nbsp;<\/strong><\/p>\n\n\n\n<p>Leader en recrutement sur le continent africain, Apave International vous propose chaque semaine de nombreuses opportunit\u00e9s de carri\u00e8re au sein d&rsquo;entreprises priv\u00e9es ou publiques et d&rsquo;Institutions Internationales.<\/p>\n\n\n\n<p><strong>Mission :&nbsp;<\/strong><\/p>\n\n\n\n<ol><li>G\u00e9rer toutes les n\u00e9gociations, renouvellements et modifications de contrats commerciaux avec les fournisseurs actuels et potentiels<\/li><li>Aider l&rsquo;entreprise et l&rsquo;usine \u00e0 documenter les accords juridiques n\u00e9cessaires<\/li><li>Coordonner la base de donn\u00e9es des contrats et le syst\u00e8me d&rsquo;enregistrement<\/li><li>Soutien suppl\u00e9mentaire aux avocats selon les besoins, y compris la r\u00e9daction et la r\u00e9vision des documents juridiques, des notes de service, de la correspondance et des documents d&rsquo;appui.<\/li><li>Maintenir les termes et conditions standard \u00e0 feuilles persistantes \u00e0 utiliser par la soci\u00e9t\u00e9 dans l&rsquo;accord de base<\/li><li>Maintenir toutes les polices d&rsquo;assurance requises par la loi camerounaise et les pr\u00eateurs et assurer une couverture compl\u00e8te<\/li><li>Faciliter la fourniture d&rsquo;une assistance \/ conseils juridiques si n\u00e9cessaire, y compris mais sans s&rsquo;y limiter:<ol><li>dispute assistance;<\/li><li>assistance contractuelle g\u00e9n\u00e9rale;<\/li><li>licences;<\/li><li>financement de projets ou autres contrats financiers;<\/li><li>projets de d\u00e9veloppement et gestion de la construction;<\/li><li>questions de droit du travail.<\/li><li>Fournir toutes autres activit\u00e9s g\u00e9n\u00e9rales de gestion et d&rsquo;administration qui peuvent \u00eatre raisonnablement demand\u00e9es afin de pouvoir poursuivre ses activit\u00e9s.<\/li><\/ol><\/li><\/ol>\n\n\n\n<p>Responsabilit\u00e9s ad hoc \u00e0 l&rsquo;appui de l&rsquo;entreprise juridique, commercial et de conformit\u00e9, le cas \u00e9ch\u00e9ant<\/p>\n\n\n\n<p><strong>Profil :&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Master of Law en droit<\/li><li>3 \u00e0 5 ans au moins dans un cabinet d&rsquo;avocats ou en interne juridique, service fiscal<\/li><li>Connaissances OHADA.<\/li><li>Forte exp\u00e9rience en r\u00e9vision et r\u00e9daction de contrats<\/li><li>Exp\u00e9rience en analyse juridique approfondie et \u00e9tudes de cas<\/li><\/ul>\n\n\n\n<ul><li>Exp\u00e9riment\u00e9 avec Excel, Word, PowerPoint, etc.<\/li><li>Parle couramment l&rsquo;anglais et le fran\u00e7ais<\/li><\/ul>\n\n\n\n<p>Niveau d&rsquo;\u00e9tudes : MASTER 2 \/ BAC+5<\/p>\n\n\n\n<p>Sp\u00e9cialisation :&nbsp;Juridique \/ Fiscalit\u00e9<\/p>\n\n\n\n<p>Niveau d&rsquo;exp\u00e9rience :&nbsp;Exp\u00e9riment\u00e9 (de 3 \u00e0 5 ans)<\/p>\n\n\n\n<p>Langues :&nbsp;<br>Fran\u00e7ais&nbsp;:&nbsp;Ma\u00eetrise courante<br>Anglais&nbsp;:&nbsp;Ma\u00eetrise courante<\/p>\n\n\n\n<p>Crit\u00e8res du poste<\/p>\n\n\n\n<ul><li>Master of Law en droit<\/li><li>6 \u00e0 8 ans au moins dans un cabinet d&rsquo;avocats ou en interne juridique, service fiscal<\/li><li>Connaissances OHADA.<\/li><li>Forte exp\u00e9rience en r\u00e9vision et r\u00e9daction de contrats<\/li><li>Exp\u00e9rience en analyse juridique approfondie et \u00e9tudes de cas<\/li><\/ul>\n\n\n\n<ul><li>Exp\u00e9riment\u00e9 avec Excel, Word, PowerPoint, etc.<\/li><li>Parle couramment l&rsquo;anglais et le fran\u00e7ais<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Toutes les Offres d&#8217;emplois et les recrutements actuellement disponibles chez APAVE Cameroun.<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21,235],"tags":[107],"villes":[135],"contrats":[234],"diplomes":[161,212,159],"louma_meta":{"emploi_title":"Agent de soutien aux entreprises H \/ F","emplois_employeur":2981,"emplois_date_publication":"2020-05-04","emplois_heure_publication":"","emplois_date_cloture":"2020-06-04","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"https:\/\/application.careerbuilder1.eu\/apave\/apply\/cb1\/J3P6LS67RTNHQSSZT2V?IPath=TNJob&Job_DID=J3P6LS67RTNHQSSZT2V&SiteID=cbnsv&VID=VXD4A369B08DF311EA8812812B657083F54066IW&sc_cmp1=JS_JobDetails_ApplyNow&TN_DID=TNKD38560K16M285NSH4&language=fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/2994"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=2994"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/2994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2982"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=2994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=2994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=2994"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=2994"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=2994"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=2994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}