{"id":29798,"date":"2022-04-21T11:29:50","date_gmt":"2022-04-21T09:29:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29798"},"modified":"2022-04-21T12:02:00","modified_gmt":"2022-04-21T10:02:00","slug":"recrutement-de-commerciaux-pour-une-multinationale","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/recrutement-de-commerciaux-pour-une-multinationale\/","title":{"rendered":"Recrutement de Commerciaux pour une multinationale"},"content":{"rendered":"\n<p>Une Multinationale de la place proposant divers produits financiers sur le march\u00e9 national recrute. Le poste ouvert dans notre branche commerciale vise \u00e0 \u00e9couler les des dits produits. Ce poste exige une forte capacit\u00e9 entrepreneuriale et un savoir-faire commercial..<\/p>\n\n\n\n<p>Poste&nbsp;: Commercial<\/p>\n\n\n\n<p>Nous souhaitons une personne&nbsp;:<\/p>\n\n\n\n<ul><li>tr\u00e8s intelligente, capable de r\u00e9fl\u00e9chir de mani\u00e8re autonome et assidue\u00a0;<\/li><li>bien organis\u00e9e dans son travail\u00a0;<\/li><li>maitrise des techniques de ventes\u00a0;<\/li><li>bonne allocution et \u00e9locution\u00a0;<\/li><li>forte capacit\u00e9 de persuasion<\/li><\/ul>\n\n\n\n<p>Profils Recherch\u00e9s&nbsp;:<\/p>\n\n\n\n<ul><li>Sexe\u00a0: masculin ou f\u00e9minin\u00a0;<\/li><li>\u00e2ge\u00a0: entre 22 ans et 45 ans\u00a0;<\/li><li>niveau d\u2019\u00e9tude\u00a0: Bac (Formation offerte) Bac+2, 3  ou 5 en Action Commerciale, Communication ou Marketing<\/li><li>langue parl\u00e9e\u00a0: fran\u00e7ais ou anglais.<\/li><\/ul>\n\n\n\n<p>Si l\u2019offre vous int\u00e9resse envoyez vos CV et votre photo via le formulaire ci-joint au plus tard le 02\/05\/2022.<\/p>\n\n\n\n<p><strong>NB\u00a0:<\/strong> Seul les candidats appel\u00e9s passeront les entretiens.<\/p>\n\n\n\n<p>Lien pour postuler (Connecter vous \u00e0 votre compte google) : <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf5G5mS9aoeId_quZeuoryVpf8mxlljhPueDj390zu7cIWUeA\/viewform\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf5G5mS9aoeId_quZeuoryVpf8mxlljhPueDj390zu7cIWUeA\/viewform<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recrutement de Commerciaux pour une multinationale \u00e0 travers le cameroun dans les villes des douala, yaound\u00e9, kribi, Limbe, Bafoussam, Bamenda,bu\u00e9a, bertoua, ebolowa, maroua, garoua, ngaound\u00e9r\u00e9.<\/p>\n","protected":false},"author":1,"comment_status":"open","ping_status":"closed","template":"","categories":[251],"tags":[],"villes":[2714],"contrats":[236,234,150],"diplomes":[248,212,159],"louma_meta":{"emploi_title":"Commerciaux pour une multinationale","emplois_employeur":3046,"emplois_date_publication":"2022-04-21","emplois_heure_publication":"","emplois_date_cloture":"2022-05-02","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSf5G5mS9aoeId_quZeuoryVpf8mxlljhPueDj390zu7cIWUeA\/viewform"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29798"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29798"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29798"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29798"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29798"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}