{"id":29710,"date":"2022-04-18T14:08:52","date_gmt":"2022-04-18T12:08:52","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29710"},"modified":"2022-04-18T14:08:56","modified_gmt":"2022-04-18T12:08:56","slug":"teleconseiller-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/teleconseiller-3\/","title":{"rendered":"T\u00e9l\u00e9conseiller"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>  Titre du poste : T\u00e9l\u00e9conseiller,\ndate d'expiration : 2022-08-31,\nentreprise : Lite Call,\nPays : cameroun,\nvilles : Yaound\u00e9,\ncontact pour postuler : makaalbarn334@gmail.com\n\n<strong>OPPORTUNIT\u00c9 D'EMPLOI<\/strong> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Afin de relancer ses activit\u00e9s, l'entreprise Lite Call,&nbsp; sp\u00e9cialis\u00e9 dans le domaine de l'\u00e9mission d'appel , recrute des t\u00e9l\u00e9op\u00e9rateurs\/t\u00e9l\u00e9op\u00e9ratrices avec ou sans exp\u00e9rience dans le&nbsp; domaine du Centre d'appel ou du CPF (Campagne en cours)<\/strong><\/div> <div><strong>\u00c9tant une nouvelle structure, nous ne recrutons actuellement que 20 t\u00e9l\u00e9pros.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Mission : Vendre des produits et services suivant nos diff\u00e9rentes campagnes \u00e0 l'\u00e9tranger.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Pr\u00e9requis :<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>- \u00catre capable de franciser (whitiser)<\/strong><\/div> <div><strong>- \u00catre de bonne moralit\u00e9&nbsp;<\/strong><\/div> <div><strong>- Avoir le sens du relationnel<\/strong><\/div> <div><strong>- \u00catre dynamique<\/strong><\/div> <div><strong>- \u00catre apte \u00e0 travailler en \u00e9quipe<\/strong><\/div> <div><strong>- \u00catre&nbsp; capable de travailler sous pression<\/strong><\/div> <div><strong>- Avoir une bonne ma\u00eetrise de la langue fran\u00e7aise.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>R\u00e9mun\u00e9ration :&nbsp;<\/strong><\/div> <div><strong>Salaire de base (conditionn\u00e9 \u00e0 01 vente effectu\u00e9e) : 60.000FCFa&nbsp;&nbsp;<\/strong><\/div> <div><strong>Prime et Challenge journalier\/hebdomadaire\/mensuel.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Mode de paiement : En main propre ou sur virement bancaire.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Horaire : Lundi - Vendredi : 08h45 - 12h.<\/strong><\/div> <div><strong>13h-15h30<\/strong><\/div> <div><strong>16h-18h30.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Localisation : Mvan - Carrefour des Carreaux. Immeuble Ndi Samba.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>P\u00e9riode d'essai : 10 Jours (02 semaines de travail).<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Si vous \u00eates tent\u00e9 de nous rejoindre dans la construction de notre entreprise, nous vous invitons \u00e0 constituer votre dossier et \u00e0 l'envoyer&nbsp; \u00e0 l'adresse mail suivante : makaalbarn334@gmail.com.<\/strong><\/div> <div><strong>Si votre profil nous int\u00e9resse, nous vous contacterons pour un entretien.<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Composition du dossier :<\/strong><\/div> <div><strong>- Curriculum vit\u00e6<\/strong><\/div> <div><strong>- Lettre de motivation<\/strong><\/div> <div><strong>- Photocopie\/ scanner de la CNI<\/strong><\/div> <div><strong>- Plan de localisation<\/strong><\/div> <div><strong>&nbsp;<\/strong><\/div> <div><strong>Pour toute information compl\u00e9mentaire, vous pouvez contacter le 675-349-074 ou le 693-433-242 par appel ou sur WhatsApp.&nbsp;<\/strong><\/div> <div>&nbsp;<\/div> \n\n\u00a9 2022 Louma Jobs. All rights reserved.\n\n<\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[335],"tags":[],"villes":[135],"contrats":[234],"diplomes":[162,212],"louma_meta":{"emploi_title":"T\u00e9l\u00e9conseiller","emplois_employeur":3046,"emplois_date_publication":"2022-04-18","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"makaalbarn334@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29710"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29710"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29710"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29710"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29710"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}