{"id":29668,"date":"2022-04-14T14:49:04","date_gmt":"2022-04-14T12:49:04","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29668"},"modified":"2022-04-14T14:49:08","modified_gmt":"2022-04-14T12:49:08","slug":"un-responsable-grands-comptes-en-charge-du-courtage-h-f-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-responsable-grands-comptes-en-charge-du-courtage-h-f-2\/","title":{"rendered":"Un Responsable Grands Comptes en charge du courtage (H\/F)"},"content":{"rendered":"\n<p>SUNU<\/p>\n\n\n\n<p>RECRUTEMENT<\/p>\n\n\n\n<p>SUNU Assurances Vie Cameroun recrute<\/p>\n\n\n\n<p>Un Responsable Grands Comptes en charge du courtage (H\/F)<\/p>\n\n\n\n<p>D\u00e9finir la strat\u00e9gie de fid\u00e9lisation et de d\u00e9veloppement du portefeuille Grands Comptes<\/p>\n\n\n\n<p>MISSIONS<\/p>\n\n\n\n<p>. Concevoir et mettre la place la politique. commerciale de d\u00e9veloppement<\/p>\n\n\n\n<p>QUALIT\u00c9S REQUISES<\/p>\n\n\n\n<p>Maitrise des outils de bureautiques et connaissance des progiciels d\u00e9di\u00e9s \u00e0 la relation client<\/p>\n\n\n\n<p>Etablir le plan d&rsquo;actions commerciales, les<\/p>\n\n\n\n<p>moyens, et le budget y relatif . D\u00e9finir la politique de fid\u00e9lisation et d&rsquo;expansion<\/p>\n\n\n\n<p>du canal des courtiers<\/p>\n\n\n\n<p>. Entretenir les relations commerciales et<\/p>\n\n\n\n<p>s&rsquo;assurer de la respectifs satisfaction de nos clients<\/p>\n\n\n\n<p>\u2022 Prendre en charge les demandes de cotations et assurer le suivi des dossiers<\/p>\n\n\n\n<p>Entretenir, fid\u00e9liser, et consolider le portefeuille existant<\/p>\n\n\n\n<p>Faire de la saturation \u00e0 travers des offres<\/p>\n\n\n\n<p>adapt\u00e9es \u2022 Pr\u00e9voir des visites trimestrielles d&rsquo;\u00e9valuation de<\/p>\n\n\n\n<p>la satisfaction et au besoin mettre en place des<\/p>\n\n\n\n<p>actions correctrices<\/p>\n\n\n\n<p>\u2022 D\u00e9finir une strat\u00e9gie de d\u00e9veloppement du segment Entreprises<\/p>\n\n\n\n<p>. Fixer des objectifs quantitatifs et qualitatifs de croissance du segment Entreprises et d\u00e9finir les actions et moyens de mise en \u0153uvre<\/p>\n\n\n\n<p>COMMENT POSTULER?<\/p>\n\n\n\n<p>Bonne connaissance du march\u00e9 de l&rsquo;assurance Vie, des produits, et de ses principaux acteurs<\/p>\n\n\n\n<p>Force de proposition<\/p>\n\n\n\n<p>\u2022 Aisance commerciale et relationnelle<\/p>\n\n\n\n<p>. Avoir de bonnes aptitudes en commerciale;<\/p>\n\n\n\n<p>n\u00e9gociation<\/p>\n\n\n\n<p>Avoir une bonne organisation du travail et des \u00e9quipes<\/p>\n\n\n\n<p>PROFIL<\/p>\n\n\n\n<p>\u2022 Bac +2\/3 en Marketing \/ Commerce<\/p>\n\n\n\n<p>\u2022 Justifier d&rsquo;au moins 05 ann\u00e9es d&rsquo;exp\u00e9rience au sein d&rsquo;une compagnie d&rsquo;assurance ou d&rsquo;une Soci\u00e9t\u00e9 de courtage<\/p>\n\n\n\n<p>Merci d&rsquo;envoyer votre candidature (CV et lettre de motivation) par mail \u00e0 l&rsquo;adresse: cameroun vio@sunu-group com en pr\u00e9cisant en objet: Responsable Grands Comptes en Charge du courtage \u00bb. Date limite de r\u00e9ception des candidatures 15 avril 2022 \u00e0 17h00<\/p>\n\n\n\n<p>N.B Seules les candidatures retenues seront contact\u00e9es<\/p>\n\n\n\n<p>R\u00e9pondre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUNU RECRUTEMENT SUNU Assurances Vie Cameroun recrute Un Responsable Grands Comptes en charge du courtage (H\/F) D\u00e9finir la strat\u00e9gie de fid\u00e9lisation et de d\u00e9veloppement du&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[343],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un Responsable Grands Comptes en charge du courtage (H\/F)","emplois_employeur":5773,"emplois_date_publication":"2022-04-14","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29668"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29668"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29668\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5776"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29668"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29668"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29668"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}