{"id":29666,"date":"2022-04-14T14:44:31","date_gmt":"2022-04-14T12:44:31","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29666"},"modified":"2022-04-14T14:44:34","modified_gmt":"2022-04-14T12:44:34","slug":"un-responsable-de-la-relation-client-en-charge-du-recouvrement-h-f-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-responsable-de-la-relation-client-en-charge-du-recouvrement-h-f-2\/","title":{"rendered":"Un Responsable de la relation client en charge du recouvrement (H\/F)"},"content":{"rendered":"\n<p>SUNU<\/p>\n\n\n\n<p>RECRUTEMENT<\/p>\n\n\n\n<p>SUNU Assurances Vie Cameroun recrute<\/p>\n\n\n\n<p>Un Responsable de la relation client en charge du recouvrement (H\/F)<\/p>\n\n\n\n<p>Mettre en place une organisation efficace ax\u00e9e sur la gestion de la relation client et le recouvrement des<\/p>\n\n\n\n<p>cr\u00e9ances<\/p>\n\n\n\n<p>ACTIVITES PRINCIPALES<\/p>\n\n\n\n<p>D\u00e9finir la strat\u00e9gie relation client\u00e8le (priorit\u00e9s, budget, moyens\u2026) et d\u00e9terminer les plans d&rsquo;actions annuels<\/p>\n\n\n\n<p>Elaborer et faire \u00e9voluer les proc\u00e9dures qualit\u00e9 de service<\/p>\n\n\n\n<p>client\u00e8le et en contr\u00f4ler l&rsquo;application<\/p>\n\n\n\n<p>. Concevoir les indicateurs de performance de service (taux de r\u00e9clamation, d&rsquo;appels, d\u00e9lais), analyser les r\u00e9sultats et<\/p>\n\n\n\n<p>mettre en place des ajustements . Assurer le suivi du portefeuille et prendre en charge les<\/p>\n\n\n\n<p>r\u00e9clamations clients<\/p>\n\n\n\n<p>Informer et conseiller le client sur l&rsquo;existence de nouveaux produits<\/p>\n\n\n\n<p>Selon la nature des r\u00e9clamations, recommander des axes<\/p>\n\n\n\n<p>d&rsquo;\u00e9volution pour am\u00e9liorer la qualit\u00e9 des produits et des<\/p>\n\n\n\n<p>services propos\u00e9s<\/p>\n\n\n\n<p>Mettre en place des enqu\u00eates de satisfaction et des programmes de fid\u00e9lit\u00e9 pertinents<\/p>\n\n\n\n<p>. Analyser les diff\u00e9rents \u00e9l\u00e9ments des dossiers, \u00e9tablir un diagnostic de la situation financi\u00e8re des clients d\u00e9biteurs et envisager des actions de recouvrement pertinentes<\/p>\n\n\n\n<p>Effectuer les relances pr\u00e9ventives avant l&rsquo;\u00e9ch\u00e9ance de<\/p>\n\n\n\n<p>paiement et apr\u00e8s le d\u00e9passement d&rsquo;\u00e9ch\u00e9ance<\/p>\n\n\n\n<p>Contacter les clients par diff\u00e9rents canaux et obtenir la<\/p>\n\n\n\n<p>r\u00e9gularisation des cr\u00e9ances<\/p>\n\n\n\n<p>\u2022 Assurer le reporting Suivi des encaissements, synth\u00e8ses<\/p>\n\n\n\n<p>d&rsquo;activit\u00e9, \u00e9volution de l&rsquo;encours, analyse des r\u00e9sultats<\/p>\n\n\n\n<p>Tenir un fichier de suivi de la base interne de donn\u00e9es clients (historique, \u00e9tat d&rsquo;avancement des actions engag\u00e9es, solde restant d\u00fb, \u00e2ge de l&rsquo;arri\u00e9r\u00e9\u2026).<\/p>\n\n\n\n<p>PROFIL<\/p>\n\n\n\n<p>\u2022 Justifier d&rsquo;au moins 05 ann\u00e9es d&rsquo;exp\u00e9rience au sein d&rsquo;un service de recouvrement, ou d&rsquo;un service de relation client<\/p>\n\n\n\n<p>\u2022 Bac +2\/3 en Marketing, Commerce, Communication.<\/p>\n\n\n\n<p>COMMENT POSTULER?<\/p>\n\n\n\n<p>Merci d&rsquo;envoyer votre candidature (CV et lettre de motivation) par<\/p>\n\n\n\n<p>mail \u00e0 l&rsquo;adresse cameroun.vie@sunu-group.com en pr\u00e9cisant en<\/p>\n\n\n\n<p>objet \u00ab Responsable de la relation client en charge du<\/p>\n\n\n\n<p>recouvrement &gt;&gt;.<\/p>\n\n\n\n<p>Date limite de r\u00e9ception des candidatures 15 avril 2022 \u00e0 17h00.<\/p>\n\n\n\n<p>QUALITES REQUISES<\/p>\n\n\n\n<p>. Maitrise des outils de bureautiques et connaissance des progiciels d\u00e9di\u00e9s \u00e0 la relation client.<\/p>\n\n\n\n<p>Connaissance des outils digitaux et<\/p>\n\n\n\n<p>r\u00e9seaux sociaux Connaissance<\/p>\n\n\n\n<p>technique et<\/p>\n\n\n\n<p>commerciale des produits et services propos\u00e9s Connaissance de base en Marketing<\/p>\n\n\n\n<p>Communication<\/p>\n\n\n\n<p>. Qualit\u00e9s relationnelles et sens de l&rsquo;\u00e9coute<\/p>\n\n\n\n<p>. Sens de la n\u00e9gociation et app\u00e9tence<\/p>\n\n\n\n<p>commerciale<\/p>\n\n\n\n<p>. Rigueur dans le recueil et le traitement. des donn\u00e9es<\/p>\n\n\n\n<p>\u2022 Force de proposition et de conviction<\/p>\n\n\n\n<p>NB: Seules les candidatures retenues seront contact\u00e9es.<\/p>\n\n\n\n<p>R\u00e9pondre<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUNU RECRUTEMENT SUNU Assurances Vie Cameroun recrute Un Responsable de la relation client en charge du recouvrement (H\/F) Mettre en place une organisation efficace ax\u00e9e&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1792],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un Responsable de la relation client en charge du recouvrement (H\/F)","emplois_employeur":5773,"emplois_date_publication":"2022-04-14","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29666"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29666"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5776"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29666"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29666"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29666"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}