{"id":29650,"date":"2022-04-14T14:06:10","date_gmt":"2022-04-14T12:06:10","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29650"},"modified":"2022-04-14T14:06:21","modified_gmt":"2022-04-14T12:06:21","slug":"un-01-business-expert-trade-finance-forex","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-01-business-expert-trade-finance-forex\/","title":{"rendered":"Un (01) Business Expert Trade Finance &amp; Forex"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Un (01) Business Expert Trade Finance &amp; Forex&nbsp;<\/h3>\n\n\n\n<p><strong>Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun&nbsp;&nbsp;<\/strong><strong>Cameroun&nbsp;<\/strong><a href=\"https:\/\/ats.talenteo.com\/job-apply\/35816398db753c070b67?step=cv\">Postuler&nbsp;<\/a>Secteur d&rsquo;activit\u00e9&nbsp;Banque, Assurance, Finance&nbsp;Date de cr\u00e9ation&nbsp;Il y a 2 jours&nbsp;Nombre de postes&nbsp;1&nbsp;Niveau de poste&nbsp;Confirm\u00e9 \/ Exp\u00e9riment\u00e9&nbsp;Type de contrat&nbsp;CDI&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Description:<\/h3>\n\n\n\n<p><strong>SOCIETE GENERALE CAMEROUN RECHERCHE POUR SA DIRECTION DE LA CLIENTELE ENTREPRISES UN (01) BUSINESS EXPERT TRADE FINANCE &amp; FOREX<\/strong><\/p>\n\n\n\n<p><strong>Cat\u00e9gorie du poste&nbsp;: Cadre<\/strong><\/p>\n\n\n\n<p><strong>Lieu d\u2019affectation&nbsp;: Douala<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Responsabilit\u00e9 Principales<\/strong><\/p>\n\n\n\n<p><strong>Assurer la vente et l\u2019animation commerciale<\/strong><\/p>\n\n\n\n<ul><li>Participer \u00e0 l\u2019\u00e9laboration du plan d\u2019action commercial Trade Finance et Forex;<\/li><li>Assister les RM dans la d\u00e9tection des opportunit\u00e9s sur leur portefeuille clients et prospects;<\/li><li>Effectuer un planning de visites clients;<\/li><li>D\u00e9finir en collaboration avec le coverage le plan de formation relevant de son domaine d\u2019expertise;<\/li><li>Organiser (participer \u00e0) des \u00e9v\u00e9nements clients d\u00e9di\u00e9s.<\/li><\/ul>\n\n\n\n<p><strong>Assurer le d\u00e9veloppement de l\u2019offre de produits Trade Finance et Change<\/strong><\/p>\n\n\n\n<ul><li>Promouvoir les solutions \u00e0 valeur ajout\u00e9e en collaboration avec le marketing (contribution m\u00e9tier aux comit\u00e9s produits pu projets);<\/li><li>Veilleur \u00e0 la mise \u00e0 niveau rapide des offres et \u00e0 l\u2019am\u00e9lioration des solutions de l\u2019offre;<\/li><li>Prioriser le d\u00e9veloppement des produits en fonction des grandes orientations commerciales.<\/li><\/ul>\n\n\n\n<p><strong>D\u00e9velopper et fid\u00e9liser le fonds de commerce<\/strong><\/p>\n\n\n\n<ul><li>\u00c9laborer des propositions commerciales (tarification, structuration)&nbsp; pour les produits les plus complexes, organiser les r\u00e9ponses aux appels d\u2019offres;<\/li><li>S\u2019assurer que les outils et produits vendus sont bien utilis\u00e9s par les clients;<\/li><li>D\u00e9finir en collaboration avec les Ressources Humaines le plan de formation relevant de son domaine d\u2019expertise;<\/li><li>D\u00e9velopper la relation commerciale avec les clients ou prospects cibl\u00e9s sur la base d\u2019un plan d\u2019action commercial (campagnes promotionnelles pour repositionner des produits strat\u00e9giques)<\/li><\/ul>\n\n\n\n<p><strong>Favoriser la synergie entre le commerce international et le cross selling<\/strong><\/p>\n\n\n\n<ul><li>Organiser la coop\u00e9ration avec les fonctions cl\u00e9s (marketing et back office)&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences m\u00e9tier<\/strong>&nbsp;<\/p>\n\n\n\n<ul><li>Connaissance des produits et services du Trade Finance et Change;<\/li><li>Connaissance de la r\u00e9glementation bancaire;<\/li><li>Maitrise de la r\u00e9glementation des Changes CEMAC;<\/li><li>Ma\u00eetrise des techniques du commerce international;<\/li><li>Connaissance de la politique de cr\u00e9dit;<\/li><li>Maitrise de l\u2019analyse financi\u00e8re;<\/li><li>Ma\u00eetrise des outils bureautique et applications m\u00e9tier;<\/li><li>Aptitude \u00e0 g\u00e9rer et animer une \u00e9quipe de vente<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences comportementales<\/strong><\/p>\n\n\n\n<ul><li>Orientation r\u00e9sultat;<\/li><li>Orientation Client;<\/li><li>Bonne capacit\u00e9 relationnelle et de communication;<\/li><li>Sens de l&rsquo;innovation et l&rsquo;esprit d&rsquo;initiative;<\/li><li>Esprit d\u2019\u00e9quipe<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Minimum BAC + 4 en Finance, Commerce international ou toute discipline connexe;<\/li><li>Minimum 03 ann\u00e9es d\u2019exp\u00e9rience professionnelle dans le commercial bancaire ou dans les op\u00e9rations internationales.<\/li><\/ul>\n\n\n\n<p><strong>Date limite de r\u00e9ception des candidatures&nbsp;:&nbsp;mercredi, 20 avril 2022 \u00e0 17 heures.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un (01) Business Expert Trade Finance &amp; Forex&nbsp; Soci\u00e9t\u00e9 G\u00e9n\u00e9rale Cameroun&nbsp;&nbsp;Cameroun&nbsp;Postuler&nbsp;Secteur d&rsquo;activit\u00e9&nbsp;Banque, Assurance, Finance&nbsp;Date de cr\u00e9ation&nbsp;Il y a 2 jours&nbsp;Nombre de postes&nbsp;1&nbsp;Niveau de poste&nbsp;Confirm\u00e9 \/&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un (01) Business Expert Trade Finance & Forex ","emplois_employeur":3502,"emplois_date_publication":"2022-04-14","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/ats.talenteo.com\/job-apply\/35816398db753c070b67"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29650"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29650"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/23563"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29650"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29650"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29650"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}