{"id":29477,"date":"2022-04-09T05:03:48","date_gmt":"2022-04-09T03:03:48","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29477"},"modified":"2022-04-09T05:03:51","modified_gmt":"2022-04-09T03:03:51","slug":"agent-technico-commercial-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/agent-technico-commercial-3\/","title":{"rendered":"AGENT TECHNICO- COMMERCIAL"},"content":{"rendered":"\n<p>Nous recrutons<br>TEMPS COMPLET<\/p>\n\n\n\n<p><br>AGENT TECHNICO- COMMERCIAL<\/p>\n\n\n\n<p><br>Nous recrutons des technico-commerciaux dynamiques et s\u00e9rieux dans la ville de Douala.<br>Qui sommes-nous ?<\/p>\n\n\n\n<p><br>Kola est une Startup Fintech qui vise \u00e0 faciliter l&rsquo;inclusion financi\u00e8re et l&rsquo;acc\u00e8s aux services financiers pour les personnes et les entreprises de la r\u00e9gion CEMAC en utilisant le pouvoir de la technologie.<\/p>\n\n\n\n<p><br>En d\u00e9finitive, notre mission est d&rsquo;acc\u00e9l\u00e9rer le d\u00e9veloppement \u00e9conomique en construisant la premi\u00e8re soci\u00e9t\u00e9 de services financiers pour l&rsquo;Afrique centrale et au-del\u00e0.<\/p>\n\n\n\n<p><br>D\u00e9posez votre CV \u00e0 cette adresse: careers@kolagroup.io et pr\u00e9ciser votre ville de pr\u00e9f\u00e9rence.<\/p>\n\n\n\n<p><br>Qui \u00eates-vous ?<br>Qualit\u00e9s Recherch\u00e9es<br>Bon vendeur \/se<br>Maitrise de l\u2019outil Excel<br>Capacit\u00e9 \u00e0 manier facilement un t\u00e9l\u00e9phone Android et iPhone<br>Habilite \u00e0 former des utilisateurs sur des solutions digitales<br>Apte \u00e0 pouvoir se d\u00e9ployer partout o\u00f9 le besoin se fait ressentir<br>Capacit\u00e9 \u00e0 bien s\u2019exprimer<br>Bonne pr\u00e9sentation physique<br>Bonne capacit\u00e9 d\u2019adaptation<br>Niveau d\u2019\u00e9tude :<br>\u00catre titulaire d\u2019un baccalaur\u00e9at au minimum<br>R\u00e9mun\u00e9rations :<br>Salaire fixe + Commissions (en fonction des objectifs atteints)<\/p>\n\n\n\n<p><br>NB : Avoir un t\u00e9l\u00e9phone Android ou iPhone.<\/p>\n\n\n\n<p><br>Les touts de la fonction<\/p>\n\n\n\n<p><br>Il s&rsquo;agit d&rsquo;un poste salari\u00e9 \u00e0 temps plein.<br>Nous vous offrirons le soutien dont vous avez besoin pour vous aider \u00e0 \u00e9voluer en tant que travailleur efficace et \u00eatre humain.<br>Nous offrons un environnement de travail convivial<br>Acc\u00e8s \u00e0 une connexion internet \u00e0 large bande<br>Postulez sur !<br>careers@kolagroup.io<br>\u00c7a vous para\u00eet excitant? Vous souhaitez avoir un impact sur l&rsquo;Afrique ?! Visitez-nous sur: https:\/\/www.kolagroup.io<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous recrutonsTEMPS COMPLET AGENT TECHNICO- COMMERCIAL Nous recrutons des technico-commerciaux dynamiques et s\u00e9rieux dans la ville de Douala.Qui sommes-nous ? Kola est une Startup Fintech&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"AGENT TECHNICO- COMMERCIAL","emplois_employeur":10225,"emplois_date_publication":"2022-04-09","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"careers@kolagroup.io"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29477"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29477"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/10232"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29477"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29477"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29477"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}