{"id":29346,"date":"2022-04-01T00:38:09","date_gmt":"2022-03-31T22:38:09","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29346"},"modified":"2022-04-01T00:38:11","modified_gmt":"2022-03-31T22:38:11","slug":"directeur-des-ressources-humaines-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/directeur-des-ressources-humaines-2\/","title":{"rendered":"Directeur des Ressources Humaines"},"content":{"rendered":"\n<p>BASSAGAL CONSULTING AFRICA recrute, pour un de ses clients de l\u2019industrie s\u00e9rigraphique :<\/p>\n\n\n\n<p><br>Rattach\u00e9(e) au <strong>Directeur des Ressources Humaines<\/strong>, vous aurez pour activit\u00e9s principales :<\/p>\n\n\n\n<p><br>\uf0b7 Assurer le management du p\u00f4le ;<br>\uf0b7 Organiser l\u2019activit\u00e9 recrutement\/mobilit\u00e9 et GPEC ;<br>\uf0b7 Organiser la circulation de l\u2019information aupr\u00e8s des interlocuteurs externes et internes au p\u00f4le ;<br>\uf0b7 Mettre en place et\/ou actualiser les tableaux de bord permettant de suivre l\u2019activit\u00e9 et sa coordination ;<br>\uf0b7 G\u00e9rer les entretiens professionnels des agents plac\u00e9s sous sa responsabilit\u00e9 ;<br>\uf0b7 Contr\u00f4ler le pilotage des recrutements\/mobilit\u00e9s internes r\u00e9alis\u00e9s au sein des Directions Op\u00e9rationnelles ;<br>\uf0b7 Contr\u00f4ler la mise en \u0153uvre des politiques RH et l\u2019application du processus recrutement\/mobilit\u00e9 ;<br>\uf0b7 Participer \u00e0 la r\u00e9flexion sur les outils en cours de construction, n\u00e9cessaires \u00e0 la GPEC (R\u00e9pertoire des m\u00e9tiers, dictionnaire des comp\u00e9tences, fiches de poste) ;<br>\uf0b7 Effectuer la classification des postes en collaboration avec la DRH ;<br>\uf0b7 Piloter le processus d\u2019\u00e9valuation de la performance et du potentiel des salari\u00e9s.<br>Profil :<br>\uf0b7 De formation sup\u00e9rieure niveau Bac+5 en Ressources Humaines, Droit du travail, Sciences Sociales ou discipline assimil\u00e9e ;<br>\uf0b7 Vous justifiez d\u2019une exp\u00e9rience de 5 ans en qualit\u00e9 de manager RH dont 1 an \u00e0 un poste similaire ;<br>\uf0b7 Une exp\u00e9rience du secteur des FMCG serait un atout ;<br>\uf0b7 Ma\u00eetriser des concepts fondamentaux de la GRH<br>\uf0b7 La mise en place des contrats sp\u00e9cifiques et la capacit\u00e9 de travailler en mode projet sont un plus ;<br>\uf0b7 Expertise sur l\u2019utilisation d\u2019Excel, SAP, SAGE ;<br>\uf0b7 Avoir d\u2019excellentes capacit\u00e9s manag\u00e9riales, une aisance relationnelle et sens du service ;<br>\uf0b7 Orient\u00e9 r\u00e9sultats, vous avez prouv\u00e9 votre capacit\u00e9 \u00e0 travailler d\u2019une mani\u00e8re ind\u00e9pendante et<br>transformez les difficult\u00e9s en opportunit\u00e9s ;<br>\uf0b7 Avoir un esprit d\u2019initiative, d\u2019analyse et de synth\u00e8se ;<\/p>\n\n\n\n<p><br>Les candidats int\u00e9ress\u00e9s devraient envoyer leur CV en pr\u00e9cisant la r\u00e9f\u00e9rence DRH0222 \u00e0 l\u2019adresse<br>suivante :<br>yannick.billigha@bassagal-consulting.com<br>La date limite de recevabilit\u00e9 des candidatures est fix\u00e9e au 08 avril 2022. Seuls les candidats shortlist\u00e9s seront contact\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BASSAGAL CONSULTING AFRICA recrute, pour un de ses clients de l\u2019industrie s\u00e9rigraphique : Rattach\u00e9(e) au Directeur des Ressources Humaines, vous aurez pour activit\u00e9s principales :&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[20],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Directeur des Ressources Humaines","emplois_employeur":4772,"emplois_date_publication":"2022-03-31","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"yannick.billigha@bassagal-consulting.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29346"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29346"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29346"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29346"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29346"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}