{"id":29338,"date":"2022-03-31T03:07:08","date_gmt":"2022-03-31T01:07:08","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=29338"},"modified":"2022-03-31T03:07:09","modified_gmt":"2022-03-31T01:07:09","slug":"04-redacteurs-web-en-freelance","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/04-redacteurs-web-en-freelance\/","title":{"rendered":"04 R\u00e9dacteurs Web en Freelance"},"content":{"rendered":"\n<p>TRUST AND AR<\/p>\n\n\n\n<p>JOB ETUDIANT-CAMEROUN<\/p>\n\n\n\n<p>Nous recherchons pour un Job \u00e9tudiant, 04 R\u00e9dacteurs Web en Freelance.<\/p>\n\n\n\n<p>Le job consiste \u00e0 \u00e9crire chaque semaine quelques articles sur des th\u00e9matiques<\/p>\n\n\n\n<p>simples, diverses et vari\u00e9es comme : le bricolage, la d\u00e9coration, le sport, la sant\u00e9, la<\/p>\n\n\n\n<p>cuisine, les astuces du quotidien, les animaux, l&rsquo;automobile, les finances, \u2026 Les titres des articles \u00e0 r\u00e9diger seront donn\u00e9s au R\u00e9dacteur en d\u00e9but de semaine, avec<\/p>\n\n\n\n<p>des instructions pr\u00e9cises.<\/p>\n\n\n\n<p>Les textes doivent \u00eatre r\u00e9dig\u00e9s en fran\u00e7ais, dans un style simple et facile \u00e0 comprendre, et<\/p>\n\n\n\n<p>bien \u00e9videmment sans fautes.<\/p>\n\n\n\n<p>Conditions d&rsquo;admissibilit\u00e9 au poste de R\u00e9dacteur Web Freelance:<\/p>\n\n\n\n<p>\u00catre \u00e2g\u00e9(e) de moins de 25 ans Avoir le statut d&rsquo;\u00e9tudiant(e) (ann\u00e9e acad\u00e9mique<\/p>\n\n\n\n<p>2021-2022)<\/p>\n\n\n\n<p>Savoir r\u00e9diger des textes simples, faciles \u00e0 comprendre et d\u00e9pourvus de fautes Avoir une bonne capacit\u00e9 d&rsquo;analyse et de synth\u00e8se (tu dois \u00eatre capable d&rsquo;effectuer rapidement des recherches sur internet et \u00eatre capable de r\u00e9diger sans copier<\/p>\n\n\n\n<p>coller ni plagiat)<\/p>\n\n\n\n<p>Pas besoin d&rsquo;avoir des connaissances en SEO.<\/p>\n\n\n\n<p>Il te suffit d&rsquo;envoyer tous les \u00e9l\u00e9ments ci-dessous \u00e0 l&rsquo;adresse recrutement.freelance@rexmicrosystems.com:<\/p>\n\n\n\n<ol><li>Ton CV \u00e0 jour<\/li><li>Ta CNI (en couleur).<\/li><li>Une attestation ou document confirmant ton statut d&rsquo;\u00e9tudiant pour le compte de<\/li><\/ol>\n\n\n\n<p>l&rsquo;ann\u00e9e acad\u00e9mique 2021-2022 4. Ton relev\u00e9 de notes du baccalaur\u00e9at<\/p>\n\n\n\n<p>Ton l\u00f4me le plus \u00e9lev\u00e9.<\/p>\n\n\n\n<p>Date limite de recevabilit\u00e9 des candidatures: Samedi 30 Avril 2022 \u00e0 23H59 (GMT+1).<\/p>\n\n\n\n<p>NB:<\/p>\n\n\n\n<p>Une fois ta candidature re\u00e7ue, nous t&rsquo;enverrons un accus\u00e9 de r\u00e9ception par mail. Donc pense \u00e0 consulter tes mails (y compris tes SPAMS) de temps en temps. Seuls les dossiers complets seront pris en consid\u00e9ration.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRUST AND AR JOB ETUDIANT-CAMEROUN Nous recherchons pour un Job \u00e9tudiant, 04 R\u00e9dacteurs Web en Freelance. Le job consiste \u00e0 \u00e9crire chaque semaine quelques articles&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[25],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"04 R\u00e9dacteurs Web en Freelance","emplois_employeur":3046,"emplois_date_publication":"2022-03-31","emplois_heure_publication":"","emplois_date_cloture":"2022-04-30","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recrutement.freelance@rexmicrosystems.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29338"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=29338"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/29338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=29338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=29338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=29338"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=29338"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=29338"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=29338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}