{"id":28902,"date":"2022-03-18T14:09:57","date_gmt":"2022-03-18T13:09:57","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=28902"},"modified":"2022-03-18T14:09:59","modified_gmt":"2022-03-18T13:09:59","slug":"finance-support","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/finance-support\/","title":{"rendered":"Finance Support"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><a href=\"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/UIVN9UG5NV6E#\"><img decoding=\"async\" src=\"https:\/\/emploi.ciblerh-emploi.com\/img\/jod-detail.png\" alt=\"\" \/><\/a><\/figure>\n\n\n\n<p><a href=\"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/UIVN9UG5NV6E#\">Finance Support<\/a><\/p>\n\n\n\n<p><\/p>\n\n\n\n<ul><li>Oil &amp; Gas<\/li><li>Cameroun, Littoral, Douala<\/li><li><strong>FS-RH-019-03-22<\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Activit\u00e9 du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>\u2022 Aider \u00e0 la num\u00e9risation, l&rsquo;enregistrement et la soumission des factures \u00e9trang\u00e8res et locales dans Proactis.<\/p>\n\n\n\n<p>\u2022 Aider \u00e0 rassembler les pi\u00e8ces justificatives n\u00e9cessaires requises par la nouvelle r\u00e9glementation FX.<\/p>\n\n\n\n<p>\u2022 Aider au suivi des factures en attente d&rsquo;approbation \u00e0 diff\u00e9rents niveaux dans Proactis.<\/p>\n\n\n\n<p>\u2022 Traiter les requ\u00eates des fournisseurs internes et externes.<\/p>\n\n\n\n<p>\u2022 G\u00e9rer les transactions de petite caisse.<\/p>\n\n\n\n<p>\u2022 Pr\u00e9parer et journaliser les feuilles d&rsquo;amortissement de fin de mois pour l&rsquo;assurance pr\u00e9pay\u00e9e et le loyer ainsi que d&rsquo;autres entr\u00e9es de fin de mois.<\/p>\n\n\n\n<p>\u2022 G\u00e9rer le rapprochement des comptes de fin de mois pour certains fournisseurs locaux et \u00e9trangers s\u00e9lectionn\u00e9s.<\/p>\n\n\n\n<p>\u2022 Assure le remplissage appropri\u00e9 des transactions journalis\u00e9es et aide aux audits internes\/externes et aux activit\u00e9s de tr\u00e9sorerie\/gestion de tr\u00e9sorerie.<\/p>\n\n\n\n<p><br><strong>Interface interne<\/strong><\/p>\n\n\n\n<p>\u2022 Autres d\u00e9partements de l&rsquo;entreprise.<\/p>\n\n\n\n<p>\u2022 Le titulaire fait partie d&rsquo;une \u00e9quipe des finances de 22 employ\u00e9s.<\/p>\n\n\n\n<p><br><strong>Interface externe<\/strong><\/p>\n\n\n\n<p>\u2022 Interagit avec tous les autres employ\u00e9s, consultants internationaux, visiteurs ou membres du personnel du si\u00e8ge social de la soci\u00e9t\u00e9 et\/ou d&rsquo;autres soci\u00e9t\u00e9s op\u00e9rationnelles, y compris les parties prenantes de la coentreprise.<\/p>\n\n\n\n<p><br><strong>Dimension<\/strong>\u2022 Le nombre de factures pay\u00e9es est de plus de 400 par semaine, avec une transaction en esp\u00e8ces mensuelle de 30 millions de dollars US.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Profil du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>\u2022 HND en Comptabilit\u00e9 ou Finance.<\/p>\n\n\n\n<p>\u2022 Excellentes comp\u00e9tences informatiques (Excel, PowerPoint, ERP).<\/p>\n\n\n\n<p>\u2022 Bonne connaissance de la comptabilit\u00e9 financi\u00e8re.<\/p>\n\n\n\n<p>\u2022 Minimum de deux ans d&rsquo;exp\u00e9rience professionnelle dans un poste li\u00e9 aux finances.<\/p>\n\n\n\n<p>\u2022 La connaissance de Sun Systems sera un atout suppl\u00e9mentaire.<\/p>\n\n\n\n<p>\u2022 Parle couramment l&rsquo;anglais et le fran\u00e7ais.<\/p>\n\n\n\n<p>\u2022 Bonnes capacit\u00e9s d&rsquo;analyse et de r\u00e9solution de probl\u00e8mes.<\/p>\n\n\n\n<p>\u2022 Bonnes comp\u00e9tences en communication.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Job d\u00e9tail<\/h4>\n\n\n\n<ul><li>Reference :&nbsp;FS-RH-019-03-22<\/li><li>Publier le :&nbsp;2022-03-14 15:43:10<\/li><li>Localisation :&nbsp;AKWA_ Ancien Dalip<\/li><li>Niveau :&nbsp;BAC + 2<\/li><li>Type Emplois :&nbsp;Temps Partiel<\/li><li>Date Limite :&nbsp;2022-03-24 12:00:00<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Informations entreprise<\/h4>\n\n\n\n<p>CONSEILS RH, MISE A DISPOSITION DU PERSONNEL, GESTION DE POLES D&rsquo;ACTIVITIES<\/p>\n\n\n\n<ul><li>Name:&nbsp;Cible RH&nbsp;<\/li><li>Web :&nbsp;https:\/\/emploi.ciblerh-emploi.com<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Finance Support Oil &amp; Gas Cameroun, Littoral, Douala FS-RH-019-03-22 Activit\u00e9 du poste \u2022 Aider \u00e0 la num\u00e9risation, l&rsquo;enregistrement et la soumission des factures \u00e9trang\u00e8res et&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Finance Support","emplois_employeur":2630,"emplois_date_publication":"2022-03-18","emplois_heure_publication":"","emplois_date_cloture":"2022-03-24","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/UIVN9UG5NV6E"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28902"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=28902"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28902\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=28902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=28902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=28902"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=28902"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=28902"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=28902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}