{"id":28896,"date":"2022-03-18T13:57:29","date_gmt":"2022-03-18T12:57:29","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=28896"},"modified":"2022-03-18T13:57:31","modified_gmt":"2022-03-18T12:57:31","slug":"wireline-technician","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/wireline-technician\/","title":{"rendered":"Wireline Technician"},"content":{"rendered":"\n<p><a href=\"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/UTQMCUH2CYM5#\">Wireline Technician<\/a><\/p>\n\n\n\n<ul><li>Oil &amp; Gas<\/li><li>Cameroun, Littoral, Douala<\/li><li><strong>WT-RH-021-03-22<\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Activit\u00e9 du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>\u2022 Responsable du suivi des proc\u00e9dures et de la documentation HSE du quart de travail sur le site.<\/p>\n\n\n\n<p>\u2022 Effectue toutes les t\u00e2ches et responsabilit\u00e9s requises en toute s\u00e9curit\u00e9 et comme d\u00e9crit dans les manuels de gestion des op\u00e9rations de la base, de gestion des op\u00e9rations du site de puits et de gestion de l&rsquo;\u00e9quipement et de la logistique<\/p>\n\n\n\n<p>\u2022 Entretien courant de l&rsquo;\u00e9quipement filaire sur le chantier et assemblage des outils<\/p>\n\n\n\n<p>\u2022 Ex\u00e9cution d&rsquo;un fonctionnement s\u00e9curitaire de la grue et du gr\u00e9ement des charges.<\/p>\n\n\n\n<p>\u2022 Effectuer la pr\u00e9paration avant le travail de l&rsquo;\u00e9quipement filaire, des unit\u00e9s filaires, des travaux d&rsquo;arpentage et assurer l&rsquo;ach\u00e8vement de la logistique avant le travail<\/p>\n\n\n\n<p>\u2022 Enlever et d\u00e9monter les outils et l&rsquo;\u00e9quipement sur le terrain<\/p>\n\n\n\n<p>\u2022 Assumer les responsabilit\u00e9s de l&rsquo;atelier apr\u00e8s le travail, y compris le nettoyage, l&rsquo;entretien de l&rsquo;\u00e9quipement, les tests de l&rsquo;\u00e9quipement de bureau et les documents de soumission pr\u00e9cis et opportuns et les fichiers connexes<\/p>\n\n\n\n<p>\u2022 Pr\u00e9parer et maintenir la documentation pour les travaux, les rapports quotidiens et toutes les fonctions administratives applicables<\/p>\n\n\n\n<p>\u2022 Responsable de la collecte de donn\u00e9es pr\u00e9cises et des rapports \u00e0 Well Analyst.<\/p>\n\n\n\n<p>\u2022 Responsable d&rsquo;ex\u00e9cuter les instructions des superviseurs filaires sur le site et dans l&rsquo;atelier.<\/p>\n\n\n\n<p>\u2022 Long shifts, regularly 12 hour shifts of work on site.<\/p>\n\n\n\n<p>\u2022 Extended stays away from home in offshore locations.<\/p>\n\n\n\n<p>\u2022 The job requires direct contact with the other crew members and as well as other operating personnel on location.<\/p>\n\n\n\n<p>\u2022 Assist with regular inspection; inventory, and function and pressure testing are direct responsibility.<\/p>\n\n\n\n<p>\u2022 Responsible for Training and Safety of junior staff on job site.<\/p>\n\n\n\n<p>\u2022 Take reasonable care to prevent harm to themselves.<\/p>\n\n\n\n<p>\u2022 Work in accordance with information and training provided.<\/p>\n\n\n\n<p>\u2022 Report any hazardous defects in plant, equipment and workplace, or shortcomings in the existing controls, to a responsible person without delay. Not undertake any task for which authorization and \/ or PTW has not been given<\/p>\n\n\n\n<p><br><strong>Internal Interfaces<\/strong><\/p>\n\n\n\n<p>\u2022 Primary contact for this position is the Well Analyst.<\/p>\n\n\n\n<p>\u2022 Secondly contact with Head of Offshore Operations and Offshore Installation manager.<\/p>\n\n\n\n<p>\u2022 Contact with Area Operations for disciplinary, promotion, or other issues concerning the Area over all.<\/p>\n\n\n\n<p><br><strong>External interfaces<\/strong><\/p>\n\n\n\n<p>\u2022 Customer Representatives, Rig Staff, other Service Operators or Staff.<\/p>\n\n\n\n<p>\u2022 Vendors specific to field operations.<\/p>\n\n\n\n<p><br><strong>Key Challenges<\/strong><\/p>\n\n\n\n<p><br>\u2022 Critical decision-making skills and ability to react based on Job needs and Safe Work Practices.<\/p>\n\n\n\n<p>\u2022 Must follow orders well, possess good interpersonal skills and have willingness to work at close proximity with other employees<\/p>\n\n\n\n<p>\u2022 Critical paperwork issues for Safety, Quality Assurance and Inventory Control.<\/p>\n\n\n\n<p>\u2022 Dealing with difficult and varied personalities of crew and other site personnel.<\/p>\n\n\n\n<p>\u2022 Requires good computer skills and good literacy.<\/p>\n\n\n\n<p>\u2022 Doit avoir de tr\u00e8s bonnes comp\u00e9tences organisationnelles et \u00eatre pr\u00eat pour des t\u00e2ches de garde 24 heures sur 24.\u00a0base<\/p>\n\n\n\n<p>\u2022 N\u00e9cessit\u00e9 des activit\u00e9s intenses, y compris marcher, se pencher, grimper et \u00eatre capable de supporter un minimum de 50\u00a0lb<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Profil du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>\u2022 Dipl\u00f4me d&rsquo;\u00e9tudes secondaires ou \u00e9quivalent.&nbsp;Une vaste exp\u00e9rience dans les champs p\u00e9trolif\u00e8res est acceptable en compensation d&rsquo;une \u00e9ducation minimale.\u2022 Excellentes aptitudes m\u00e9caniques et connaissances en pneumatique et instrumentation.\u2022 Bonnes comp\u00e9tences en informatique et litt\u00e9rature\u2022 N\u00e9cessite H2S valide, WHIMS, TDG, et de pr\u00e9f\u00e9rence un certificat de secourisme<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Job d\u00e9tail<\/h4>\n\n\n\n<ul><li>Reference :&nbsp;WT-RH-021-03-22<\/li><li>Publier le :&nbsp;2022-03-17 07:58:42<\/li><li>Localisation :&nbsp;AKWA_ Ancien Dalip<\/li><li>Niveau :&nbsp;BAC +1<\/li><li>Type Emplois :&nbsp;Plein temps<\/li><li>Date Limite :&nbsp;2022-03-28 12:00:00<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Informations entreprise<\/h4>\n\n\n\n<p>CONSEILS RH, MISE A DISPOSITION DU PERSONNEL, GESTION DE POLES D&rsquo;ACTIVITIES<\/p>\n\n\n\n<ul><li>Name:&nbsp;Cible RH&nbsp;<\/li><li>Web :&nbsp;https:\/\/emploi.ciblerh-emploi.com<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wireline Technician Oil &amp; Gas Cameroun, Littoral, Douala WT-RH-021-03-22 Activit\u00e9 du poste \u2022 Responsable du suivi des proc\u00e9dures et de la documentation HSE du quart&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[26],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Wireline Technician","emplois_employeur":2630,"emplois_date_publication":"2022-03-18","emplois_heure_publication":"","emplois_date_cloture":"2022-03-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/UTQMCUH2CYM5"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28896"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=28896"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=28896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=28896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=28896"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=28896"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=28896"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=28896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}