{"id":28703,"date":"2022-03-15T03:07:43","date_gmt":"2022-03-15T02:07:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=28703"},"modified":"2022-03-15T03:07:46","modified_gmt":"2022-03-15T02:07:46","slug":"monteuse-de-perruque-a-la-machine","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/monteuse-de-perruque-a-la-machine\/","title":{"rendered":"Monteuse de perruque a la machine"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Monteuse de perruque a la machine ,\ndate d'expiration : 2022-07-12,\nentreprise  : Entreprise de recrutement ,\nNouvelle entreprise : Feulefack industrie sarl \nPays : cameroun,\nvilles : Douala ,\ncontact pour postuler : nangdong.charnele@feulefack-industrie.com\n\nNous recrutons 03 couturi\u00e8res qui savent montrer les perruques a la machine a la cit\u00e9 sic a douala.&nbsp;<br>Profil recherch\u00e9:<br>Postuler en envoyant votre CV via whatsap au 680035762 <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[4018],"tags":[],"villes":[135],"contrats":[234],"diplomes":[158,157],"louma_meta":{"emploi_title":"Monteuse de perruque a la machine","emplois_employeur":28630,"emplois_date_publication":"2022-03-15","emplois_heure_publication":"","emplois_date_cloture":"2022-03-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"nangdong.charnele@feulefack-industrie.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28703"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=28703"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/28631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=28703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=28703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=28703"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=28703"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=28703"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=28703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}