{"id":28124,"date":"2022-02-25T02:09:07","date_gmt":"2022-02-25T01:09:07","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=28124"},"modified":"2022-02-25T02:09:08","modified_gmt":"2022-02-25T01:09:08","slug":"10-hotesses-supermarches","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/10-hotesses-supermarches\/","title":{"rendered":"10 H\u00f4tesses Supermarch\u00e9s"},"content":{"rendered":"\n<p>Une entreprise de la place recherche pour sa campagne dans la ville de Douala : 10 h\u00f4tesses supermarch\u00e9s.<\/p>\n\n\n\n<p><br>Contact : aur\u00e9lien.bekatal@gmail.com ou WhatsApp :6 56 52 80 10<\/p>\n\n\n\n<p><br>N.B: les entretiens auront lieu vendredi 25 f\u00e9vrier \u00e0 15h \u00e0 SITRACEL situ\u00e9 \u00e0 la Texaco du port (beach). Veuillez vous munir de votre CV.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise de la place recherche pour sa campagne dans la ville de Douala : 10 h\u00f4tesses supermarch\u00e9s. Contact : aur\u00e9lien.bekatal@gmail.com ou WhatsApp :6 56&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1273],"tags":[],"villes":[135,136],"contrats":[234],"diplomes":[162],"louma_meta":{"emploi_title":"10 H\u00f4tesses Supermarch\u00e9s","emplois_employeur":3046,"emplois_date_publication":"2022-02-25","emplois_heure_publication":"","emplois_date_cloture":"2022-03-25","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"aur\u00e9lien.bekatal@gmail.com ou WhatsApp :6 56 52 80 10"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28124"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=28124"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/26274"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=28124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=28124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=28124"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=28124"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=28124"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=28124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}