{"id":28122,"date":"2022-02-25T01:53:43","date_gmt":"2022-02-25T00:53:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=28122"},"modified":"2022-02-25T01:53:45","modified_gmt":"2022-02-25T00:53:45","slug":"un-01-senior-service-officer-ops","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-01-senior-service-officer-ops\/","title":{"rendered":"Un (01) Senior Service Officer Ops"},"content":{"rendered":"\n<p>RECRUTEMENT : INTERNE \/ EXTERNE<br>ECOBANK CAMEROUN S.A. recrute pour les besoins de ses services, Un (01) Senior Service Officer Ops<br>Type de Contrat :<br>CDI<\/p>\n\n\n\n<p><br>MISSION DU POSTE :<\/p>\n\n\n\n<p><br>Le titulaire du poste aura pour mission principales de :<\/p>\n\n\n\n<ul><li>Assurer la r\u00e9conciliation journali\u00e8re de tous les produits digitaux et ATM,<\/li><li>Identifier et apurer tous les suspens sur les comptes ATM et de tous les produits digitaux<\/li><li>Anticiper et traiter les r\u00e9clamations des clients relatifs aux ATM et produits digitaux<\/li><li>Apporter une satisfaction G\u00e9n\u00e9rale aux clients et partenaires<\/li><li>Aider \u00e0 l\u2019am\u00e9lioration de la qualit\u00e9 de service de la banque<\/li><li>Fournir un service de qualit\u00e9 afin de r\u00e9duire les r\u00e9clamations des clients<\/li><li>Apporter de fa\u00e7on prompte des solutions aux r\u00e9clamations des clients<\/li><li>Diminuer ou intercepter les actes de fraudes internes<\/li><li>Permettre la continuit\u00e9 de l\u2019activit\u00e9 avec les cartes en agissant \u00e0 temps<\/li><li><br>PRINCIPALES RESPONSABILITES<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<ul><li>Appliquer les politiques et proc\u00e9dures standard \u00e0 l&rsquo;\u00e9chelle du groupe concernant le guichet automatique et d&rsquo;autres produits num\u00e9riques<\/li><li>R\u00e9diger et mettre \u00e0 jour les proc\u00e9dure relatives \u00e0 la r\u00e9conciliation des ATM et Produits digitaux<\/li><li>S\u2019assurer que les r\u00e9clamations sur les ATM sont trait\u00e9es dans le respect du SLA &amp; TAT.<\/li><li>Initier \u00e0 l\u2019issue des r\u00e9conciliations journali\u00e8res, le Booking Form\/memo de liquidation des<br>transactions ATM<\/li><li>Initier les r\u00e9conciliation journali\u00e8re et regl\u00e8ment des transactions Xpress Cash , MOMO, Orange<br>money, MasterPass &amp; mVisa QR<\/li><li>Effectuer les r\u00e9conciliations journali\u00e8res des transaction Agency banking<\/li><li>Proc\u00e9der \u00e0 la r\u00e9conciliation journali\u00e8re des comptes de produits digitaux dans CLIREC<\/li><li>Prompt investigation et r\u00e9ponse aux r\u00e9clamations des clients \u00e0 travers les agences<\/li><li>Veiller \u00e0 l\u2019embarquement des comptes de produits digitaux dans CLIREC<\/li><li>Checker et corriger les cash load\/cash off load erron\u00e9s dans CLIREC<\/li><li>R\u00e9pondre et corriger dans les respect des SLA, les r\u00e9clamations clients sur ATM &amp; transactions<br>Digitales.<\/li><li>Identifier et suivre journali\u00e8rement les diff\u00e9rences sur Proof ATM pour r\u00e9gularisation.<\/li><li>Veiller \u00e0 ce que les Proof ATM soit mis \u00e0 jour et transmis dans les d\u00e9lais.<\/li><li>Assurer le suivi de la transmission des Proof mensuels des comptes ATM.<br>\u2013 ATM\/All Digital Products Reconciliation &amp; Settlement<br>bas\u00e9 \u00e0 Douala. Job grade : 3C\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026\u2026.Job level : 4<br>PUBLIC<\/li><\/ul>\n\n\n\n<p>PUBLIC<\/p>\n\n\n\n<ul><li>Effectuer toutes autres t\u00e2ches d\u00e9finies par la hi\u00e9rarchie<\/li><li><br>SUPERIEUR HIERARCHIQUE :<br>Head Card Operations<\/li><li><br>QUALIFICATIONS &amp; EXPERIENCE REQUISES<\/li><li><\/li><li>Formation sup\u00e9rieure Bac + 3\/4 de pr\u00e9f\u00e9rence en finance, gestion, comptabilit\u00e9, marketing ou autres disciplines connexes.<\/li><li>Exp\u00e9rience dans le secteur bancaire et particuli\u00e8rement une bonne connaissance des produits digitaux et de la mon\u00e9tique;<\/li><li>Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur. Exp\u00e9rience dans le secteur bancaire et particuli\u00e8rement une bonne connaissance des produits digitaux et de la mon\u00e9tique;<\/li><li>Bonne maitrise du fonctionnement de Mastercard et Visa<\/li><li><br>ATTITUDES ET APTITUDES<\/li><li><\/li><li>Bonnes aptitudes communicationnelles et du travail en \u00e9quipe<\/li><li>Capacit\u00e9 \u00e0 travailler de fa\u00e7on autonome sur des objectifs fix\u00e9s<\/li><li>Sens aigu du travail bien fait.<\/li><li>Innovation<\/li><li>Ma\u00eetrise des outils Microsoft Word, Excel et Powerpoint<\/li><li>Bilingue Fran\u00e7ais\/Anglais serait un atout<\/li><li>La ma\u00eetrise de Microsoft ACCESS et de Visual Basic for Applications (VBA) serait un atout<\/li><li>Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur.<\/li><li>Bonne maitrise de la r\u00e8glementation en mon\u00e9tique en vigueur<\/li><li>Grande discr\u00e9tion, \u00eatre rigoureux dans le travail, efficace, et disponible<\/li><li>Etre dot\u00e9 d\u2019une compr\u00e9hension facile<\/li><li>Savoir r\u00e9sister \u00e0 la pression<\/li><li>Etre courtois,<\/li><li>Travailler en \u00e9quipe avec tout le personnel<\/li><li>Respecter les visiteurs et les collaborateurs<\/li><li>Avoir une parfaite ma\u00eetrise des techniques de communication<\/li><li>Etre autonome<\/li><li>Etre Polyvalent<\/li><li>Travailler en \u00e9quipe pluridisciplinaire<\/li><li><br>PROCESSUS DE CANDIDATURE<\/li><li><br>Bien vouloir transmettre votre CV et lettre de motivation \u00e0 ECM-Recruit@ecobank.com au plus tard le Vendredi 04 mars 2022 \u00e0 17h00 pr\u00e9cises en mentionnant en objet \u00ab Senior Service officer Ops, ATM &amp; All digital products reconciliation &amp; settlement \u00bb<\/li><li><br>ECOBANK CAMEROUN SA est une entreprise qui pr\u00f4ne l\u2019\u00e9galit\u00e9 des chances. Nous ne faisons pas de discrimination sur la base du genre, de la religion, de l\u2019appartenance ethnique, du statut social, de l\u2019aptitude physique, etc\u2026<br>Visitez notre site www.ecobank.com<br>PUBLIC<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>RECRUTEMENT : INTERNE \/ EXTERNEECOBANK CAMEROUN S.A. recrute pour les besoins de ses services, Un (01) Senior Service Officer OpsType de Contrat :CDI MISSION DU&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un (01) Senior Service Officer Ops","emplois_employeur":4430,"emplois_date_publication":"2022-02-25","emplois_heure_publication":"","emplois_date_cloture":"2022-03-04","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"ECM-Recruit@ecobank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28122"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=28122"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/28122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4443"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=28122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=28122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=28122"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=28122"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=28122"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=28122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}