{"id":27799,"date":"2022-02-14T04:46:46","date_gmt":"2022-02-14T03:46:46","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=27799"},"modified":"2022-02-14T04:46:47","modified_gmt":"2022-02-14T03:46:47","slug":"un-01-card-officer","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/un-01-card-officer\/","title":{"rendered":"Un (01) Card Officer"},"content":{"rendered":"\n<p>ECOBANK CAMEROUN S.A. recrute pour les besoins de ses services,<br><strong>Un (01) Card Officer<\/strong><br>Ce poste sera bas\u00e9 \u00e0 Douala.<br>JobLevel:3 -JobGrade:2A<br>TYPE DE CONTRAT<br>CDI<\/p>\n\n\n\n<p><br>MISSION DU POSTE<\/p>\n\n\n\n<p><br>Le titulaire du poste aura pour missions principales de :<br>Assurer la compensation\/R\u00e8glement des transactions par Cartes (Visa, MasterCard, CUP, GIMAC, GTP, etc\u2026)<br>Veiller \u00e0 ce que les r\u00e9conciliations et R\u00e8glement soient effectu\u00e9s quotidiennement afin d\u2019\u00e9viter \u00e0 la banque des pertes de change<br>Contribuer \u00e0 l\u2019am\u00e9lioration du service \u00e0 la client\u00e8le en garantissant une prompte r\u00e9solution des r\u00e9clamations des clients relatives aux paiements effectu\u00e9s sur d\u2019autres r\u00e9seaux (Interbancaire, Inter filiale, Online o\u00f9 \u00e0 l\u2019international).<br>Apporter une satisfaction g\u00e9n\u00e9rale aux clients et partenaires.<br>Aider \u00e0 l\u2019am\u00e9lioration de la qualit\u00e9 de service de la banque<br>Fournir un service de qualit\u00e9 afin de r\u00e9duire les r\u00e9clamations des clients Apporter de fa\u00e7on prompte les solutions aux r\u00e9clamations des clients Diminuer ou intercepter les actes de fraudes internes<br>Permettre la continuit\u00e9 de l\u2019activit\u00e9 avec les cartes en agissant \u00e0 temps<\/p>\n\n\n\n<p><br>PRINCIPALES RESPONSABILIT\u00c9S<\/p>\n\n\n\n<p><br>R\u00e9conciliation et Settlement des transactions Visa, MasterCard (\u00e9metteur et acqu\u00e9reur) R\u00e9conciliation et Settlement des transactions CUP, GTP, GIMAC<br>R\u00e9conciliation et Settlement des transactions PRIME ; MIGS<br>Assurer le suivi des ChargeBack et leur r\u00e9solution<br>Effectuer le rapprochement journalier des comptes de transactions par cartes (ACQUIRER SUSPENS ACCOUNT ; ISSUER S\/A ; PRIME; etc\u2026) dans CLIREC<br>Identifier les suspens dans ces comptes et les corrig\u00e9s<br>S\u2019assurer du respect du SLA dans le traitement des r\u00e9clamations des clients<br>Proposer\/initier la revue des proc\u00e9dures relatives \u00e0 la r\u00e9conciliation et \u00e0 la compensation des op\u00e9rations par cartes.<br>Veiller \u00e0 la bonne comptabilisation des revenus sur transactions (Interchange fees ; Mark-UP ; OIF; etc\u2026) Autoriser les op\u00e9rations d\u2019Onboarding sur IBK ;<br>V\u00e9rification factures GTP ; E-PROCESS ; VISA<\/p>\n\n\n\n<p>PRINCIPALES RESPONSABILIT\u00c9S<\/p>\n\n\n\n<p><br>Dispatcher des instant Cards aux agences sur INDIGO. Fournir les \u00e9l\u00e9ments de statistiques sur toutes les cartes Effectuer toutes autres t\u00e2ches d\u00e9finies par la hi\u00e9rarchie<br>SUPERIEUR HIERARCHIQUE<br>Head Cards OPS<\/p>\n\n\n\n<p><br>PROFIL DU POSTE<\/p>\n\n\n\n<p><br>Qualifications &amp; Experience Requises<br>Exp\u00e9rience dans le secteur bancaire et particuli\u00e8rement une bonne connaissance des produits digitaux et de la mon\u00e9tique ;<br>Bonne Maitrise des r\u00e8gles VISA\/MASTERCARD<br>Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur.<br>Formation sup\u00e9rieure Bac + 3\/4 de pr\u00e9f\u00e9rence en finance, gestion, comptabilit\u00e9, marketing ou autres disciplines connexes<\/p>\n\n\n\n<p><br>Attitudes Et Aptitudes<\/p>\n\n\n\n<p><br>Excellentes aptitudes communicationnelles et du travail en \u00e9quipe Capacit\u00e9 \u00e0 travailler de fa\u00e7on autonome sur des objectifs fix\u00e9s Sens aigu du travail bien fait.<br>Innovation<br>Ma\u00eetrise des outils Microsoft Word, Excel et Powerpoint<br>Connaissance en gestion des risques<br>Bilingue Fran\u00e7ais\/Anglais serait un atout<br>Une maitrise de l\u2019automatisation sur VBA serait un atout<br>Bonne maitrise de la r\u00e8glementation des finances et des services bancaires en vigueur. Bonne maitrise de la r\u00e8glementation en mon\u00e9tique en vigueur.<br>Grande discr\u00e9tion, \u00eatre rigoureux dans le travail, efficace, et disponible Etre dot\u00e9 d\u2019une comprehension facile<br>Savoir resister \u00e0 la pression<br>Etre courtois,<br>Travailler en \u00e9quipe avec tout le personnel<br>Respecter les visiteurs et les collaborateurs<br>Avoir une parfaite ma\u00eetrise des techniques de communication Etre autonome<br>Etre Polyvalent<br>Travailler en \u00e9quipe pluridisciplinaire<\/p>\n\n\n\n<p><br>PROCESSUS DE CANDIDATURE<\/p>\n\n\n\n<p><br>Bien vouloir transmettre votre CV et lettre de motivation \u00e0 ECM-Recruit@ecobank.com au plus tard le Vendredi 18 f\u00e9vrier 2022 \u00e0 17h00 pr\u00e9cises en mentionnant en objet \u00ab Card Officer\u00bb<br>ECOBANK CAMEROUN SA est une entreprise qui pr\u00f4ne l\u2019\u00e9galit\u00e9 des chances. Nous ne faisons pas de discrimination sur la base du genre, de la religion, de l\u2019appartenance ethnique, du statut social, de l\u2019aptitude physique, etc\u2026 Visitez notre site www.ecobank.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ECOBANK CAMEROUN S.A. recrute pour les besoins de ses services,Un (01) Card OfficerCe poste sera bas\u00e9 \u00e0 Douala.JobLevel:3 -JobGrade:2ATYPE DE CONTRATCDI MISSION DU POSTE Le&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[23],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un (01) Card Officer","emplois_employeur":4430,"emplois_date_publication":"2022-02-14","emplois_heure_publication":"","emplois_date_cloture":"2022-02-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"ECM-Recruit@ecobank.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27799"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=27799"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/4443"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=27799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=27799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=27799"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=27799"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=27799"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=27799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}