{"id":27785,"date":"2022-02-14T04:13:12","date_gmt":"2022-02-14T03:13:12","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=27785"},"modified":"2022-02-14T04:13:14","modified_gmt":"2022-02-14T03:13:14","slug":"une-responsable-des-activites-juridiques-legal-h-f-cdi","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/une-responsable-des-activites-juridiques-legal-h-f-cdi\/","title":{"rendered":"Un(e) responsable des activit\u00e9s juridiques (\u00ab Legal \u00bb) (H\/F) &#8211; CDI"},"content":{"rendered":"\n<p><br>KPMG C\u00f4te d\u2019Ivoire recrute :<\/p>\n\n\n\n<p><br><strong>Un(e) responsable des activit\u00e9s juridiques (\u00ab Legal \u00bb) (H\/F) &#8211; CDI<\/strong><\/p>\n\n\n\n<p><br>Pr\u00e9sentation de KPMG C\u00f4te d\u2019Ivoire :<\/p>\n\n\n\n<p><br>KPMG C\u00f4te d\u2019Ivoire est membre du r\u00e9seau KPMG International, l\u2019un des r\u00e9seaux mondiaux leader de l\u2019audit et du conseil, reconnu par les chefs d\u2019entreprises, les gouvernements et les bailleurs de<br>fonds.<br>KPMG C\u00f4te d\u2019Ivoire se positionne comme un acteur majeur de l\u2019offre d\u2019audit et de conseil en Afrique Subsaharienne.<br>Nos clients nous sollicitent de plus en plus pour des interventions \u00e0 forte valeur ajout\u00e9e, pour lesquelles nous agissons en tant que partenaire privil\u00e9gi\u00e9.<br>Vous recherchez une culture d&rsquo;entreprise o\u00f9 la gestion des comp\u00e9tences est une r\u00e9alit\u00e9. Gr\u00e2ce \u00e0 la multiplicit\u00e9 des \u00e9changes g\u00e9n\u00e9r\u00e9s par nos missions et \u00e0 la pr\u00e9sence internationale de notre<br>Cabinet, nous vous donnons les moyens de vous \u00e9panouir pleinement.<\/p>\n\n\n\n<p><br>R\u00f4le et responsabilit\u00e9s :<\/p>\n\n\n\n<p><br>Pour accompagner et poursuivre la dynamique de croissance de ses activit\u00e9s de conseil juridique en C\u00f4te d\u2019Ivoire et en Afrique Francophone Subsaharienne (AFS), nous recherchons un(e)<br>responsable des activit\u00e9s juridiques (\u00ab Legal \u00bb) qui rejoindra notre \u00e9quipe. La personne retenue sera sous la supervision du Senior Partner et de l\u2018Associ\u00e9 responsable de l\u2019activit\u00e9 Tax &amp; Legal.<br>Le poste est bas\u00e9 en C\u00f4te d\u2019Ivoire avec des d\u00e9placements \u00e9ventuels dans la r\u00e9gion AFS.<\/p>\n\n\n\n<p><br>Missions :<\/p>\n\n\n\n<p><br>Notre futur(e) responsable des activit\u00e9s juridiques devra \u00eatre un leader motiv\u00e9, dynamique, capable de s\u2019adapter et de d\u00e9montrer une exp\u00e9rience ant\u00e9rieure dans la plupart des t\u00e2ches et aptitudes<br>suivantes :<\/p>\n\n\n\n<p><br>\u2022 Assurer la gestion des activit\u00e9s de conseil juridique ;<br>\u2022 Assurer les missions de secr\u00e9tariat juridique de soci\u00e9t\u00e9s ;<br>\u2022 Exercer une fonction de conseil sur tous les aspects juridiques de la vie sociale de nos clients ;<br>\u2022 Savoir conduire les dossiers de Due Diligence juridique de nos diff\u00e9rents clients ;<br>\u2022 Savoir conduire les dossiers de restructuration d\u2019entreprises (incluant APA, M&amp;A, etc) ;<br>\u2022 R\u00e9diger des contrats commerciaux, en fran\u00e7ais et anglais (ex. PPP, contrats de sous-traitance, de fourniture, d&rsquo;exploitation et de maintenance, conventions de partenariats locaux et<br>internationaux, autres contrats \u00e9quivalents) ;<br>\u2022 Etre le lien principal entre nos clients et les acteurs juridiques externes, tels que les cabinets d\u2019avocats, les cabinets de notaires et les structures gouvernementales ;<br>\u2022 Assister nos clients dans la cr\u00e9ation d&rsquo;entreprises (ex. choix du type d&rsquo;entreprise, formalit\u00e9s de cr\u00e9ation et d&rsquo;enregistrement de l&rsquo;entreprise aupr\u00e8s des organismes sociaux et fiscaux, aide au<br>d\u00e9marrage, etc) ;<br>\u2022 Assister nos clients dans l\u2019obtention des agr\u00e9ments (ex. code des investissements, etc) ;<br>\u2022 Suivre les probl\u00e9matiques juridiques li\u00e9es au d\u00e9veloppement de nos clients \u00e0 l&rsquo;international ;<br>\u2022 D\u00e9finir des m\u00e9thodes de travail efficaces et encourager la collaboration entre les \u00e9quipes en AFS ;<br>\u2022 Assurer la gestion et le coaching des \u00e9quipes dans la r\u00e9alisation de leurs t\u00e2ches selon les standards de qualit\u00e9 requis par le r\u00e9seau KPMG ;<br>\u2022 Accompagner les \u00e9quipes dans la mise en \u0153uvre et l\u2019atteinte de leurs objectifs de carri\u00e8re ;<br>\u2022 Soutenir la strat\u00e9gie et le d\u00e9veloppement commercial futurs des engagements juridiques en AFS tout en d\u00e9veloppant le portefeuille du cabinet.<\/p>\n\n\n\n<p><br>Profil recherch\u00e9 :<\/p>\n\n\n\n<p><br>\u2022 Vous \u00eates titulaire d\u2019un dipl\u00f4me de 3\u00e8me cycle en droit des affaires et\/ou droit fiscal (DESS, DEA, DJCE, LLM, Mast\u00e8re, CAPA) et\/ou d\u2019un dipl\u00f4me de Grande Ecole ;<br>\u2022 Vous justifiez d\u2018environ 10 ann\u00e9es d&rsquo;exp\u00e9rience dans un important cabinet et\/ou au sein de la direction juridique et\/ou fiscale d&rsquo;un groupe international ;<br>\u2022 Vous avez une parfaite connaissance du droit OHADA ;<br>\u2022 Vous avez une culture juridique pluridisciplinaire en droit des affaires afin de pouvoir superviser et traiter les dossiers multi-pays du cabinet ;<br>\u2022 Une connaissance des r\u00e8gles de protection des donn\u00e9es en Afrique Subsaharienne serait un atout ;<br>\u2022 Vous avez une pratique courante de l&rsquo;anglais juridique tant \u00e0 l&rsquo;\u00e9crit qu&rsquo;\u00e0 l&rsquo;oral ;<br>\u2022 Vous faites preuve de comp\u00e9tences manag\u00e9riales av\u00e9r\u00e9es, avez le sens des responsabilit\u00e9s et une exp\u00e9rience de la gestion d\u2019\u00e9quipe pluridisciplinaire et transfrontali\u00e8re ;<br>\u2022 Vous \u00eates reconnu(e) pour votre curiosit\u00e9, votre motivation, votre excellent relationnel, et votre souci constant de la satisfaction client ;<br>\u2022 Vous \u00eates dynamique, entreprenant(e), dot\u00e9(e) d&rsquo;un fort esprit d&rsquo;analyse, et vous souhaitez \u00e9largir vos comp\u00e9tences dans un environnement stimulant.<br>Alors, n&rsquo;attendez plus pour nous rejoindre et faire vivre vos projets !<br>Adressez-nous votre dossier de candidature par courriel \u00e0 l\u2019adresse ci-recrutement@kpmg.ci avec l\u2019intitul\u00e9 du poste choisi en objet.<\/p>\n\n\n\n<p><br>Votre dossier devra inclure un curriculum vitae, une lettre de motivation pr\u00e9cisant vos pr\u00e9tentions salariales ainsi que les attestations de travail de vos deux derni\u00e8res exp\u00e9riences professionnelles.<br>Date limite de r\u00e9ception des candidatures : 15\/02\/2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KPMG C\u00f4te d\u2019Ivoire recrute : Un(e) responsable des activit\u00e9s juridiques (\u00ab Legal \u00bb) (H\/F) &#8211; CDI Pr\u00e9sentation de KPMG C\u00f4te d\u2019Ivoire : KPMG C\u00f4te d\u2019Ivoire&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[235],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Un(e) responsable des activit\u00e9s juridiques (\u00ab Legal \u00bb) (H\/F) - CDI","emplois_employeur":6401,"emplois_date_publication":"2022-02-14","emplois_heure_publication":"","emplois_date_cloture":"2022-02-15","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"ci-recrutement@kpmg.ci "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27785"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=27785"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6402"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=27785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=27785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=27785"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=27785"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=27785"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=27785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}