{"id":27706,"date":"2022-02-10T19:16:33","date_gmt":"2022-02-10T18:16:33","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=27706"},"modified":"2022-02-10T19:16:35","modified_gmt":"2022-02-10T18:16:35","slug":"chargee-de-communication-abidjan","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/chargee-de-communication-abidjan\/","title":{"rendered":"CHARG\u00c9E DE COMMUNICATION ABIDJAN"},"content":{"rendered":"\n<p>NOUS EMBAUCHONS CHARG\u00c9E DE COMMUNICATION ABIDJAN<\/p>\n\n\n\n<p> \u2022 Ma\u00eetrise et minimum 3 ans d&rsquo;exp\u00e9rience pertinente dans un r\u00f4le en communication Excellentes comp\u00e9tences en r\u00e9daction et en cr\u00e9ativit\u00e9 et \u00eatre capable de comprendre rapidement comment les exigences de l&rsquo;entreprise peuvent se traduire par des r\u00e9sultats exceptionnels. compoigns <\/p>\n\n\n\n<p>\u2022 Excellentes comp\u00e9tences interpersonnelles avec une capacit\u00e9 \u00e0 \u00e9tablir des relations avec des personnes \u00e0 tous les niveaux d&rsquo;anciennet\u00e9 et dans diff\u00e9rents d\u00e9partements<\/p>\n\n\n\n<p> \u2022 R\u00e9daction de communiqu\u00e9s de presse et cr\u00e9ation de listes de m\u00e9dias <\/p>\n\n\n\n<p>\u2022 Maintenir la sensibilisation et les relations avec les principaux m\u00e9dias et assurer la couverture des campagnes, y compris les m\u00e9dias nationaux, commerciaux, commerciaux et en ligne<\/p>\n\n\n\n<p> \u2022 La connaissance de la plateforme Canva et de la cr\u00e9ation de contenu vid\u00e9o est souhaitable Int\u00e9ress\u00e9? Nous serions ravis de vous en dire plus ! <br><\/p>\n\n\n\n<p>Merci d&rsquo;adresser votre CV \u00e0 cdi.recrutement@olamnet.com Avec pour objet : Poste de Charg\u00e9e de communication Avant le 28 f\u00e9vrier 2022<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOUS EMBAUCHONS CHARG\u00c9E DE COMMUNICATION ABIDJAN \u2022 Ma\u00eetrise et minimum 3 ans d&rsquo;exp\u00e9rience pertinente dans un r\u00f4le en communication Excellentes comp\u00e9tences en r\u00e9daction et en&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[25],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"CHARG\u00c9E DE COMMUNICATION ABIDJAN","emplois_employeur":24682,"emplois_date_publication":"2022-02-10","emplois_heure_publication":"","emplois_date_cloture":"2022-02-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cdi.recrutement@olamnet.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27706"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=27706"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/24683"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=27706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=27706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=27706"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=27706"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=27706"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=27706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}