{"id":27226,"date":"2022-01-26T16:45:01","date_gmt":"2022-01-26T15:45:01","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=27226"},"modified":"2022-01-26T16:45:04","modified_gmt":"2022-01-26T15:45:04","slug":"developpeur-dapplications-web","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2022\/developpeur-dapplications-web\/","title":{"rendered":"D\u00c9VELOPPEUR D\u2019APPLICATIONS WEB"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>FICHE DE POSTE<\/code><\/pre>\n\n\n\n<p>D\u00c9VELOPPEUR D\u2019APPLICATIONS WEB<br>Fonction<br>D\u00e9veloppeur d\u2019applications Web<br>P\u00f4le<br>D\u00e9veloppement logiciel<br>Structure<br>DSI<br>Type de contrat<br>CDI assorti d\u2019une p\u00e9riode d\u2019essai<br>Dur\u00e9e<br>Date<br>ASAP<br>Contexte<br>upOwa est une entreprise solidaire, cr\u00e9\u00e9e en France, avec la vocation de rayonner dans le monde un impact positif sur la vie des personnes et des communaut\u00e9s tout en assurant une rentabilit\u00e9 \u00e9conomique solide pour la p\u00e9rennit\u00e9 et le d\u00e9veloppement de ses actions.<br>Le personnel partage un socle de trois valeurs communes, fondements des motivations individuelles :<br>\u25cf Le COURAGE : Audace et Ouverture,<br>\u25cf Le BIEN-\u00caTRE : Respect et Partage,<br>\u25cf La R\u00c9USSITE COLLECTIVE : Organisation et Optimisation.<br>upOwa con\u00e7oit, d\u00e9veloppe, finance, produit, installe et exploite des solutions solaires adapt\u00e9es aux zones mal desservies par les r\u00e9seaux \u00e9lectriques publics en Afrique sub-saharienne.<br>La force de l\u2019entreprise r\u00e9side dans son mod\u00e8le \u00e9conomique, qui permet d\u2019offrir \u00e0 des familles et des micro-entrepreneurs auparavant sans \u00e9lectricit\u00e9, des \u00e9quipements garantis et \u00e0 un prix abordable gr\u00e2ce \u00e0 des facilit\u00e9s de paiement particuli\u00e8res.<br>L\u2019entreprise upOwa d\u00e9veloppe et int\u00e8gre des applications web, mobile et des APIs pour la gestion de ses clients et le contr\u00f4le \u00e0 distances des syst\u00e8mes install\u00e9s chez ceux-ci. L\u2019entreprise est aujourd\u2019hui en forte croissance. Elle compte actuellement un peu plus d\u2019une centaine d\u2019employ\u00e9s et pr\u00e9voit de se d\u00e9velopper rapidement dans les prochaines ann\u00e9es. Cette dynamique de d\u00e9veloppement des activit\u00e9s implique des besoins forts pour le d\u00e9veloppement de nouvelles solutions mais aussi l\u2019\u00e9volution de celles existantes..<br>L\u2019objet de la mission propos\u00e9e sera de contribuer au d\u00e9veloppement et \u00e0 l&rsquo;\u00e9volution de ces applications dans le respect des m\u00e9thodes Agiles (Scrum\/Kanban).<br>Base et Localisation du poste<br>Ce poste est bas\u00e9 \u00e0 la Direction G\u00e9n\u00e9rale d\u2019upOwa \u00e0 Yaound\u00e9.<br>Responsabilit\u00e9s du d\u00e9veloppeur d\u2019application web<br>Analyser les besoins et mod\u00e9liser les applications<\/p>\n\n\n\n<ol><li>Participation \u00e0 la d\u00e9finition des besoins fonctionnels en collaboration avec l\u2019ensemble des services op\u00e9rationnels,<\/li><li>Analyse des besoins fonctionnels avec mod\u00e9lisation,<\/li><li>Conception des solutions informatiques avec mod\u00e9lisation,<\/li><li>R\u00e9daction des dossiers de sp\u00e9cifications d\u00e9taill\u00e9s (analyse, mod\u00e9lisation, conception).<br>D\u00e9velopper les applications et les maintenir<\/li><li>D\u00e9veloppement des applications,<br>upOwa<br>SAS au capital de 10 000\u20ac, RC Grenoble 807 493 259 00012 Contact : info@upowa.org<\/li><li>Conception et ex\u00e9cution des sc\u00e9narios de tests,<\/li><li>D\u00e9ploiement et test des applications d\u00e9velopp\u00e9es,<\/li><li>Gestion des demandes de maintenances \u00e9volutive et correctives,<\/li><li>Int\u00e9gration des applications mobiles d\u00e9velopp\u00e9es avec les applications web existantes d\u2019upOwa,<\/li><li>Param\u00e9trage et int\u00e9gration des applications mobiles du march\u00e9 avec les applications existantes<br>d\u2019upOwa,<\/li><li>Veillez au respect de la m\u00e9thode Scrum au sein de l&rsquo;\u00e9quipe de d\u00e9veloppement<br>Fiche de poste<br>Assister les utilisateurs<\/li><li>Formation des utilisateurs,<\/li><li>Assistance aux \u00e9quipes op\u00e9rationnelles : analyse et r\u00e9solution \u00e0 distance de cas de SAV en rapport<br>avec les logiciels d\u00e9ploy\u00e9s,<\/li><li>R\u00e9daction de la documentation technique n\u00e9cessaire pour la p\u00e9rennit\u00e9 de la maintenance des<br>applications d\u00e9ploy\u00e9es en respectant les standards mis en place.<br>Organisation hi\u00e9rarchique<\/li><\/ol>\n\n\n\n<ul><li>Le DAW est plac\u00e9 sous la responsabilit\u00e9 directe du Responsable des d\u00e9veloppements logiciels (N+1)<\/li><li>Le DAW s&rsquo;int\u00e9grera au sein d\u2019une \u00e9quipe compos\u00e9 de :<\/li><li>01 Directeur des systemes d\u2019information (N+2),<\/li><li>01 Responsable des d\u00e9veloppements logiciel (N+1),<\/li><li>02 D\u00e9veloppeurs d\u2019applications,<\/li><li>01 Ing\u00e9nieur IT<\/li><li>01 IT Junior<br>Profil recherch\u00e9<\/li><li>Formation niveau BAC+5 (grande \u00e9cole ou universit\u00e9) en informatique, sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de logiciels et applications mobiles,<\/li><li>5 ans d\u2019exp\u00e9rience minimum \u00e0 un poste de similaire,<\/li><li>Ma\u00eetrise des langages de programmation Java, SQL, HTML5, CSS3, Javascript, Python<\/li><li>Ma\u00eetrise des environnements Java, Spring boot, VueJS, Glassfish, Tomcat, PostgreSQL, JUnit, AppSheet<\/li><li>Ma\u00eetrise des outils collaboratifs pour \u00e9quipes de d\u00e9veloppeurs (Git\/GitLab)<\/li><li>Bonne ma\u00eetrise de l\u2019anglais (lu, \u00e9crit, parl\u00e9)<\/li><li>Excellent relationnel et forte capacit\u00e9 \u00e0 travailler en \u00e9quipe<\/li><li>Forte autonomie et capacit\u00e9 \u00e0 travailler en mode projet<\/li><li>Forte motivation pour travailler au sein d\u2019une start-up \u00e0 impact social, et fort int\u00e9r\u00eat pour les questions<br>li\u00e9es \u00e0 l\u2019environnement et l\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie<\/li><li>Connaissances appr\u00e9ci\u00e9es dans le domaine du Big data<br>Processus de recrutement<br>upOwa<br>SAS au capital de 10 000\u20ac, RC Grenoble 807 493 259 00012 Contact : info@upowa.org Pour postuler, soumettez-nous votre candidature en remplissant le formulaire disponible via le lien ci-apr\u00e8s :<br>https:\/\/bit.ly\/3nSR15C<br>Les candidatures f\u00e9minines sont fortement encourag\u00e9es !<br>Fiche de poste<br>upOwa<br>SAS au capital de 10 000\u20ac, RC Grenoble 807 493 259 00012 Contact : info@upowa.org<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D\u00c9VELOPPEUR D\u2019APPLICATIONS WEBFonctionD\u00e9veloppeur d\u2019applications WebP\u00f4leD\u00e9veloppement logicielStructureDSIType de contratCDI assorti d\u2019une p\u00e9riode d\u2019essaiDur\u00e9eDateASAPContexteupOwa est une entreprise solidaire, cr\u00e9\u00e9e en France, avec la vocation de rayonner dans&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"D\u00c9VELOPPEUR D\u2019APPLICATIONS WEB","emplois_employeur":5832,"emplois_date_publication":"2022-01-26","emplois_heure_publication":"","emplois_date_cloture":"2022-02-28","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/bit.ly\/3nSR15C"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27226"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=27226"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/27226\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=27226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=27226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=27226"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=27226"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=27226"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=27226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}