{"id":26266,"date":"2021-12-30T03:27:50","date_gmt":"2021-12-30T02:27:50","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=26266"},"modified":"2021-12-30T03:32:50","modified_gmt":"2021-12-30T02:32:50","slug":"01-un-assistant-technico-commercial-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/01-un-assistant-technico-commercial-h-f\/","title":{"rendered":"01 (un) Assistant Technico-Commercial H\/F"},"content":{"rendered":"\n<p>Nous recrutons urgemment HSD-MELT recherche, 01 (un) Assistant technico-commercial H\/F pour l&rsquo;un de ses clients, acteur majeur du secteur de la quincaillerie, bas\u00e9 \u00e0 Douala, Les missions: Assister les \u00e9quipes commerciales dans leur activit\u0117s quotidiennes Faire les mails aux clients<\/p>\n\n\n\n<p> \u2022 Comprendre et proposer des produits adapt\u00e9s aux \u00e9quipements du client dans le domaine \u00e9lectrique en g\u00e9n\u00e9rale<\/p>\n\n\n\n<p> Profil recherch\u00e9 : <\/p>\n\n\n\n<p>\u2022 Avoir au moins un BTS industriel au tout autre dipl\u00f4me du domaine <\/p>\n\n\n\n<p>Avoir au moins 02 ann\u00e9es d&rsquo;exp\u00e9rience \u00e0 un poste similaire <\/p>\n\n\n\n<p>Avoir une bonne maitrise de SAGE Gestion Commerciale <\/p>\n\n\n\n<p>Avoir une bonne maitrise de l&rsquo;outil informatique <\/p>\n\n\n\n<p>Avoir le sens du relationnel <\/p>\n\n\n\n<p>Avoir une bonne \u00e9locution et une bonne capacit\u00e9 r\u00e9dactionnelle <\/p>\n\n\n\n<p>RECRUITMENT SERCES <\/p>\n\n\n\n<p>Ce poste vous int\u00e9resse ? <br><\/p>\n\n\n\n<p>Envoyez votre candidature \u00e0 : cameroon.office@hsd-melt.com ou via www.mhd.hsd-melt.com au plus tard le 30\/12\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous recrutons urgemment HSD-MELT recherche, 01 (un) Assistant technico-commercial H\/F pour l&rsquo;un de ses clients, acteur majeur du secteur de la quincaillerie, bas\u00e9 \u00e0 Douala,&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"01 (un) Assistant Technico-Commercial H\/F ","emplois_employeur":4816,"emplois_date_publication":"2021-12-30","emplois_heure_publication":"","emplois_date_cloture":"2021-12-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cameroon.office@hsd-melt.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/26266"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=26266"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/26266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13905"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=26266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=26266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=26266"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=26266"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=26266"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=26266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}