{"id":26095,"date":"2021-12-24T11:34:20","date_gmt":"2021-12-24T10:34:20","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=26095"},"modified":"2021-12-24T11:35:36","modified_gmt":"2021-12-24T10:35:36","slug":"chef-secteur-centre-210000ko","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/chef-secteur-centre-210000ko\/","title":{"rendered":"Chef Secteur Centre (210000KO)"},"content":{"rendered":"\n<p>LOCALISATION :YAOUNDE-REGION-CENTRE-CAMEROUN DATE DE PUBLICATION :22\/12\/2021<br>Description de l&#8217;emploi &#8211; Chef Secteur Centre (210000KO)<br>Description<\/p>\n\n\n\n<p>D\u00e9ployer et animer les op\u00e9rations terrain en droite ligne avec la politique commerciale d\u2019Orange, mettre en \u0153uvre le suivi et le contr\u00f4le op\u00e9rationnel des points de vente dans sa zone g\u00e9ographique:<\/p>\n\n\n\n<p>D\u00e9velopper les Parts de March\u00e9 (Telco &amp; Orange Money) au niveau des d\u00e9taillants<br>Superviser l\u2019activit\u00e9 des commerciaux Partners de son secteur<br>Assurer la veille concurrentielle terrain dans son secteur de vente<br>Co-Construire le Business Plan de son secteur en \u00e9troite collaboration avec son distributeur<br>Assurer le reporting et l\u2019analyse de la performance de l\u2019activit\u00e9 dans son secteur<\/p>\n\n\n\n<p>Qualifications<\/p>\n\n\n\n<p>Bac +2\/3 en commerce, ventes, distribution, Marketing ou gestion<\/p>\n\n\n\n<p>2 ans dans la vente de produits grand public<\/p>\n\n\n\n<p>Lieu principal: CM-Centre<br>Emploi: Client<br>Organisation: Orange Cameroun<br>: CDI<br>Type de contrat: Employ\u00e9<\/p>\n\n\n\n<p>Postulez UNIQUEMENT en ligne via le lien Internet dont l&rsquo;adresse est : https:\/\/orangecameroun.taleo.net\/careersection\/ex\/jobdetail.ftl<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LOCALISATION :YAOUNDE-REGION-CENTRE-CAMEROUN DATE DE PUBLICATION :22\/12\/2021Description de l&#8217;emploi &#8211; Chef Secteur Centre (210000KO)Description D\u00e9ployer et animer les op\u00e9rations terrain en droite ligne avec la politique&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Chef Secteur Centre (210000KO)","emplois_employeur":3116,"emplois_date_publication":"2021-12-24","emplois_heure_publication":"","emplois_date_cloture":"2022-01-24","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/orangecameroun.taleo.net\/careersection\/ex\/jobdetail.ftl"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/26095"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=26095"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/26095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2384"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=26095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=26095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=26095"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=26095"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=26095"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=26095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}