{"id":25532,"date":"2021-12-07T20:41:05","date_gmt":"2021-12-07T19:41:05","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=25532"},"modified":"2021-12-07T20:44:10","modified_gmt":"2021-12-07T19:44:10","slug":"assistant-rh-4","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/assistant-rh-4\/","title":{"rendered":"ASSISTANT RH"},"content":{"rendered":"\n<p>OFFRE D&rsquo;EMPLOL ASSISTANT RH, FORMATION ET GPEC <\/p>\n\n\n\n<p>ACTIVITES <\/p>\n\n\n\n<p>&#8211; Elaborer le Plan de Formation annuel en recueillant et synth\u00e9tisant les besoins des Directions \/ D\u00e9partements \/Services en ad\u00e9quation avec les orientations strat\u00e9giques de la banque 1 <\/p>\n\n\n\n<p>G\u00e9rer l&rsquo;organisation logistique et administrative des <\/p>\n\n\n\n<p>MISSION PRINCIPALE <\/p>\n\n\n\n<p>L&rsquo;Assistant RH Formation et GPECintervient au coeur du d\u00e9veloppement des comp\u00e9tences du personnel de la banque en accompagnant le changement de ses besoins et des enjeux futurs. actions de formation : supports de formation, enregistrements, gestion des pr\u00e9sences, logistique, <\/p>\n\n\n\n<p>Assurer l&rsquo;organisation des campagnes des \u00e9valuations annuelles de bout en bout (fixation des objectifs, \u00e9valuations semestrielles et annuelles, gestion des PAPS).<\/p>\n\n\n\n<p> 1 Suivi de la mise en euvre des actions li\u00e9es aux plans <\/p>\n\n\n\n<p>PROFIL &#8211; Minimum Bac+3enGestion des Ressources Humaines, Droit, Sociologie ouautre discipline assimil\u00e9e<\/p>\n\n\n\n<p> &#8211; Exp\u00e9rience minimum de 3ans \u00e0 un poste similaire, de pr\u00e9f\u00e9rence au sein d&rsquo;une banque, ou d&rsquo;un Cabinet de de succession <\/p>\n\n\n\n<p>Impl\u00e9menter de mani\u00e8re op\u00e9rationnelle les plans de mobilit\u00e9 valid\u00e9s Formation.<\/p>\n\n\n\n<p> &#8211; Mettre \u00e0 disposition les tableaux carri\u00e8re \u00e0 jour en cas de besoin <\/p>\n\n\n\n<p>LIEU: Douala <\/p>\n\n\n\n<p>DATE LIMITE: Lundi 13 D\u00e9cembre 2021 <\/p>\n\n\n\n<p>D\u00c9P\u00d4T DES CANDIDATURES |banque atlantique Cameroun Envoyez votre lettre de motivation et votre CV \u00e0 rh.recrutement@banqueatlantique.net en pr\u00e9cisant en objet \u201cAssistant RH\u00a0\u00bb atlanti Ggroup<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE D&rsquo;EMPLOL ASSISTANT RH, FORMATION ET GPEC ACTIVITES &#8211; Elaborer le Plan de Formation annuel en recueillant et synth\u00e9tisant les besoins des Directions \/ D\u00e9partements&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[20],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"ASSISTANT RH","emplois_employeur":2974,"emplois_date_publication":"2021-12-07","emplois_heure_publication":"","emplois_date_cloture":"2021-12-13","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"rh.recrutement@banqueatlantique.net en pr\u00e9cisant en objet \u201cAssistant RH\" atlanti Ggroup"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25532"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=25532"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2197"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=25532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=25532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=25532"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=25532"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=25532"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=25532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}