{"id":25500,"date":"2021-12-07T12:18:00","date_gmt":"2021-12-07T11:18:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=25500"},"modified":"2021-12-07T12:18:09","modified_gmt":"2021-12-07T11:18:09","slug":"webdesigner-professionnel-et-tres-creatif","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/webdesigner-professionnel-et-tres-creatif\/","title":{"rendered":"Webdesigner Professionnel et tr\u00e8s cr\u00e9atif"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>  Titre du poste : Recherche d'un webdesigner professionnel et tr\u00e8s cr\u00e9atif,\ndate d'expiration : 2021-12-08,\nentreprise : dnimas ccreative,\nPays : cameroun,\nvilles : douala,\ncontact pour postuler : etsdnimas@gmail.com\n<p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Dnimas Creative est une startup en cours de lancement et pour nos besoins de service nous recherchons un webdesigner junior mais tr\u00e8s cr\u00e9atif.<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Respectez les conditions suivantes\u00a0:<\/p> <p class=\"MsoListParagraphCxSpFirst\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Ag\u00e9 de 27 ans au max<\/p> <p class=\"MsoListParagraphCxSpMiddle\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Ma\u00eetriser parfaitement les logiciels tels qu\u2019Adobe Photoshop et Adobe XD (l\u2019un ou l\u2019autre, le plus important \u00e9tant la cr\u00e9ativit\u00e9)<\/p> <p class=\"MsoListParagraphCxSpMiddle\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Avoir d\u00e9j\u00e0 r\u00e9alis\u00e9 plusieurs maquettes web avec l\u2019un de ces logiciels<\/p> <p class=\"MsoListParagraphCxSpMiddle\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Etre dynamique et travailleur<\/p> <p class=\"MsoListParagraphCxSpMiddle\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Etre assez rapide dans son travail car la plus part des projets de l\u2019entreprise passera au pr\u00e9alable par une maquette web.<\/p> <p class=\"MsoListParagraphCxSpLast\" style=\"text-indent: -18.0pt\"><span><span>-<span style=\"font: 7.0pt 'Times New Roman'\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/span><\/span><\/span>Doit utiliser la plupart des r\u00e9seaux sociaux (Facebook, Instagram, Whatsapp,Tiktok et autres)<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Un test sera fait \u00e9ventuellement dans l\u2019entreprise pour juger vos comp\u00e9tences.<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">NB : Dans votre CV veillez pr\u00e9ciser le nombre de projets r\u00e9alis\u00e9s et les liens vers ceux-ci ou les joindre par mail.<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">La cr\u00e9ativit\u00e9 est la qualit\u00e9 la plus recherch\u00e9 \u00e0 ce poste.<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Horaire de travail : De lundi \u00e0 vendredi : 8h \u2013 17h<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Et \u00e9ventuellement les samedis en cas de travaux urgent : 9h \u2013 13h<\/p> <p class=\"MsoNormal\" style=\"margin-left: 18.0pt\">Entretien mercredi \u00e0 partir de 13h, pour toutes personnes int\u00e9ress\u00e9s, veillez envoyer votre CV \u00e0 l\u2019adresse email : massokadominique@gmail.com au plus tard le mardi 07\/12\/2021 20h.<\/p> <\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Webdesigner Professionnel et tr\u00e8s cr\u00e9atif","emplois_employeur":3046,"emplois_date_publication":"2021-12-07","emplois_heure_publication":"","emplois_date_cloture":"2021-12-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"etsdnimas@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25500"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=25500"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25500\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=25500"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=25500"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=25500"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=25500"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=25500"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=25500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}