{"id":25430,"date":"2021-12-06T00:41:00","date_gmt":"2021-12-05T23:41:00","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=25430"},"modified":"2021-12-06T00:41:03","modified_gmt":"2021-12-05T23:41:03","slug":"responsable-dexploitation-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-dexploitation-2\/","title":{"rendered":"RESPONSABLE D\u2019EXPLOITATION"},"content":{"rendered":"\n<p>RESPONSABLE D\u2019EXPLOITATION<\/p>\n\n\n\n<ul><li>Gestion &amp; Administration<\/li><li>Cameroun, Littoral, Douala<\/li><li><strong>RE-RH-049-11-21<\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Activit\u00e9 du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer la supervision, coordination et la gestion des activit\u00e9s du restaurant<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mettre en place des strat\u00e9gies marketing permettant d\u2019assurer un bon accueil et un service de qualit\u00e9 afin de d\u00e9velopper la marque employeur et fid\u00e9liser&nbsp;les clients<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer le reporting aupr\u00e8s de la Direction<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer la gestion financi\u00e8re, la d\u00e9finition des tarifs et le respect des normes<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Veiller \u00e0 la satisfaction clients<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;G\u00e9rer les r\u00e9servations<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Elaborer les plannings de travail du personnel<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Concevoir des strat\u00e9gies de d\u00e9veloppement et de performance de l\u2019\u00e9tablissement<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h2 class=\"wp-block-heading\">Profil du poste<\/h2>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Minimum BAC+3 en Gestion ,et\/ou&nbsp;&nbsp;Dipl\u00f4me de qualification professionnelle en&nbsp;h\u00f4tellerie&nbsp;et restauration&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Au moins 5 ans d\u2019exp\u00e9rience professionnelle \u00e0 un poste similaire<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maitrise des techniques d\u2019\u00e9laboration des menus et des calculs ratios en cuisine<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maitrise pratique du contr\u00f4le de production et de distribution culinaire<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maitrise des normes d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9 du secteur de la restauration<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maitrise des techniques d\u2019accueil, de vente et de relation clients<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Solides aptitudes en gestion administrative, financi\u00e8re et comptable<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maitrise de l\u2019outil informatique et du pack office<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Etre bilingue serait un atout&nbsp;<\/p>\n\n\n\n<p>&#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Savoir \u00eatre&nbsp;: Leadership, aisance relationnelle et communicationnelle, orientation r\u00e9sultat, esprit d\u2019\u00e9coute, sens du dialogue et de la n\u00e9gociation<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Job d\u00e9tail<\/h4>\n\n\n\n<ul><li>Reference :&nbsp;RE-RH-049-11-21<\/li><li>Publier le :&nbsp;2021-11-30 08:23:51<\/li><li>Localisation :&nbsp;AKWA_ Ancien Dalip<\/li><li>Niveau :&nbsp;BAC + 3<\/li><li>Type Emplois :&nbsp;Plein temps<\/li><li>Date Limite :&nbsp;2021-12-06 17:12:00<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>RESPONSABLE D\u2019EXPLOITATION Gestion &amp; Administration Cameroun, Littoral, Douala RE-RH-049-11-21 Activit\u00e9 du poste &#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Assurer la supervision, coordination et la gestion des activit\u00e9s du restaurant &#8211;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Mettre en&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[113],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"RESPONSABLE D\u2019EXPLOITATION","emplois_employeur":2630,"emplois_date_publication":"2021-12-06","emplois_heure_publication":"","emplois_date_cloture":"2021-12-09","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/emploi.ciblerh-emploi.com\/detail-offre\/OU2R32HJAYYP"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25430"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=25430"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2631"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=25430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=25430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=25430"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=25430"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=25430"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=25430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}