{"id":25315,"date":"2021-12-01T11:18:22","date_gmt":"2021-12-01T10:18:22","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=25315"},"modified":"2021-12-01T11:18:25","modified_gmt":"2021-12-01T10:18:25","slug":"recrutement-chauffeurs-voitures","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/recrutement-chauffeurs-voitures\/","title":{"rendered":"*RECRUTEMENT CHAUFFEURS VOITURES*"},"content":{"rendered":"\n<p>*RECRUTEMENT CHAUFFEURS VOITURES*<\/p>\n\n\n\n<p>Pour les besoins de ses services, une nouvelle entreprise *russe* de la place recrute des chauffeurs.<\/p>\n\n\n\n<p>*BESOINS :*<br>&#8211; 49 chauffeurs.<\/p>\n\n\n\n<p>*CONDITIONS :*<br>&#8211; \u00catre majeur (+21)<br>&#8211; Permis de conduire valide<br>&#8211; \u00catre disponible pour les services<br>&#8211; Poss\u00e9der un t\u00e9l\u00e9phone Android (pour t\u00e9l\u00e9charger l&rsquo;application de travail)<br>&#8211; Avoir la disponibilit\u00e9 d&rsquo;une \u00a0\u00bbvoiture\u00a0\u00bb est obligatoire<\/p>\n\n\n\n<p>*VILLE:*<br>&#8211; Douala (pour le moment)<\/p>\n\n\n\n<p>*SALAIRE:*<br>&#8211; 120.000fcfa ~ 400.000fcfa (salaire minimal de 120.000fcfa \u00e0 condition de faire 3 courses par jour pendant 20 jours)<\/p>\n\n\n\n<p>*HORAIRES :*<br>*- Jours:* *flexibles* (de lundi \u00e0 dimanche, 7j\/7j chaque chauffeur organise son emploi du temps selon sa disponibilit\u00e9)<br>*- Heures:* *flexibles* ( 24h\/24h, chaque chauffeur d\u00e9cide de ses heures de travail selon sa disponibilit\u00e9).<br>Contact : 691281995<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*RECRUTEMENT CHAUFFEURS VOITURES*<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[369],"tags":[],"villes":[2714],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"*RECRUTEMENT CHAUFFEURS VOITURES*","emplois_employeur":3046,"emplois_date_publication":"2021-12-01","emplois_heure_publication":"","emplois_date_cloture":"2021-12-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"1","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25315"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=25315"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/25315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=25315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=25315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=25315"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=25315"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=25315"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=25315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}