{"id":24927,"date":"2021-11-22T03:33:08","date_gmt":"2021-11-22T02:33:08","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24927"},"modified":"2021-11-23T12:21:49","modified_gmt":"2021-11-23T11:21:49","slug":"analyste-immobilier","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/analyste-immobilier\/","title":{"rendered":"ANALYSTE IMMOBILIER"},"content":{"rendered":"\n<p>ANALYSTE IMMOBILIER<br>(Stage Pr\u00e9-emploi)<br>LECKPA GROUP SARL (Yaound\u00e9, Cameroun)<br>Publi\u00e9e : 19 Novembre 2021<br>Domaine de l&rsquo;offre : Foncier-Immobilier<br>Lieu : R\u00e9gion du centre, Cameroun<br>Type de l&rsquo;offre : STAGE PRE-EMPLOI (06 mois \u00e0 09 Mois) Temps Plein<br>NB : Tout candidat doit avoir une bonne connaissance pratique et administrative des<br>proc\u00e9dures d\u2019acquisitions et ventes fonci\u00e8res.<br>L\u2019entreprise LECKPA GROUP SARL recherche actuellement une personne form\u00e9e<br>acad\u00e9miquement et apte en question fonci\u00e8re.<br>MISSIONS<br>Rapportant chez le Manageur du d\u00e9partement immobilier, il ou elle aura pour mission :<\/p>\n\n\n\n<ul><li>La prospection des sites \u00e0 acqu\u00e9rir ;<\/li><li>La r\u00e9daction de rapports d\u2019inspection et communication subs\u00e9quente \u00e0 la hi\u00e9rarchie<\/li><li>L\u2019\u00e9tablissement d\u2019une proc\u00e9dure d\u2019acquisition adapt\u00e9e \u00e0 chaque dossier ;<\/li><li>Pr\u00e9d\u00e9finir les \u00e9tapes \u00e0 parcourir pour chaque acquisition avec d\u00e9lais approximatifs ainsi<br>que les diff\u00e9rents r\u00e9sultats attendus \u00e0 la fin de chacune des \u00e9tapes incluant les pi\u00e8ces<br>justificatives (documents administratifs conformes etc.) ;<\/li><li>Collaborer avec d\u2019autres d\u00e9partements pour s\u2019assurer que ces r\u00e9sultats sont atteints, les<br>pi\u00e8ces justificatives et documents administratifs sont fournis ;<\/li><li>Le suivi des projets immobiliers sur le terrain et en entreprise ;<br>Page 2 sur 2<\/li><li>L\u2019\u00e9valuation les projets immobiliers et proposition des solutions fiables ;<\/li><li>Anticiper et \u00e9viter les litiges fonciers dans les diff\u00e9rents dossiers ;<\/li><li>Avoir une bonne connaissance des m\u00e9thodes juridiques de r\u00e9solutions des litiges fonciers<br>selon divers cas ;<\/li><li>\u00catre capable de diligenter un projet foncier de l\u2019acquisition \u00e0 la vente ;<\/li><li>Maitriser la communication en entreprise ainsi que les outils de communication<br>moderne.<\/li><li><br>QUALIT\u00c9S<\/li><li><\/li><li>\u00catre honn\u00eate, loyal(e) et respectueux(se) ;<\/li><li>Avoir un sens pouss\u00e9 de l\u2019organisation et l\u2019anticipation ;<\/li><li>\u00catre capable de proposer des am\u00e9liorations ;<\/li><li>\u00catre dot\u00e9 d\u2019un bon relationnel et d\u2019une grande capacit\u00e9 d\u2019adaptation ;<\/li><li>Avoir une grande autonomie dans le travail ;<\/li><li>Pouvoir travailler sous pression<\/li><li>\u00catre capable de bien utiliser les logiciels Word, Excel, PowerPoint ;<\/li><li>Maitriser l\u2019art de la communication professionnelle.<br>PROFIL<\/li><li>Avoir au minimum BAC +3 ;<\/li><li>Avoir une exp\u00e9rience pratique dans le domaine foncier ;<\/li><li>Avoir une bonne connaissance du droit li\u00e9 aux questions fonci\u00e8res ;<\/li><li>Avoir une bonne sant\u00e9 physique et mentale ;<\/li><li>Avoir une formation professionnelle dans le domaine foncier est un plus<br>N.B : Avoir son ordinateur portable personnel et son t\u00e9l\u00e9phone Android(obligatoire)<\/li><\/ul>\n\n\n\n<p>Envoyez votre dossier de candidature CV et Lettre de Motivation \u00e0 : jobs@leckpagroup.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANALYSTE IMMOBILIER(Stage Pr\u00e9-emploi)LECKPA GROUP SARL (Yaound\u00e9, Cameroun)Publi\u00e9e : 19 Novembre 2021Domaine de l&rsquo;offre : Foncier-ImmobilierLieu : R\u00e9gion du centre, CamerounType de l&rsquo;offre : STAGE PRE-EMPLOI&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1139],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"ANALYSTE IMMOBILIER","emplois_employeur":8367,"emplois_date_publication":"2021-11-22","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"jobs@leckpagroup.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24927"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24927"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/8368"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24927"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24927"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24927"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}