{"id":24886,"date":"2021-11-20T19:12:46","date_gmt":"2021-11-20T18:12:46","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24886"},"modified":"2021-11-20T19:12:51","modified_gmt":"2021-11-20T18:12:51","slug":"community-manager-yaounde-ihuman-resource-solutions","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/community-manager-yaounde-ihuman-resource-solutions\/","title":{"rendered":"COMMUNITY MANAGER &#8211; YAOUNDE IHUMAN RESOURCE SOLUTIONS"},"content":{"rendered":"\n<p>COMMUNITY MANAGER &#8211; YAOUNDE IHUMAN RESOURCE SOLUTIONS <\/p>\n\n\n\n<p>HSD-Melt recherche pour l&rsquo;un de ses clients, un Community Manager (H\/F) pour accompagner le d\u00e9veloppement de ses activit\u00e9s dans la ville de Yaound\u00e9, au Cameroun <\/p>\n\n\n\n<p>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/p>\n\n\n\n<p> \u2022 Bilingue : Fran\u00e7ais et anglais ;<\/p>\n\n\n\n<p> \u2022 Niveau BAC + 4 minimum;<\/p>\n\n\n\n<p> \u2022 Minimum 5 ans d&rsquo;exp\u00e9rience en Community management ; <\/p>\n\n\n\n<p>\u2022 Maitrise parfaite de MS Office : Power point, Word and Excel. <\/p>\n\n\n\n<p>Comp\u00e9tences fonctionnelles : <\/p>\n\n\n\n<p>Cr\u00e9ativit\u00e9, analyse, capacit\u00e9 d&rsquo;adaptation, connaissance du march\u00e9 et des tendances, multit\u00e2ches et gestion de plusieurs priorit\u00e9s concurrentes maitrise des principaux langages (HTML et d\u00e9riv\u00e9s)<\/p>\n\n\n\n<p>CsS, Pack Adobe (Photoshop, Illustrator, Image Ready), notions en programmation (javascript, php..) Documents de candidature \u00bb <\/p>\n\n\n\n<p>Lettre de motivation \u00bb Curriculum Vitae <\/p>\n\n\n\n<p>Les candidats int\u00e9ress\u00e9s sont pri\u00e9s de faire parvenir leur candidature \u00e0 l&rsquo;adresse cameroon.office@hsd- melt.com et https:\/\/mhd.hsd-melt.com au plus tard le 30\/11\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COMMUNITY MANAGER &#8211; YAOUNDE IHUMAN RESOURCE SOLUTIONS HSD-Melt recherche pour l&rsquo;un de ses clients, un Community Manager (H\/F) pour accompagner le d\u00e9veloppement de ses activit\u00e9s&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1773,300],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"COMMUNITY MANAGER - YAOUNDE IHUMAN RESOURCE SOLUTIONS ","emplois_employeur":4816,"emplois_date_publication":"2021-11-20","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cameroon.office@hsd- melt.com et https:\/\/mhd.hsd-melt.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24886"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24886"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13905"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24886"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24886"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24886"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}