{"id":24767,"date":"2021-11-17T19:38:52","date_gmt":"2021-11-17T18:38:52","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24767"},"modified":"2021-11-17T19:39:07","modified_gmt":"2021-11-17T18:39:07","slug":"avis-dappel-a-candidatures-pour-le-recrutement-dun-superviseur-regional-pour-le-projet-star","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/avis-dappel-a-candidatures-pour-le-recrutement-dun-superviseur-regional-pour-le-projet-star\/","title":{"rendered":"AVIS D\u2019APPEL A CANDIDATURES POUR LE RECRUTEMENT D\u2019UN SUPERVISEUR REGIONAL POUR LE PROJET STAR"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><br>AVIS D\u2019APPEL A CANDIDATURES POUR LE RECRUTEMENT D\u2019UN SUPERVISEUR REGIONAL POUR LE PROJET STAR<\/h3>\n\n\n\n<p><strong>Contexte et justification<\/strong><\/p>\n\n\n\n<p><em>&nbsp;Avec plus de 45 ann\u00e9es d&rsquo;exp\u00e9rience et travaillant dans plus de 50 pays, Population Services International (PSI) est le leader mondial du marketing social \u00e0 but non lucratif. PSI r\u00e9invente les soins de sant\u00e9, en mettant le consommateur au centre, et dans la mesure du possible en apportant des soins \u00e0 la porte d&rsquo;entr\u00e9e. Nous nous effor\u00e7ons de corriger les d\u00e9faillances du march\u00e9, de fa\u00e7onner les futurs march\u00e9s dans le domaine de la sant\u00e9 et de modifier les politiques et le financement afin de mieux soutenir les soins de sant\u00e9 ax\u00e9s sur les consommateurs.<\/em><\/p>\n\n\n\n<p><em>&nbsp;L&rsquo;Association Camerounaise pour le Marketing Social (ACMS) est une organisation non gouvernementale de droit Camerounais et membre du R\u00e9seau de Population Services International (PSI) depuis 1996. ACMS est reconnu comme \u00e9tant l&rsquo;un des principaux acteurs au Cameroun dans la pr\u00e9vention du VIH \/ SIDA et la promotion de la planification familiale \u00e0 travers le marketing social et la communication pour le changement de comportement. ACMS est une organisation complexe avec de multiples projets et donateurs et une large gamme de produits et services, y compris un projet de franchisage social avec 372 cliniques au sein du r\u00e9seau.<\/em><\/p>\n\n\n\n<p><em>L\u2019Association Camerounaise pour le Marketing Social (ACMS) \u00e0 travers son partenaire technique Population Services International (PSI) a s\u00e9curis\u00e9 un financement pour le d\u00e9marrage d\u2019un projet d\u2019auto- d\u00e9pistage du VIH au Cameroun appel\u00e9 \u00ab&nbsp;HIV Self-Testing Africa Initiative&nbsp;\u00bb (STAR) et financ\u00e9 par Unitaid.&nbsp;<\/em><\/p>\n\n\n\n<p><em>En effet l\u2019initiative STAR vise \u00e0 apporter un appui au gouvernement du Cameroun en vue de l&rsquo;\u00e9limination des barri\u00e8res li\u00e9es au d\u00e9veloppement du march\u00e9 de l\u2019auto- d\u00e9pistage volontaire \u00e0 travers la mise en place des structures, des syst\u00e8mes et des m\u00e9canismes de surveillance n\u00e9cessaires \u00e0 la durabilit\u00e9 des actions sur le long terme en utilisant les connaissances obtenues des succ\u00e8s et bonnes pratiques de l\u2019initiative STAR dans d\u2019autres pays.<\/em><\/p>\n\n\n\n<p><em>Toutefois, l<\/em><em>e projet STAR va faciliter le passage \u00e0 l&rsquo;\u00e9chelle rapide de l\u2019auto d\u00e9pistage du VIH, dans le but de r\u00e9duire la mortalit\u00e9 et la morbidit\u00e9 li\u00e9es au VIH dans les pays cibles. L&rsquo;extension de l&rsquo;initiative STAR aura un impact direct sur la sant\u00e9 publique en r\u00e9duisant le nombre de nouvelles infections \u00e0 VIH et en \u00e9vitant les d\u00e9c\u00e8s dus \u00e0 l&rsquo;infection \u00e0 VIH en augmentant la demande et l&rsquo;acc\u00e8s \u00e0 l\u2019auto d\u00e9pistage du VIH et aux services de traitement et de pr\u00e9vention ult\u00e9rieurs.&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p><em>Au niveau du Cameroun, le Projet est mis en \u0153uvre dans deux r\u00e9gions&nbsp;: le Centre et le Sud. Les cibles vis\u00e9es sont les travailleurs des grands entreprises, les partenaires de PVVIH et femmes enceintes et les jeunes \u00e0 haut risque (18 \u00e0 24 ans).<\/em><\/p>\n\n\n\n<p><em>Afin d\u2019assurer la mise en \u0153uvre<\/em><em>&nbsp;du projet STAR dans les r\u00e9gions s\u00e9lectionn\u00e9es<\/em><em>,&nbsp;<\/em><em>l\u2019ACMS recherche pour les besoins de service, un (01) Superviseur R\u00e9gional.<\/em><\/p>\n\n\n\n<p><strong>Type de contrat&nbsp;: Contrat \u00e0 Dur\u00e9e D\u00e9termin\u00e9 li\u00e9 \u00e0 la dur\u00e9e du Projet&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Lieu de travail : &nbsp;&nbsp;Yaound\u00e9<\/strong><\/p>\n\n\n\n<p><strong>Niveau du poste :&nbsp;9\u00e8me cat\u00e9gorie, \u00e9chelon A du secteur tertiaire II de la Convention Collective Nationale du Commerce<\/strong><\/p>\n\n\n\n<p><strong>Type de Poste&nbsp;: Junior<\/strong><\/p>\n\n\n\n<p><strong>Statut&nbsp;:<\/strong>&nbsp;<strong>Poste Local<\/strong><\/p>\n\n\n\n<p><strong>Date de prise de fonction&nbsp;: Janvier 2022<\/strong><\/p>\n\n\n\n<p><strong>Description du poste<\/strong><\/p>\n\n\n\n<p>Travaillant sous la supervision directe du Coordonnateur du Projet STAR, le Superviseur R\u00e9gional aura pour responsabilit\u00e9s de&nbsp;:<\/p>\n\n\n\n<ul><li>Participer et veiller au recrutement des partenaires \u00e0 impliquer dans le Projet STAR H\u00e9patite C&nbsp;;<\/li><li>Suivre et archiver les contrats des associations partenaires et les autres documents cl\u00e9s du Projet au niveau de la r\u00e9gion de comp\u00e9tence ;<\/li><li>Coordonner et superviser les associations impliqu\u00e9es dans le projet STAR dans la r\u00e9gion de comp\u00e9tence&nbsp;;<\/li><li>Repr\u00e9senter le Projet STAR \u00e0 toutes les r\u00e9unions organis\u00e9es dans la r\u00e9gion de comp\u00e9tence sur d\u00e9l\u00e9gation de sa hi\u00e9rarchie&nbsp;;<\/li><li>D\u00e9velopper et entretenir de bonnes relations de travail avec les partenaires de mise en \u0153uvre&nbsp;;<\/li><li>Impl\u00e9menter les strat\u00e9gies mises en place par la coordination du Projet conform\u00e9ment aux Directives nationales en vue de garantir un plein succ\u00e8s du Projet au niveau r\u00e9gional ;<\/li><li>Veiller \u00e0 l\u2019atteinte des objectifs de distribution des kits d\u2019auto tests dans sa r\u00e9gion ;<\/li><li>Coordonner et veiller \u00e0 la mobilisation des partenaires lors des \u00e9v\u00e8nements sp\u00e9ciaux identifi\u00e9s au niveau national et r\u00e9gional ;<\/li><li>Assurer le renforcement des capacit\u00e9s des acteurs de mise en \u0153uvre de la r\u00e9gion de comp\u00e9tence&nbsp;;<\/li><li>Suivre et superviser sur une base hebdomadaire les activit\u00e9s des acteurs de mise en \u0153uvre&nbsp;;<\/li><li>Contribuer au d\u00e9veloppement et\/ou \u00e0 l&rsquo;utilisation des informations, des messages de communication li\u00e9s \u00e0 la cr\u00e9ation de la demande en mati\u00e8re d\u2019auto d\u00e9pistage h\u00e9patite C&nbsp;;<\/li><li>G\u00e9rer le mat\u00e9riel promotionnel et les supports \u00e9ducatifs, outils de collecte et autres outils de cr\u00e9ation de la demande produits par le projet et veiller \u00e0 la mise \u00e0 disposition de ceux-ci aux partenaires de mise en \u0153uvre ;<\/li><li>Mettre \u00e0 jour le fichier des partenaires du projet au niveau r\u00e9gional ;<\/li><li>Organiser les r\u00e9unions de coordination mensuelle e avec les partenaires de mise en \u0153uvre de sa r\u00e9gion de comp\u00e9tence ;<\/li><li>Participer et veiller \u00e0 la tenue de tous les ateliers organis\u00e9s au niveau r\u00e9gional dans le cadre du Projet&nbsp;;<\/li><li>Veiller \u00e0 la synergie et la compl\u00e9mentarit\u00e9 d&rsquo;actions entre les diff\u00e9rents partenaires op\u00e9rationnels impliqu\u00e9s dans l\u2019ADVIH ;<\/li><li>S\u2019assurer de la compl\u00e9tude et promptitude des donn\u00e9es de sa r\u00e9gion enregistr\u00e9es dans DHIS2 ;<\/li><li>Veiller \u00e0 la compilation des rapports des partenaires de mise en oevure et \u00e0 la r\u00e9daction des rapports du Projet au niveau r\u00e9gional ;<\/li><li>Ex\u00e9cuter toutes autres t\u00e2ches li\u00e9es \u00e0 vos activit\u00e9s \u00e0 vous assign\u00e9es par la hi\u00e9rarchie.<\/li><\/ul>\n\n\n\n<p><strong>Qualifications et exp\u00e9rience professionnelle requises&nbsp;<\/strong><\/p>\n\n\n\n<ul><li>Avoir&nbsp;<strong>un dipl\u00f4me d\u2019\u00e9tudes d\u2019au moins BACC+3 en sciences sociales, sant\u00e9 publique, droit, gestion des projets ou tout autre dipl\u00f4me li\u00e9 au d\u00e9veloppement<\/strong>&nbsp;<strong>;<\/strong><\/li><li><strong>Avoir au moins deux (02) ann\u00e9es d\u2019exp\u00e9rience professionnelle en mati\u00e8re de gestion des projets, ou de mise en \u0153uvre des interventions \u00e0 une \u00e9chelle r\u00e9gionale.<\/strong><\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences suppl\u00e9mentaires requises :<\/strong><\/p>\n\n\n\n<ul><li><strong>Avoir une parfaite ma\u00eetrise de la langue fran\u00e7aise et une bonne capacit\u00e9 de travail de la langue anglaise.&nbsp;<\/strong><\/li><li><strong>Disposer d\u2019un permis A pour conduite de moto ;<\/strong><\/li><li><strong>Avoir de bonnes connaissances \u00e0 jour en mati\u00e8re de lutte contre le VIH, les h\u00e9patites au Cameroun&nbsp;;<\/strong><\/li><li><strong>Jouir des comp\u00e9tences av\u00e9r\u00e9es dans le renforcement des capacit\u00e9s des adultes en mati\u00e8re de VIH, h\u00e9patite C ou tout autre th\u00e9matique de sant\u00e9 publique au cours des deux derni\u00e8res ann\u00e9es ;<\/strong><\/li><li><strong>Avoir des comp\u00e9tences en mati\u00e8re d&rsquo;analyse, de r\u00e9daction de rapports et d&rsquo;\u00e9dition ;<\/strong><\/li><li><strong>Jouir de solides comp\u00e9tences en mati\u00e8re de facilitation des ateliers de renforcement de capacit\u00e9s des adultes ;<\/strong><\/li><li><strong>Avoir une bonne ma\u00eetrise de l\u2019outil informatique et des logiciels (Word, power point, Excel)<\/strong><\/li><li><strong>\u00catre capable de suivre les r\u00e9sultats et les d\u00e9penses des projets par rapport aux plans de travail ;<\/strong><\/li><li><strong>Avoir des comp\u00e9tences en mati\u00e8re de gestion ax\u00e9e sur les r\u00e9sultats<\/strong><\/li><li><strong>\u00catre disponible \u00e0 effectuer des missions r\u00e9guli\u00e8res de terrain&nbsp;<\/strong><\/li><li><strong>La familiarit\u00e9 avec le marketing social et\/ou les ONG constitue un atout.<\/strong><\/li><\/ul>\n\n\n\n<p><strong>Exp\u00e9rience Professionnelle Requise en Substitution du Dipl\u00f4me&nbsp;:<\/strong><\/p>\n\n\n\n<ul><li>Avoir&nbsp;<strong>Plus de cinq (05) ann\u00e9es d\u2019exp\u00e9rience professionnelle en mati\u00e8re de gestion des projets, ou de mise en \u0153uvre des interventions \u00e0 une \u00e9chelle r\u00e9gionale.<\/strong><\/li><\/ul>\n\n\n\n<p><strong>Dossier de candidature&nbsp;<\/strong><\/p>\n\n\n\n<ol><li>Une Lettre de motivation&nbsp;;<\/li><li>Un curriculum vitae d\u00e9taill\u00e9 (CV)&nbsp;suivant le formulaire disponible \u00e0 cet effet sur le site&nbsp;:&nbsp;<strong>http:\/\/ www.acms-cm.org<\/strong>&nbsp;;<\/li><li>Photocopies des dipl\u00f4mes exig\u00e9s. Une v\u00e9rification des Dipl\u00f4mes sera effectu\u00e9e pour le\/la candidat (e) retenu(e)&nbsp;;<\/li><li>Les photocopies des documents qui justifient l\u2019exp\u00e9rience du \/ de la candidat (e), (Attestation, d\u2019emploi, certificat de travail, ou tout autre document y relatif)&nbsp;;<\/li><\/ol>\n\n\n\n<p><strong>Lieu de d\u00e9p\u00f4ts des dossiers<\/strong><\/p>\n\n\n\n<p>Les dossiers complets seront envoy\u00e9s \u00e0 l\u2019adresse suivante&nbsp;:&nbsp;<strong>https:\/\/jobs.acms-cm.org<\/strong><\/p>\n\n\n\n<p><strong>N.B&nbsp;: Les candidatures se feront uniquement par le site internet de l\u2019ACMS.<\/strong><\/p>\n\n\n\n<p>&nbsp;Les candidats sous contrat avec la fonction publique Camerounaise ne sont pas \u00e9ligibles.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>STATUT<\/strong><\/p>\n\n\n\n<ul><li>Exempt<\/li><\/ul>\n\n\n\n<p>&nbsp;<em>PSI est un employeur \u00e9quitable et encourage les candidatures de personnes qualifi\u00e9es sans distinction de race, religion, couleur, sexe, \u00e2ge, origine nationale, handicap, \u00e9tat matrimonial, immatriculation, appartenance politique, statut ou responsabilit\u00e9s familiales, identit\u00e9 ou, grossesse, accouchement, conditions m\u00e9dicales connexes ou allaitement maternel, information g\u00e9n\u00e9tique, amnistie, ancien combattant, ancien combattant handicap\u00e9, statut de membre des forces arm\u00e9es ou de statut professionnel.<\/em><\/p>\n\n\n\n<p><strong>ACMS est un employeur qui offre des chances \u00e9gales d\u2019emploi et encourage fortement les candidatures f\u00e9minines. Seuls les candidats pr\u00e9s\u00e9lectionn\u00e9s seront contact\u00e9s.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>L\u2019ACMS se r\u00e9serve le droit de proc\u00e9der \u00e0 un recrutement \u00e0 un niveau inf\u00e9rieur ou sur la base d&rsquo;un profil de poste modifi\u00e9.<\/strong><br><a href=\"https:\/\/jobs.acms-cm.org\/en\/informations_personnelles\/26.html\">Apply<\/a><a href=\"https:\/\/jobs.acms-cm.org\/upload\/0ab70c8b81c3d3243ec65e443850113c.pdf\">Download the call for applications<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVIS D\u2019APPEL A CANDIDATURES POUR LE RECRUTEMENT D\u2019UN SUPERVISEUR REGIONAL POUR LE PROJET STAR<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"AVIS D\u2019APPEL A CANDIDATURES POUR LE RECRUTEMENT D\u2019UN SUPERVISEUR REGIONAL POUR LE PROJET STAR","emplois_employeur":3436,"emplois_date_publication":"2021-11-17","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/jobs.acms-cm.org\/en\/informations_personnelles\/26.html"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24767"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24767"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/3437"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24767"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24767"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24767"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}