{"id":24733,"date":"2021-11-17T01:33:40","date_gmt":"2021-11-17T00:33:40","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24733"},"modified":"2021-11-17T01:33:44","modified_gmt":"2021-11-17T00:33:44","slug":"digital-brand-content-manager","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/digital-brand-content-manager\/","title":{"rendered":"Digital Brand Content Manager"},"content":{"rendered":"\n<pre class=\"wp-block-code\"><code>Titre du poste : Digital Brand Content Manager,\ndate d'expiration : 2021-12-15,\nentreprise (existante dans notre base de donn\u00e9es) : \"Soci\u00e9t\u00e9 internationale de renomm\u00e9e, sp\u00e9cialis\u00e9e dans le Business d\u00e9veloppement et Marketing Digital, pr\u00e9sente dans 14 pays et op\u00e9rant dans plus de 30 secteurs, ne cesse de conqu\u00e9rir du terrain sur le march\u00e9 international. C'est ainsi qu'elle cherche \u00e0 recruter un (e) Digital Brand Content Manager afin de renforcer son \u00e9quipe. Nous proposons \u00e0 ses clients des solutions uniques et innovantes dans le but d'optimiser leurs performances, am\u00e9liorer leur rendement, accro\u00eetre leur visibilit\u00e9 et de rester pionniers sur leur secteur. Notre force est de d\u00e9dier des sp\u00e9cialistes en ing\u00e9nierie travaillant de pair avec des marketeurs et directeurs artistiques pour chaque corps de m\u00e9tier afin d'offrir une approche diff\u00e9rente et unique sur le march\u00e9.\",\nPays : cameroun,\nvilles : Douala, Yaound\u00e9, Bafoussam,\ncontact pour postuler : recrutement@digitalmanagement.fr\n\n<div><strong>Mission :<\/strong><\/div> <div>Vous serez en charge du contenu num\u00e9rique. Vous \u00eates responsable de tout contenu publi\u00e9 sur internet pour le compte d\u2019un client\/marque.<\/div> <div>Votre r\u00f4le se positionne entre le Community Manager et le R\u00e9dacteur Web.<\/div> <div>Vous cr\u00e9ez et diffusez des contenus (vid\u00e9os, articles de blog ou de presse, podcasts et posts sur les r\u00e9seaux sociaux), afin de populariser la marque, informer, convaincre les clients finaux et cr\u00e9er de l\u2019engagement.<\/div> <div>Vous aurez \u00e0 d\u00e9finir les campagnes digitales innovantes, faire de l\u2019Inbound marketing et veiller \u00e0 l\u2019e-r\u00e9putation du client.<\/div> <div>&nbsp;<\/div> <div><strong>Profil recherch\u00e9:<\/strong><\/div> <div>Issu d'une Ecole de Commerce ou d'une Ecole d'Ing\u00e9nieurs.&nbsp;<\/div> <div>Exp\u00e9rience significative en marketing digital<\/div> <div>Excellent niveau r\u00e9dactionnel<\/div> <div>Excellent niveau en Fran\u00e7ais parl\u00e9, lu et \u00e9crit<\/div> <div>Capacit\u00e9 d'analyse<\/div> <div>&nbsp;<\/div> <div><strong>Type d\u2019emploi :<\/strong> Temps plein, \u00e0 distance<\/div><\/code><\/pre>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[22],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Digital Brand Content Manager","emplois_employeur":3046,"emplois_date_publication":"2021-11-17","emplois_heure_publication":"","emplois_date_cloture":"2021-12-15","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement@digitalmanagement.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24733"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24733"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24733"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24733"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24733"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}