{"id":24339,"date":"2021-11-08T20:59:33","date_gmt":"2021-11-08T19:59:33","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24339"},"modified":"2021-11-08T20:59:36","modified_gmt":"2021-11-08T19:59:36","slug":"stagiaire-programme","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/stagiaire-programme\/","title":{"rendered":"Stagiaire Programme"},"content":{"rendered":"\n<p>Stagiaire Programme<br>Identification<\/p>\n\n\n\n<p>Titre du poste : Stagiaire Programme<br>Rapporte \u00e0 : Programme Coordinator<br>Lieu d\u2019affectation : Yaound\u00e9<br>Type de contrat : Contrat de stage non r\u00e9mun\u00e9r\u00e9<br>Dur\u00e9e du contrat : 3 mois renouvelable une fois<br>Disponibilit\u00e9 : Imm\u00e9diate<\/p>\n\n\n\n<p>Missions et Responsabilit\u00e9s<br>I- Suivi des projets<br>1- Gestion des outils de monitoring pour tous les projets en cours :<br>a. Pr\u00e9paration et mise \u00e0 jour lors de la signature et la r\u00e9vision des accords<br>b. V\u00e9rification de la coh\u00e9rence du contenu des rapports mensuels et des outils de monitoring<br>2- Archivage et mise \u00e0 disposition, dans les espaces de stockage en ligne, des versions critiques des documents ressource<br>a. Mise en place d\u2019un dossier partag\u00e9 sur les espaces de stockage en ligne<br>b. Assurer l\u2019organisation et la mise \u00e0 jour permanente des contenus<br>c. Assurer le partage des ressources aux personnes d\u00fbment autoris\u00e9es<br>3- Pr\u00e9paration, harmonisation et finalisation des documents ressource<br>a. Correction du contenu et harmonisation des<br>b. Harmonisation visuelle et graphique des documents et pr\u00e9sentations selon la charte d\u2019INTERSOS<br>c. V\u00e9rification de la coh\u00e9rence du contenu avec les indicateurs contenus dans les outils de monitoring<br>4- S\u2019assurer du respect des \u00e9ch\u00e9ances de rapportage par les points focaux<br>a. Dresser, pour chaque projet et en coordination le chef de l\u2019unit\u00e9 Programmes, le tableau de suivi des \u00e9ch\u00e9ances, en relation avec les indicateurs contractuels, les r\u00e9solutions adopt\u00e9es lors de meetings ou des requ\u00eates sp\u00e9ciales du CdM ou du Si\u00e8ge<br>b. Effectuer des relances r\u00e9guli\u00e8res aux points focaux des projets<br>II- Programme : Mise \u00e0 disposition de la documentation ressource<br>1- Assurer la pr\u00e9paration de pr\u00e9sentations pour des meetings en externe ou en interne 2- Appuyer la pr\u00e9paration de propositions de projet ou de concept notes \u00e0 travers :<br>a. La collecte la structuration et la centralisation de la documentation ou secondaire<br>b. Cr\u00e9ation de fiches de synth\u00e8se de documents annexes ou secondaires : rapports, m\u00e9thodologies et rapports de situation<br>c. La r\u00e9organisation, v\u00e9rification et la d\u00e9sagr\u00e9gation de donn\u00e9es statistiques<\/p>\n\n\n\n<p>d. La v\u00e9rification des sources ou de la conformit\u00e9 des documents aux exigences des bailleurs de fonds.<br>3- Assurer une veille informationnelle aupr\u00e8s des plateformes de coordination : \u00e9valuations, initiatives et appels \u00e0 contribution.<br>NB : le\/la stagiaire devra assurer toutes autres t\u00e2ches qui lui sont seront confi\u00e9es par son superviseur et qui ne sont pas pr\u00e9vues dans le pr\u00e9sent TDR.<\/p>\n\n\n\n<p>Exigences du poste<br>Education \u2022 Master II, \u00e9quivalent ou plus en Sciences sociales, du d\u00e9veloppement et de l\u2019aide humanitaire : Management et d\u00e9veloppement de projets, coop\u00e9ration internationale, droit International humanitaire, action humanitaire, agriculture ou \u00e9conomie rurale et disciplines connexes.<\/p>\n\n\n\n<p>Exp\u00e9rience Jeune dipl\u00f4m\u00e9<br>Une exp\u00e9rience ant\u00e9rieure de stage ou de volontariat dans une organisation Internationale \u00e0 but non lucratif serait un plus.<br>Langage <\/p>\n\n\n\n<p>\u2022 \u00catre Bilingue (Fran\u00e7ais\/anglais) : capable de communiquer et de r\u00e9diger<br>dans l\u2019autre langue.<\/p>\n\n\n\n<p>Connaissances<br>Comp\u00e9tences \/<br>Attitudes <\/p>\n\n\n\n<p>\u2022 \u00catre \u00e2g\u00e9.e de moins de 35 ans<br>\u2022 \u00catre proactif.ve, organis\u00e9.e, avoir le sens du d\u00e9tail<br>\u2022 Forte capacit\u00e9 \u00e0 travailler sous pression et \u00e0 livrer un travail de qualit\u00e9 dans des d\u00e9lais courts<br>\u2022 Avoir une forte capacit\u00e9 de recherche et de documentation<br>\u2022 Avoir une bonne maitrise des logiciels de traitement de texte et des tableurs, mainstream ou alternatifs<br>\u2022 Avoir la capacit\u00e9 \u00e0 travailler dans des environnements multiculturels et qui admettent la diversit\u00e9<br>\u2022 Ne pas \u00eatre engag\u00e9e dans des mouvements d\u2019activisme politique<br>\u2022 Avoir l\u2019esprit ouvert et un bon sens d\u2019humour<\/p>\n\n\n\n<p>Envoyez votre CV (renomm\u00e9 en respectant le format : CV-Nom) et votre lettre de motivation en PDF en suivant et en remplissant le questionnaire du lien ci \u2013 apr\u00e8s :<br>https:\/\/cutt.ly\/iR7YIet<\/p>\n\n\n\n<p>Le d\u00e9lai de d\u00e9p\u00f4t de candidature est fix\u00e9 au Jeudi 11 Novembre 2021 \u00e0 17h.<br>NB : Seules les candidatures pr\u00e9s\u00e9lectionn\u00e9es seront contact\u00e9es pour le Test \u00e9crit<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stagiaire ProgrammeIdentification Titre du poste : Stagiaire ProgrammeRapporte \u00e0 : Programme CoordinatorLieu d\u2019affectation : Yaound\u00e9Type de contrat : Contrat de stage non r\u00e9mun\u00e9r\u00e9Dur\u00e9e du contrat&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[21],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Stagiaire Programme","emplois_employeur":3046,"emplois_date_publication":"2021-11-08","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/cutt.ly\/iR7YIet"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24339"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24339"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24339"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24339"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24339"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}