{"id":24236,"date":"2021-11-05T06:27:45","date_gmt":"2021-11-05T05:27:45","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24236"},"modified":"2021-11-05T15:51:32","modified_gmt":"2021-11-05T14:51:32","slug":"infirmier-sante-au-travail","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/infirmier-sante-au-travail\/","title":{"rendered":"Infirmier Sant\u00e9 au Travail"},"content":{"rendered":"\n<p>Je #recrute en urgence un(e) infirmier(e) sant\u00e9 au travail. Connaissez-vous quelqu\u2019un qui pourrait correspondre au profil d\u00e9crit ci-dessous ?<\/p>\n\n\n\n<p>OFFRE D&rsquo;EMPLOI &#8211; APPEL A CANDIDATURE<\/p>\n\n\n\n<p>Poste \u00e0 pourvoir : Infirmier Sant\u00e9 au Travail<br>Nombre de personnes : 01<br>Type de contrat : contrat \u00e0 dur\u00e9e d\u00e9termin\u00e9e (CDD)<br>Localisation g\u00e9ographique : Yaound\u00e9-Cameroun<\/p>\n\n\n\n<p>MISSIONS PRINCIPALES DU POSTE<\/p>\n\n\n\n<p>Rattach\u00e9 au Service des Ressources Humaines, l&rsquo;infirmier(e) a pour principale mission d&rsquo;assurer la prise en charge m\u00e9dicale rapide de l&rsquo;ouvrier afin qu&rsquo;il puisse retourner rapidement \u00e0 son poste de travail. Ainsi il\/elle sera appel\u00e9(e) \u00e0 :<br>\u00b7 Effectuer des interventions d&rsquo;actes infirmiers dans un but pr\u00e9ventif ou curatif ;<br>\u00b7 faire un bon usage des produits param\u00e9dicaux, m\u00e9dicaux et autres mat\u00e9riels utiles ;<br>\u00b7 Respecter les consignes d&rsquo;hygi\u00e8nes et de s\u00e9curit\u00e9 ;<br>\u00b7 Assurer toutes les responsabilit\u00e9s li\u00e9es \u00e0 son m\u00e9tier et rester flexible pour les sollicitations de la hi\u00e9rarchie.<\/p>\n\n\n\n<p>COMPETENCES REQUISES \/SAVOIRS-FAIRE<\/p>\n\n\n\n<p>\u00b7 Dipl\u00f4me d&rsquo;infirmier ou tout autre dipl\u00f4me \u00e9quivalent ;<br>\u00b7 Bonnes connaissances en gestion des risques ;<br>\u00b7 Bonnes connaissances en gestion de la qualit\u00e9, de l&rsquo;hygi\u00e8ne, de la s\u00e9curit\u00e9 et de l&rsquo;environnement ;<br>\u00b7 Bonnes connaissances en gestion budg\u00e9taire ;<br>\u00b7 Aptitudes \u00e0 travailler en \u00e9quipe ;<br>\u00b7 Capacit\u00e9s communicationnelles et r\u00e9dactionnelles av\u00e9r\u00e9es ;<br>\u00b7 Connaissance en droit du travail ;<br>\u00b7 Aptitudes av\u00e9r\u00e9es en veille technologique ;<br>\u00b7 exp\u00e9rience en mati\u00e8re de collecte des donn\u00e9es ;<br>\u00b7 L&rsquo;exp\u00e9rience en m\u00e9decine du travail serait un atout.<\/p>\n\n\n\n<p>Postulez en envoyant votre CV actualis\u00e9 (versionPDF) maximum 02 pages et au plus tard le 15\/11\/2021 \u00e0 15h00 via l&rsquo;adresse rmpmpilla@hotmail.fr avec pour objet : \u00ab VOTRE NOM_INFIRMIER-SANTE-TRAVAIL_2021 \u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je #recrute en urgence un(e) infirmier(e) sant\u00e9 au travail. Connaissez-vous quelqu\u2019un qui pourrait correspondre au profil d\u00e9crit ci-dessous ? OFFRE D&rsquo;EMPLOI &#8211; APPEL A CANDIDATURE&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[27],"tags":[],"villes":[136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Infirmier Sant\u00e9 au Travail","emplois_employeur":3046,"emplois_date_publication":"2021-11-05","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"rmpmpilla@hotmail.fr "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24236"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24236"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24236"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24236"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24236"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}