{"id":24017,"date":"2021-11-02T04:50:13","date_gmt":"2021-11-02T03:50:13","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=24017"},"modified":"2021-11-02T04:50:17","modified_gmt":"2021-11-02T03:50:17","slug":"directeur-incubateur-panafricain-h-f","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/directeur-incubateur-panafricain-h-f\/","title":{"rendered":"Directeur Incubateur Panafricain (H\/F)"},"content":{"rendered":"\n<p>Directeur incubateur panafricain (H\/F)<br>HSD-Melt group recherche pour l\u2019un de ses clients, un Directeur incubateur panafricain (H\/F) pour accompagner le d\u00e9veloppement des activit\u00e9s de l\u2019un de ses clients, dans la ville de Yaound\u00e9, au Cameroun.<\/p>\n\n\n\n<p><br>Activit\u00e9s du poste :<\/p>\n\n\n\n<p><br>Ambassadeur et porte-parole de l\u2019incubateur, le Directeur sera en charge \u00e0 la fois du d\u00e9veloppement, de la gestion, et de l\u2019organisation strat\u00e9gique et op\u00e9rationnelle de l\u2019incubateur. <br><\/p>\n\n\n\n<p>Ce poste s&rsquo;adresse \u00e0 un candidat de formation sup\u00e9rieure militant de la cause entrepreneuriale. <br><\/p>\n\n\n\n<p>Le candidat devra pouvoir se pr\u00e9valoir d&rsquo;une exp\u00e9rience probante dans la conduite de projet id\u00e9alement acquise dans le domaine de l&rsquo;innovation ainsi que d&rsquo;une bonne culture g\u00e9n\u00e9rale sur le management et la gestion d&rsquo;une jeune soci\u00e9t\u00e9, particuli\u00e8rement en Afrique.<br>Votre capacit\u00e9 \u00e0 f\u00e9d\u00e9rer autour de valeurs fortes et \u00e0 insuffler une dynamique mobilisatrice constitueront des atouts majeurs pour r\u00e9ussir dans ce poste.<\/p>\n\n\n\n<p><br>Vos principales missions :<\/p>\n\n\n\n<p><br>\uf0b7 V\u00e9hiculer une image positive de l&rsquo;entreprise \u00e0 l&rsquo;externe (m\u00e9dias, institutions, milieu entrepreneurial etc.)<br>\uf0b7 Assurer le pilotage strat\u00e9gique de l\u2019incubateur<br>\uf0b7 Assurer la gestion administrative, financi\u00e8re et commerciale<br>\uf0b7 Encadrer les ressources humaines<br>\uf0b7 Superviser l\u2019ensemble des activit\u00e9s de l\u2019incubateur<br>\uf0b7 D\u00e9tecter, s\u00e9lectionner et accompagner les porteurs de projet de cr\u00e9ation d\u2019entreprises<br>Innovantes<br>Profil requis :<br>\uf0b7 Bilingue fran\u00e7ais et anglais<br>\uf0b7 Mast\u00e8re ou doctorat avec id\u00e9alement formation en gestion d\u2019entreprise<br>\uf0b7 Minimum 10 ans d\u2019exp\u00e9riences en entreprenariat<br>\uf0b7 Maitrise parfaite de ms office: PowerPoint, Word and Excel<br>Comp\u00e9tences fonctionnelles<br>\uf0b7 Leadership, capacit\u00e9 d\u2019adaptation, connaissances en gestion, comptabilit\u00e9, management et Marketing.<br>\uf0b7 Planification et organisation, gestion de projet, management de larges \u00e9quipes<br>\uf0b7 \u00c9tablissement et maintien de relations de collaboration, r\u00e9solution de probl\u00e8mes,<br>multit\u00e2ches et Gestion de plusieurs priorit\u00e9s concurrentes<\/p>\n\n\n\n<p><br>Qualit\u00e9s comportementales:<\/p>\n\n\n\n<p><br>\uf0b7 Vision \u00e0 long terme, enthousiasme, pers\u00e9v\u00e9rance, optimisme, prise de d\u00e9cision efficace, comp\u00e9tences en communication, travail d\u2019\u00e9quipe, d\u00e9veloppement personnel et entrepreneuriat.<\/p>\n\n\n\n<p><br>Les candidats int\u00e9ress\u00e9s sont pri\u00e9s de faire parvenir leur candidature \u00e0 l\u2019adresse cameroon.office@hsd-melt.com et https:\/\/mhd.hsd-melt.com\/ au<br>plus tard le 31\/12\/2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Directeur incubateur panafricain (H\/F)HSD-Melt group recherche pour l\u2019un de ses clients, un Directeur incubateur panafricain (H\/F) pour accompagner le d\u00e9veloppement des activit\u00e9s de l\u2019un de&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[113],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"Directeur Incubateur Panafricain (H\/F)","emplois_employeur":4816,"emplois_date_publication":"2021-11-02","emplois_heure_publication":"","emplois_date_cloture":"2021-12-31","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"cameroon.office@hsd-melt.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24017"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=24017"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/24017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/13905"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=24017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=24017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=24017"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=24017"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=24017"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=24017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}