{"id":23768,"date":"2021-10-26T10:20:36","date_gmt":"2021-10-26T08:20:36","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=23768"},"modified":"2021-10-26T16:20:22","modified_gmt":"2021-10-26T14:20:22","slug":"un-charge-de-relation-clientele-corporate","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/un-charge-de-relation-clientele-corporate\/","title":{"rendered":"Un Charg\u00e9 de Relation Client\u00e8le Corporate"},"content":{"rendered":"\n<p>NOUS RECRUTONS <\/p>\n\n\n\n<p><strong>Un Charg\u00e9 de Relation Client\u00e8le Corporate <\/strong><\/p>\n\n\n\n<p>Missions : <\/p>\n\n\n\n<p>Assurer et superviser la r\u00e9alisation du budget de production <\/p>\n\n\n\n<p>Repr\u00e9senter la banque aupr\u00e8s des clients sensibles et importants <\/p>\n\n\n\n<p>Mener Gestion administrative des dossiers des clients et animer les actions commerciales <\/p>\n\n\n\n<p>Etude des demandes de financement <\/p>\n\n\n\n<p>Reporting des activit\u00e9s Management de l&rsquo;\u00e9quipe <\/p>\n\n\n\n<p>Exp\u00e9rience souhait\u00e9e: 5 ans minimum d&rsquo;exp\u00e9rience \u00e0 un poste de Charg\u00e9 de relation client\u00e8le PME\/PMI, Entreprises \/ Institutionnels ou BFI; ou\u00e0 un poste d&rsquo;Analyste Cr\u00e9dit S\u00e9nior : Minimum 1 an d&rsquo;exp\u00e9rience \u00e0 un poste d&rsquo;encadrement <\/p>\n\n\n\n<p>Niveau d&rsquo;\u00e9tude: Bac +4\/5 en Gestion\/ Banque\/ Finance\/ Action commerciale ou Analyse Financi\u00e8re Formation bancaire: ITB, BBS ou \u00e9quivalent. <\/p>\n\n\n\n<p>Qualit\u00e9s recherch\u00e9es: <\/p>\n\n\n\n<p>Vous faites preuve de rigueur, d&rsquo;adaptation, de grande capacit\u00e9 r\u00e9dactionnelle, de sang-froid, d&rsquo;\u00e9coute, d&rsquo;int\u00e9grit\u00e9 et \u00eates force de proposition. <\/p>\n\n\n\n<p>Vous \u00eates dot\u00e9 d&rsquo;un bon sens de l&rsquo;organisation. <\/p>\n\n\n\n<p>Vous avez de grandes qualit\u00e9s relationnelles et humaines, de r\u00e9elles capa- cit\u00e9s d&rsquo;analyse et vous \u00e9tes r\u00e9actif \u00e0 mettre en place des actions. <\/p>\n\n\n\n<p>Vous avez le sens de la n\u00e9gociation ainsi que l&rsquo;esprit d&rsquo;initiative, d&rsquo;analyse et de syn- th\u00e8se. <\/p>\n\n\n\n<p>Vous \u00f6tos orient\u00e9 performance. <\/p>\n\n\n\n<p>La maitrise de l&rsquo;anglais professionnel et de l&rsquo;outil informatique sont indis- pensables. <\/p>\n\n\n\n<p>La bonne maitrise du logiciel Amplitude est indispensable. Les candidats dont les profils correspondent aux exigences requises, sont pri\u00e9s de d\u00e9poser leurs candidatures (cv et lettre de motivation) \u00e0 la Direction du Capital Humain et de la Transformation ou par courriel \u00e0 l&rsquo;adresse recrutement.bgfibankcameroun@bgfi.com, en prenant le soin d&rsquo;indiquer sur leurs demandes respectives la r\u00e9f\u00e9rence: R\u00e9f\/N\u00b001 octobre 2021 BGFIBank Cameroun_ (pr\u00e9ciser le poste sollicit\u00e9). <\/p>\n\n\n\n<p>La maitrise de l&rsquo;anglais, de l&rsquo;outil informatique et du logiciel Amplitude sont indispensables. Date limite de transmission des candidatures : 05\/11\/2021 BGFIBank www.groupebgfibank.com Votre partenaire pour l&rsquo;avenir O.Planers 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NOUS RECRUTONS Un Charg\u00e9 de Relation Client\u00e8le Corporate Missions : Assurer et superviser la r\u00e9alisation du budget de production Repr\u00e9senter la banque aupr\u00e8s des clients&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[],"tags":[],"villes":[],"contrats":[],"diplomes":[],"louma_meta":{"emploi_title":"Un Charg\u00e9 de Relation Client\u00e8le Corporate ","emplois_employeur":11226,"emplois_date_publication":"2021-10-26","emplois_heure_publication":"","emplois_date_cloture":"2021-11-05","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutement.bgfibankcameroun@bgfi.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23768"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=23768"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/11227"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=23768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=23768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=23768"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=23768"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=23768"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=23768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}