{"id":23693,"date":"2021-10-25T02:32:36","date_gmt":"2021-10-25T00:32:36","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=23693"},"modified":"2021-10-25T02:32:38","modified_gmt":"2021-10-25T00:32:38","slug":"kpmg-recrutement-manager-senior-manager-audit-bureau-du-cameroun-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/kpmg-recrutement-manager-senior-manager-audit-bureau-du-cameroun-2\/","title":{"rendered":"KPMG Recrutement &#8211; Manager\/ Senior Manager Audit Bureau du Cameroun"},"content":{"rendered":"\n<p>KPMG Recrutement &#8211; Manager\/ Senior Manager Audit Bureau du Cameroun le monde \u00e9conomique et financier \u00e9volue, le m\u00e9tier d&rsquo;Auditeur \u00e9galement. <\/p>\n\n\n\n<p><br>Nos clients nous sollicitent de plus en plus pour des interventions \u00e0 forte valeur ajout\u00e9e, pour lesquelles, plus que jamais, nous agissons en tant que partenaire privil\u00e9gi\u00e9. <\/p>\n\n\n\n<p>Rejoindre KPMG, c&rsquo;est d\u00e9velopper unie expertise reconnue, gagner rapidement en responsabilit\u00e9s, booster votre KPMG carri\u00e8re et vous r\u00e9aliser dans un environnement propice. <\/p>\n\n\n\n<p>Nous recherchons un(e) : Manager \/Senior Manager Audit Rattach\u00e9le) \u00e0 la Business Unit Audit GRANDS COMPTES de KPMG Afrique Centrale, bureau du Cameroun, vous r\u00e9alisez des missions \u00e0 forte valeur ajout\u00e9e en \u00e9tablissant une relation de confiance et en assurant un soutien continu \u00e0 nos dients. <\/p>\n\n\n\n<p>Vous interviendrez principalement sur des missions d&rsquo;audit aupr\u00e8s d&rsquo;une client\u00e8le diversifi\u00e9e, dans un environnement national mais aussi international. <\/p>\n\n\n\n<p>Vous serez responsable des missions suivantes : <\/p>\n\n\n\n<p>\u2022 Audit l\u00e9gal et contractuel sur un portefeuille client diversifi\u00e9;<\/p>\n\n\n\n<p> \u2022 Encadrement et coordination des \u00e9quipes d&rsquo;audit (gestion planning, encourager, donner des consignes claires, valoriser les succ\u00e8s de l&rsquo;\u00e9quipe et l&rsquo;inciter \u00e0 une constante am\u00e9lioration); <\/p>\n\n\n\n<p>\u2022 Etre garant du niveau de valeur ajout\u00e9e apport\u00e9e par l&rsquo;\u00e9quipe aux clients;<\/p>\n\n\n\n<p> \u2022 Actions de d\u00e9veloppement commercial. <\/p>\n\n\n\n<p>Profil: <\/p>\n\n\n\n<p>\u2022 Vous \u00eates un expert comptable dipl\u00f4m\u00e9 (e) ou expert comptable stagiaire avec un niveau BAC +5 en finance\/comptabilit\u00e9. <\/p>\n\n\n\n<p>\u2022 Vous disposez d&rsquo;une exp\u00e9rience d&rsquo;au moins 8 ans au sein d&rsquo;un cabinet d&rsquo;audit. <\/p>\n\n\n\n<p>Vous disposez d&rsquo;une exp\u00e9rience en audit des \u00e9tablissements de cr\u00e9dits et institutions financi\u00e8res. <\/p>\n\n\n\n<p>\u2022 Vous avez une exp\u00e9rience r\u00e9ussie du management d&rsquo;\u00e9quipe.<\/p>\n\n\n\n<p> \u2022 Vous vous exprimez couramment en fran\u00e7ais et en anglais (une forte comp\u00e9tence en communication (\u00e9crite et orale) en anglais est un plus) <\/p>\n\n\n\n<p>\u2022 Vous maitrisez les normes comptables internationales (IFRS); Vous avez une parfaite connaissance des normes locales (COBAC, SYSCHOHADA et PCEC) et international de tous les secteurs <\/p>\n\n\n\n<p>\u2022 Enfin, vous \u00eates dynamique, entreprenantle), dot\u00e9le) d&rsquo;un fort esprit d&rsquo;analyse, et de capacit\u00e9s de d\u00e9veloppement commercial et, vous souhaitez \u00e9largir vos comp\u00e9tences dans un environnement stimulant \u00e0 la pointe des nouvelles technologies en mati\u00e8re d&rsquo;audit. <\/p>\n\n\n\n<p>Dossier de candidature \u00e0 envoyer par email: CV d\u00e9taill\u00e9 \u00e0 jour des r\u00e9f\u00e9rences du candidat et tout autre document jug\u00e9 n\u00e9cessaire;<\/p>\n\n\n\n<p> Bien marquer en objet du mail la r\u00e9f\u00e9rence inscrite ci-dessous. Veuillez postuler avec le 30 octobre 2021.<\/p>\n\n\n\n<p> Seuls les candidats retenus pour les prochaines \u00e9tapes seront contact\u00e9s. . <br><\/p>\n\n\n\n<p>Email : recrutementaudit@kpmg.cm <\/p>\n\n\n\n<p>R\u00e9f\u00e9rence : KPMG_AC_MA\/SM_202110 www : https:\/\/home.kpmg\/cm\/fr\/home.html kpmg.com\/socialmedia in f Oa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>KPMG Recrutement &#8211; Manager\/ Senior Manager Audit Bureau du Cameroun le monde \u00e9conomique et financier \u00e9volue, le m\u00e9tier d&rsquo;Auditeur \u00e9galement. Nos clients nous sollicitent de&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[1766],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"KPMG Recrutement - Manager\/ Senior Manager Audit Bureau du Cameroun","emplois_employeur":6401,"emplois_date_publication":"2021-10-25","emplois_heure_publication":"","emplois_date_cloture":"2021-11-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutementaudit@kpmg.cm"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23693"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=23693"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/6402"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=23693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=23693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=23693"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=23693"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=23693"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=23693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}