{"id":23689,"date":"2021-10-25T02:51:56","date_gmt":"2021-10-25T00:51:56","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=23689"},"modified":"2021-10-25T16:27:45","modified_gmt":"2021-10-25T14:27:45","slug":"stagiaires-pre-emploi-en-transport-et-logistique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/stagiaires-pre-emploi-en-transport-et-logistique\/","title":{"rendered":"Stagiaires pr\u00e9-emploi en Transport et Logistique"},"content":{"rendered":"\n<p>PROFIL 3: Stagiaires pr\u00e9-emploi en Transport et Logistique pour les op\u00e9rations de terrain Dipl\u00f4me : BTS en Logistique &amp; Transport ou Douane &amp; Transit <\/p>\n\n\n\n<p>Exp\u00e9rience : Aucune <\/p>\n\n\n\n<p>Sexe : Masculin <\/p>\n\n\n\n<p>\u2022 Etre brave, vaillant et motiv\u00e9 <\/p>\n\n\n\n<p>\u2022 Etre rigoureux et m\u00e9ticuleux <\/p>\n\n\n\n<p>\u2022 Etre un minimum bilingue <\/p>\n\n\n\n<p>\u2022 Maitriser l&rsquo;outil informatique <\/p>\n\n\n\n<p>\u2022 Avoir le sens des valeurs et l&rsquo;esprit d&rsquo;\u00e9quipe <\/p>\n\n\n\n<p>\u00catre apte \u00e0 travailler sous pression<\/p>\n\n\n\n<p>DELAIS DE CLOTURE DE CANDIDATURE : 30 Octobre 2021 DOCUMENTS A FOURNIR : CV actualis\u00e9 avec photo <\/p>\n\n\n\n<p>ADRESSE MAIL : recruitment@green-lo.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PROFIL 3: Stagiaires pr\u00e9-emploi en Transport et Logistique pour les op\u00e9rations de terrain Dipl\u00f4me : BTS en Logistique &amp; Transport ou Douane &amp; Transit Exp\u00e9rience&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[113,369],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212],"louma_meta":{"emploi_title":"Stagiaires pr\u00e9-emploi en Transport et Logistique","emplois_employeur":16340,"emplois_date_publication":"2021-10-25","emplois_heure_publication":"","emplois_date_cloture":"2021-10-31","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"recruitment@green-lo.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23689"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=23689"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23689\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/16341"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=23689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=23689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=23689"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=23689"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=23689"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=23689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}