{"id":23617,"date":"2021-10-22T09:14:18","date_gmt":"2021-10-22T07:14:18","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=23617"},"modified":"2021-10-22T09:14:21","modified_gmt":"2021-10-22T07:14:21","slug":"ouvrier-de-chantier-sinohydro","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/ouvrier-de-chantier-sinohydro\/","title":{"rendered":"Ouvrier de chantier-Sinohydro"},"content":{"rendered":"<p style=\"text-align: left\">Titre du poste : ouvrier de chantier,<br \/>\ndate d&rsquo;expiration : 2021-11-21,<br \/>\nentreprise : sinohydro,<br \/>\nPays : cameroun,<br \/>\nvilles : yaounde,<br \/>\ncontact pour postuler : recrutementsinohydrocameroun@yahoo.com<br \/>\n####### description du poste ######<\/p>\n<div class=\"msg-body P_wpofO mq_AS\" data-test-id=\"message-view-body-content\">\n<div class=\"jb_0 X_6MGW N_6Fd5\">\n<div>\n<div dir=\"ltr\">L\u2019entreprise chinoise SINOHYDRO informe le public camerounais qu\u2019elle\u00a0 lance un recrutement massif d\u2019ouvrier de chantier (manutentionnaire) pour l&rsquo;ach\u00e8vement des travaux de l&rsquo;auto route\u00a0 Yaound\u00e9-nsimalen<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Comp\u00e9tences de base :<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">S\u00e9curiser le chantier et ses abords (signalisation, balisage, d\u00e9viations, &#8230;) et \u00e9tablir les modalit\u00e9s de rotation des engins selon les contraintes du terrain Am\u00e9nagement urbain Positionner des rep\u00e8res d&rsquo;ouvrages sur un chantier Techniques de jointement R\u00e9aliser des travaux de terrassement, de fondations Techniques de coulage du b\u00e9ton Implanter des pav\u00e9s ou des dalles Techniques d&rsquo;application d&rsquo;enrob\u00e9s Poser des \u00e9l\u00e9ments de voirie Caract\u00e9ristiques des enrob\u00e9s Remblayer l&rsquo;excavation et compacter les tranch\u00e9es R\u00e8gles et consignes de s\u00e9curit\u00e9 Appliquer les couches d&rsquo;assises de chauss\u00e9e Guidage d&rsquo;engins de chantier Compacter les couches d&rsquo;assises de chauss\u00e9e Lecture de plan, de sch\u00e9ma R\u00e9pandre les granulats, les gravillons ou les d\u00e9blayer<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Savoir travailler en \u00e9quipe,<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Etre dynamique,<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Etre honn\u00eate et humble.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Etre cr\u00e9atif.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Avoir au minimum un BEPC pas plus ni moins \u00eatre en bonne condition physique<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Sexe masculin uniquement<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">lieu de travail : yaounde<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Les int\u00e9ress\u00e9s sont pri\u00e9s de<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">d\u00e9poser leur CV \u00e0 l&rsquo;adresse: <a href=\"mailto:recrutementsinohydrocameroun@yahoo.com\">recrutementsinohydrocameroun@yahoo.com<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"I_2iedTo k_w H_7yHc p_R o_h\" data-test-id=\"attachment-container\">\n<div class=\"D_F ab_C gl_C H_6D6F\"><img decoding=\"async\" class=\"W_6D6F\" src=\"https:\/\/apis.mail.yahoo.com\/ws\/v3\/mailboxes\/@.id==VjN-_Il2T_4M52Va-AhdoOdy4CPfaBOjDU7-OzZ95aT_njPn4Blz5RQzaf3lAzcZpeibi4pka2NA-i9hx_OkcKJDrOEEufPZtlC5-Bzn95DAhf4\/messages\/@.id==ABASNvdK6IxzYW-5RwYuCNrUCyA\/content\/parts\/@.id==2\/thumbnail?appid=YMailNorrin&amp;size=400w&amp;w=400&amp;h=400\" data-test-id=\"attachment-thumbnail\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Titre du poste : ouvrier de chantier, date d&rsquo;expiration : 2021-11-21, entreprise : sinohydro, Pays : cameroun, villes : yaounde, contact pour postuler : recrutementsinohydrocameroun@yahoo.com&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[79],"tags":[],"villes":[136],"contrats":[151],"diplomes":[156,164],"louma_meta":{"emploi_title":"Ouvrier de chantier-Sinohydro","emplois_employeur":23618,"emplois_date_publication":"2021-10-22","emplois_heure_publication":"","emplois_date_cloture":"2021-11-21","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"recrutementsinohydrocameroun@yahoo.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23617"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=23617"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/23620"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=23617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=23617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=23617"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=23617"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=23617"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=23617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}