{"id":23547,"date":"2021-10-21T06:56:52","date_gmt":"2021-10-21T04:56:52","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=23547"},"modified":"2021-10-21T06:56:54","modified_gmt":"2021-10-21T04:56:54","slug":"offre-des-bourses-de-formations-humanitaires-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/offre-des-bourses-de-formations-humanitaires-2\/","title":{"rendered":"OFFRE DES BOURSES DE FORMATIONS HUMANITAIRES"},"content":{"rendered":"<p>Titre du poste : OFFRE DES BOURSES DE FORMATIONS HUMANITAIRES,<br \/>\ndate d&rsquo;expiration : 2021-12-20,<br \/>\nNouvelle entreprise : Acad\u00e9mie de l&rsquo;Excellence,<br \/>\nPays : cameroun,<br \/>\nvilles : Douala,<br \/>\ncontact pour postuler : contact.acadexe@yahoo.com<br \/>\n####### description du poste ######<\/p>\n<div>Offre sp\u00e9ciale de 100 bourses d\u2019\u00e9tudes en janvier 2022<\/div>\n<div>&nbsp;<\/div>\n<div>L\u2019Acad\u00e9mie de l\u2019Excellence vous remercie d\u2019avoir choisi de cliquer sur notre offre de de bourse de formation. Savoir choisir c\u2019est d\u00e9j\u00e0 r\u00e9ussir et nous vous souhaitons la bienvenue \u00e0 l\u2019Acad\u00e9mie de l\u2019Excellence. Nous sommes situ\u00e9s \u00e0 Douala, Rond-Point Dakar, Douala-Cameroun.<\/div>\n<div>&nbsp;<\/div>\n<div>Cette bourse a pour objectif de permettre aux couches vuln\u00e9rables et personnes d\u00e9favoris\u00e9es en Afrique de b\u00e9n\u00e9ficier d\u2019un soutien financier de l\u2019ordre de 125.000FCFA en r\u00e9duction du co\u00fbt de la formation. Le cout global de la formation d\u2019une dur\u00e9e de 10 mois est de 495 KFCFA\/ 754.62 Euros\/ 983 US Dollars. Cette bourse est ouverte \u00e0 tous ceux qui s\u2019inscriront avant le 20 D\u00e9cembre 2021.&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Si vous \u00eates retenus pour la bourse, vous ne payerez que 370.000FCFA au lieu de 495.000FCFA. R\u00e9servez vitre votre place et inscrivez-vous avant la date de la cl\u00f4ture de la bourse, le 20 D\u00e9cembre 2021. La premi\u00e8re tranche \u00e0 payer pour r\u00e9server sa place pour cette bourse est de 125.000FCFA.Les options de paiement sont \u00e0 la derni\u00e8re page de nos catalogues de formation ci-joints.<\/div>\n<div>&nbsp;<\/div>\n<div>Faites votre choix de sp\u00e9cialit\u00e9 tout de suite et envoyez-nous votre dossier de candidature comprenant votre CV, lettre de motivation, dernier dipl\u00f4m\u00e9 exig\u00e9 pour la formation et vos attestations d\u2019exp\u00e9rience si vous travaillez d\u00e9j\u00e0. Vos dossiers complets doivent \u00eatre envoy\u00e9s par mail exclusivement et \u00e0 cette adresse: Email: contact.acadexe@yahoo.com. Tel\/WhatsApp : +237 690 82 74 74.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>OFFRE DES BOURSES DE FORMATIONS HUMANITAIRES<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[35],"tags":[],"villes":[135],"contrats":[3588],"diplomes":[162,212,159],"louma_meta":{"emploi_title":"OFFRE DES BOURSES DE FORMATIONS HUMANITAIRES","emplois_employeur":23503,"emplois_date_publication":"2021-10-21","emplois_heure_publication":"","emplois_date_cloture":"2021-11-21","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"contact.acadexe@yahoo.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23547"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=23547"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/23547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/23504"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=23547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=23547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=23547"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=23547"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=23547"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=23547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}