{"id":22629,"date":"2021-09-30T14:23:26","date_gmt":"2021-09-30T12:23:26","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22629"},"modified":"2021-09-30T14:23:31","modified_gmt":"2021-09-30T12:23:31","slug":"livreurs-a-velo-h-f-pour-la-restauration-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/livreurs-a-velo-h-f-pour-la-restauration-2\/","title":{"rendered":"LIVREURS A VELO (H\/F) POUR LA RESTAURATION"},"content":{"rendered":"\n<p><strong>Description du poste&nbsp;:<\/strong><\/p>\n\n\n\n<p><strong>CATERING CENTER (DESANNE SAS)<\/strong>, est une Entreprise sp\u00e9cialis\u00e9e dans le domaine de restauration, fort de plusieurs ann\u00e9es d\u2019exp\u00e9rience elle produit et vend des plats de la gastronomie nationale et internationale \u00e0 ses diff\u00e9rents clients via la plateforme asktatchop.fr dont elle est partenaire.<\/p>\n\n\n\n<p><strong>Objectifs&nbsp;:<\/strong><\/p>\n\n\n\n<p>Vous int\u00e9grez une \u00e9quipe de taille humaine dans le domaine de la restauration. Votre objectif sera de r\u00e9cup\u00e9rer les commandes des clients et aller livrer dans les d\u00e9lais avec un v\u00e9lo.<\/p>\n\n\n\n<p><strong>Missions Principales&nbsp;:<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;R\u00e9cup\u00e9rer les commandes et les mettre dans le sac de livraison pour les acheminer aux clients&nbsp;&nbsp;<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Etre rapide pour respecter les d\u00e9lais de livraison et le temps d\u2019attente des clients<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Faire attention aux diff\u00e9rents colis et plats transport\u00e9s afin qu\u2019ils soient livr\u00e9s intacts aux clients<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Rechercher les clients et prendre leurs commandes depuis l\u2019application Asktatchop via le t\u00e9l\u00e9phone mobile,<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Aller vers les clients et les d\u00e9marcher en proposant les diff\u00e9rents plats au menu<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Faire un rapport et d\u00e9comptes de ses livraisons au responsable.<\/p>\n\n\n\n<p><strong>Conditions pour nous rejoindre :<\/strong><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Niveau scolaire minimum CEP<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Savoir p\u00e9daler correctement un v\u00e9lo avec un sac de livraison \u00e0 dos<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Conna\u00eetre la ville<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00catre majeur minimum 21 ans<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Etre poli, jovial, courtois et de tr\u00e8s bonne moralit\u00e9<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Etre en bonne sant\u00e9 et disponible<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Savoir bien communiquer et s\u2019exprimer<\/p>\n\n\n\n<p>\u00b7&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Etre toujours propre, pr\u00e9sentable et savoir entretenir sa tenue de travail<\/p>\n\n\n\n<p>Vous remplissez ces crit\u00e8res et \u00eates int\u00e9ress\u00e9s ? Alors envoyez-nous votre candidature \u00e0 l&rsquo;adresse suivante :&nbsp;<a href=\"mailto:recrutement@desanne.fr\"><strong>recrutement@desanne.fr<\/strong><\/a><\/p>\n\n\n\n<p>Votre CV (sur une seule page &#8211; obligatoire) et une lettre de motivation, doivent avoir en objet du mail,&nbsp;<strong>le nom du poste pour lequel vous candidatez<\/strong>.<\/p>\n\n\n\n<p><strong>Contact&nbsp;: 690 26 20 28&nbsp;\/ 694 48 32 90<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DESANNE SAS recrute pour ses services des LIVREURS A VELO (H\/F) POUR LA RESTAURATION. Postulez via  recrutement@desanne.fr<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[369],"tags":[3597,4,3874],"villes":[135],"contrats":[148],"diplomes":[158,3083],"louma_meta":{"emploi_title":"LIVREURS A VELO (H\/F) POUR LA RESTAURATION","emplois_employeur":10786,"emplois_date_publication":"2021-09-30","emplois_heure_publication":"13:18","emplois_date_cloture":"2021-10-06","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":" recrutement@desanne.fr"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22629"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22629"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/10787"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22629"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22629"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22629"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}