{"id":22504,"date":"2021-09-28T01:44:43","date_gmt":"2021-09-27T23:44:43","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22504"},"modified":"2021-09-28T10:39:27","modified_gmt":"2021-09-28T08:39:27","slug":"assistante-personnelle","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/assistante-personnelle\/","title":{"rendered":"ASSISTANTE PERSONNELLE"},"content":{"rendered":"\n<p>ASSISTANTE PERSONNELLE <\/p>\n\n\n\n<p>Courses personnelles Gestion de l&rsquo;agenda Gestion des stocks Pr\u00e9paration et exp\u00e9dition des commandes Suivi des prestataires et fournisseurs <\/p>\n\n\n\n<p>\u2022 Gestion des bases de donn\u00e9es Achats et ravitaillement Support organisation \u00e9v\u00e9nement Suivi du personnel et dossiers administratifs V\u00e9rification des comptes et versement 6Jours\/7 <\/p>\n\n\n\n<p>\u2022 Yaound\u00e9 Profil :<\/p>\n\n\n\n<p> &#8211; Maitrise du Pack Office <\/p>\n\n\n\n<p>&#8211; Disponible et rigoureuse<\/p>\n\n\n\n<p> &#8211; Sens pouss\u00e9 de l&rsquo;organisation<\/p>\n\n\n\n<p> &#8211; Bonne ma\u00eetrise de langue fran\u00e7aise R\u00e9mun\u00e9ration selon le profil.<\/p>\n\n\n\n<p> CV via WhatsApp: 694909988 ou e-mail stellaonanaoyono@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASSISTANTE PERSONNELLE Courses personnelles Gestion de l&rsquo;agenda Gestion des stocks Pr\u00e9paration et exp\u00e9dition des commandes Suivi des prestataires et fournisseurs \u2022 Gestion des bases de&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[],"tags":[],"villes":[],"contrats":[],"diplomes":[],"louma_meta":{"emploi_title":"ASSISTANTE PERSONNELLE","emplois_employeur":3046,"emplois_date_publication":"2021-09-28","emplois_heure_publication":"","emplois_date_cloture":"2021-10-02","emplois_heure_cloture":"","emplois_experience_min":"","emplois_experience_max":"","emploi_email":"stellaonanaoyono@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22504"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22504"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22504"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22504"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22504"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}