{"id":22449,"date":"2021-09-27T12:21:12","date_gmt":"2021-09-27T10:21:12","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22449"},"modified":"2021-09-27T12:21:25","modified_gmt":"2021-09-27T10:21:25","slug":"responsable-des-operations-it","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-des-operations-it\/","title":{"rendered":"RESPONSABLE DES OPERATIONS IT"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p>Une entreprise d\u2019int\u00e9gration des solutions informatiques et t\u00e9l\u00e9communication bas\u00e9e \u00e0 Douala recherche pour les besoins de ses activit\u00e9s un Ing\u00e9nieur R\u00e9seau et syst\u00e8me informatique exp\u00e9riment\u00e9 dans la gestion des infrastructures IT et des Datacenters en particulier.\u00a0<\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Impl\u00e9menter &amp; Administrer les syst\u00e8mes, les \u00e9quipements, les outils et les bases de donn\u00e9es ;<\/li><li>Concevoir, g\u00e9rer et utiliser les outils, syst\u00e8mes, applications et bases de donn\u00e9es adapt\u00e9s \u00e0 la gestion informatique et du r\u00e9seau ;<\/li><li>Assurer la maintenance \u00e9volutive et curative des mat\u00e9riels informatiques professionnels, logiciels et syst\u00e8mes d\u2019exploitations;<\/li><li>Concevoir et mettre en \u0153uvre les solutions techniques informatiques ;<\/li><li>Prendre en charge les projets d&rsquo;infrastructure ;<\/li><li>Assurer la s\u00e9curit\u00e9 et l&rsquo;optimisation des syst\u00e8mes informatiques des clients<\/li><li>S\u2019assurer que l&rsquo;ensemble du parc interne et des clients est \u00e0 jour et en ad\u00e9quation avec les r\u00e8gles de s\u00e9curit\u00e9 informatique de l&rsquo;entreprise ;<\/li><li>Participer \u00e0 la proposition, \u00e0 la n\u00e9gociation et \u00e0 la r\u00e9daction des offres de contrat de maintenance<\/li><li>Assister les commerciaux pour le montage des r\u00e9ponses techniques et financi\u00e8res aux appels d\u2019offres.<\/li><li>Vente de services et r\u00e9pondre aux consultations relatives<\/li><li>Participer activement \u00e0 la r\u00e9daction et la mise \u00e0 jour des documents d\u2019architecture, des documents de support et de maintenance ;<\/li><li>Participer \u00e0 l\u2019\u00e9laboration des termes de r\u00e9f\u00e9rences et des cahiers de charge relatifs aux mat\u00e9riels et prestations intellectuelles dans le domaine de l&rsquo;informatique;<\/li><li>Former et assister les utilisateurs;<\/li><li>Participer \u00e0 la r\u00e9ception technique des mat\u00e9riels, logiciels et prestations informatiques \u00e9manant des fournisseurs externes.<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Etre titulaire d&rsquo;un dipl\u00f4me Bac+5 ou certification \u00e9quivalente en information ou t\u00e9l\u00e9communication<\/li><li>Jouir d&rsquo;une exp\u00e9rience de 5 ans ou plus dans l&rsquo;administration syst\u00e8me et r\u00e9seau;<\/li><li>Avoir une ou plusieurs certifications CISCO, MICROSOFT, ITIL, Agile, PMP, PRINC2 ou autres&nbsp;est un atout pour ce poste<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences techniques<\/strong><\/p>\n\n\n\n<ul><li>Ma\u00eetrise voire expertise des logiciels de l\u2019infrastructure technique notamment des syst\u00e8mes d\u2019exploitation et de Virtualisation (VMware, Citrix Zen server, LINUX, MVS, Windows serveur\u2026), et des interpr\u00e9tateurs de commandes (Shell) pour diagnostiquer et r\u00e9parer les dysfonctionnements<\/li><li>Savoir-faire et exp\u00e9rience dans l\u2019administration des Datacenter<\/li><li>Savoir-faire et exp\u00e9rience dans les technologies Cloud computing&nbsp;&nbsp;&nbsp;<\/li><li>Savoir-faire et exp\u00e9rience dans l\u2019utilisation des bonnes pratiques de management des services informatiques et notamment ITIL, Agile, PMP, PRINCE2 ou&nbsp;\u2026.<\/li><li>Utilisation des Protocoles r\u00e9seaux (TCP\/IP, UDP\/IP), protocoles applicatifs (HTTP, FTP, SMTP, POP, IMAP&#8230;)<\/li><li>Maitrise des environnements&nbsp;r\u00e9seau et s\u00e9curit\u00e9&nbsp;et de l\u2019Active Directory<\/li><li>Maitrise des environnements Virtualis\u00e9s :&nbsp;VMware&nbsp;et&nbsp;Citrix XEN<\/li><li>Bonne connaissance de l\u2019architecture et des fonctionnalit\u00e9s du SI de l\u2019entreprise<\/li><li>Connaissance des principaux constructeurs et \u00e9diteurs prestataires du march\u00e9 et notamment de l\u2019offre hardware du march\u00e9<\/li><li>Notion sur les bases de donn\u00e9es (Oracle, SQLServer, Postgresql, Mysq \u2026) et des serveurs de messagerie<\/li><li>Bonne connaissance des syst\u00e8mes: Linux,&nbsp;VMware, Windows Server 2012 &amp; 2016, Windows 8 et 10<\/li><li>Connaissances en langages de d\u00e9veloppement (Java, PHP, Python, etc.);<\/li><li>Connaissance des normes et proc\u00e9dures de s\u00e9curit\u00e9 et des outils associ\u00e9s<\/li><li>Bonne connaissance des clients internes de la DSI&nbsp;: les principaux m\u00e9tiers de l\u2019entreprise<\/li><li>Bonne connaissance &nbsp;de l\u2019anglais technique<\/li><\/ul>\n\n\n\n<p><strong>Qualit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Etre flexible et travailleur;<\/li><li>Etre organis\u00e9 et apte au travail sous pression pour une organisation exigeante;<\/li><li>Avoir de bonnes capacit\u00e9s relationnelles et une capacit\u00e9 d&rsquo;adaptation;<\/li><li>La discr\u00e9tion et le sens du secret professionnel sont de rigueur.<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong><\/p>\n\n\n\n<p>\u00bb Niveau d&rsquo;exp\u00e9rience: Exp\u00e9riment\u00e9<br>\u00bb Ann\u00e9es d&rsquo;exp\u00e9rience: 5 ans <br>\u00bb Niveau Acad\u00e9mique Minimum: Master<br><strong>Documents de candidature<\/strong><\/p>\n\n\n\n<p>\u00bb Lettre de motivation<br>\u00bb Curriculum Vitae<br><strong>NOTE: LES ARNAQUEURS SONT DE PLUS EN PLUS ASTUCIEUX! N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison! Et Si vous devriez le faire, que ce soit \u00e0 vos PROPRES RISQUES!<\/strong><\/p>\n\n\n\n<p><strong>Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Vous postulerez en envoyant votre\u00a0CV + lettre de motivation\u00a0par email \u00e0 l&rsquo;adresse suivante :\u00a0<a href=\"mailto:senserecruitment@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">senserecruitment@gmail.com<\/a><br>La date de cl\u00f4ture des candidatures est fix\u00e9e au 04 octobre 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une entreprise bas\u00e9e \u00e0 Douala recrute un RESPONSABLE DES OPERATIONS IT. Postulez via  senserecruitment@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[3212,22],"tags":[4,1641,3852],"villes":[135],"contrats":[148],"diplomes":[159],"louma_meta":{"emploi_title":"RESPONSABLE DES OPERATIONS IT","emplois_employeur":3046,"emplois_date_publication":"2021-09-27","emplois_heure_publication":"11:17","emplois_date_cloture":"2021-10-04","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"5","emploi_email":" senserecruitment@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22449"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22449"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22449"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22449"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22449"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}