{"id":22352,"date":"2021-09-24T14:27:47","date_gmt":"2021-09-24T12:27:47","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22352"},"modified":"2021-09-24T14:28:00","modified_gmt":"2021-09-24T12:28:00","slug":"responsable-daudit-interne-2","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/responsable-daudit-interne-2\/","title":{"rendered":"RESPONSABLE D\u2019AUDIT INTERNE"},"content":{"rendered":"\n<p> <\/p>\n\n\n\n<p>CARE International Cameroun<br>CDD d\u2019usage d\u2019un an renouvelable<br>A temps plein<br>Date-limite de candidature : 10\/10\/2021<\/p>\n\n\n\n<p><br>Contexte<br>Fond\u00e9 en 1945, CARE est l&rsquo;un des plus grands r\u00e9seaux humanitaires mondiaux, apolitique et non<br>confessionnel. Notre mission est de lutter contre l&rsquo;extr\u00eame pauvret\u00e9. CARE met en place des projets<br>d\u2019urgence et de d\u00e9veloppement dans des domaines compl\u00e9mentaires les uns des autres : \u00e9ducation,<br>s\u00e9curit\u00e9 alimentaire, sant\u00e9 eau potable, d\u00e9veloppement d\u2019activit\u00e9s g\u00e9n\u00e9ratrices de revenus en<br>impliquant les communaut\u00e9s et en collaborant avec des partenaires locaux. CARE d\u00e9fend les droits<br>des femmes et soutient leur autonomisation. En 2020, CARE France est intervenue dans une trentaine<br>de pays et a la charge manag\u00e9riale des bureaux du Liban, du Cameroun et de Madagascar. Le volume<br>annuel de ressources est de 38,4 M\u20ac. L\u2019\u00e9quipe pr\u00e9sente \u00e0 Paris regroupe une soixantaine de personnes<br>Pour en savoir plus sur CARE : www.carefrance.org<br>CARE France recherche pour le bureau de CARE International Cameroun un.e Responsable d\u2019audit<br>interne. Ce poste est ouvert aux nationaux et aux expatri\u00e9s.<\/p>\n\n\n\n<p><br>Descriptif de la mission<br>Sous la responsabilit\u00e9 de la Directrice Pays, et l\u2019autorit\u00e9 fonctionnelle de la Responsable du service<br>Risque, Audit et Contr\u00f4le du si\u00e8ge, le\/la Responsable d\u2019audit interne est l\u2019interlocuteur\/trice<br>privil\u00e9gi\u00e9.e concernant les audits, internes comme externes, ainsi que l\u2019archivage et les questions li\u00e9es<br>aux proc\u00e9dures internes de l\u2019association.<\/p>\n\n\n\n<p><br>LES PRINCIPALES FONCTIONS<br>G\u00e9rer les risques et renforcer la conformit\u00e9<\/p>\n\n\n\n<p><br>\u2022 Identifier l\u2019ensemble des sources de risques internes et externes, et \u00e9valuer les mesures<br>pr\u00e9ventives et la maitrise des risques identifi\u00e9s,<br>\u2022 Participer \u00e0 la gestion des risques de la mission ; proposer des mesures pour att\u00e9nuer les risques<br>identifi\u00e9s. Soutenir et suivre la mise en \u0153uvre du plan d\u2019action correspondant et \u00e0 la demande<br>du Directeur de pays et\/ou du RSI, participer aux actions entreprises en cas d\u2019alerte.<br>\u2022 V\u00e9rifier avec r\u00e9gularit\u00e9 les op\u00e9rations et leur conformit\u00e9 aux proc\u00e9dures (interne et bailleurs),<br>de formuler des recommandations et de suivre leur mise en \u0153uvre.<br>\u2022 Donner des conseils ind\u00e9pendants au SMT, aux \u00e9quipes sur le terrain et aux partenaires pour<br>une bonne op\u00e9rationnalisation et mise en \u0153uvre des programmes dans le respect des<br>politiques, \u00e0 la suite des audits ;<br>\u2022 Participe \u00e0 la mise \u00e0 jour des manuels de proc\u00e9dures comptables, financi\u00e8res, administratives<br>et de gestion des sous contrats<br>\u2022 Coordonner et conduire l\u2019audit interne de CARE et des partenaires, des projets ou services selon<br>le niveau de risque identifi\u00e9<br>\u2022 Bas\u00e9e sur l\u2019analyse des risques, d\u00e9velopper et mettant en \u0153uvre le plan d\u2019audit interne annuel<br>de la mission<br>\u2022 Alerter sur les \u00e9l\u00e9ments susceptibles de constituer un risque (financier, de conformit\u00e9 ou autre)<br>Assurer la r\u00e9ponse aux audits externes<br>\u2022 Planifier et mettre \u00e0 jour le calendrier des audits contractuels, le diffuser aux responsables<br>concern\u00e9s dans le bureau pays comme au si\u00e8ge ;<br>\u2022 Organiser le travail de pr\u00e9paration et de suivi des audits externes, par les D\u00e9partements<br>concern\u00e9s et par le partenaire (si besoin) de toute la documentation n\u00e9cessaire dans les d\u00e9lais<br>impartis<br>\u2022 Garantir la disponibilit\u00e9 et la coh\u00e9rence des documents et informations n\u00e9cessaires \u00e0 l\u2019audit :<br>v\u00e9rification de la pr\u00e9sentation des pi\u00e8ces support et gestion du flux d\u2019archives papiers ou<br>\u00e9lectroniques, en lien avec les interlocuteurs associ\u00e9s ;<br>\u2022 Pr\u00e9parer les audits externes en \u00e9troite collaboration avec le Grant et le Directeur Pays, ainsi<br>qu\u2019avec le service audit au si\u00e8ge. Faciliter et coordonner les audits externes et contribuer \u00e0 leur<br>r\u00e9ussite.<br>\u2022 Participer \u00e0 l\u2019analyse des synth\u00e8ses des audits externes pour restitutions aux \u00e9quipes<br>op\u00e9rationnelles et \u00e0 la coordination.<br>\u2022 Assurer la diss\u00e9mination, le suivi proactif de la mise en \u0153uvre des recommandations des audits<br>externes via la base de donn\u00e9es consolid\u00e9e des recommandations mise \u00e0 jour r\u00e9guli\u00e8rement.<br>Contribuer \u00e0 l\u2019\u00e9volution du processus interne de gestions des audits bailleurs et du contr\u00f4le interne<br>au sein de l\u2019organisation<br>\u2022 S\u2019assurer de la diffusion, de la bonne compr\u00e9hension et du respect des r\u00e8gles bailleurs et CARE<br>en mettant en \u0153uvre des formations et du renforcement de capacit\u00e9s en \u00e9troite collaboration<br>avec les coordonnateurs.<br>\u2022 Former et informer le personnel sur les proc\u00e9dures de contr\u00f4le interne approuv\u00e9es ;<br>\u2022 Faciliter la compr\u00e9hension et l\u2019int\u00e9riorisation des politiques et restrictions des bailleurs par les<br>staffs CARE et partenaires ;<br>\u2022 Participer aux r\u00e9unions de lancement et de cl\u00f4ture des projets en mettant l\u2019accent sur les<br>bonnes pratiques, les le\u00e7ons apprises et les risques \u00e0 att\u00e9nuer.<br>\u2022 Assurer le r\u00f4le de point focal fraude pour tous les cas de fraude\/corruption, non-respect des<br>principes d\u2019\u00e9thiques et valeurs de CARE<br>\u2022 S\u2019assurer de la bonne compr\u00e9hension du principe z\u00e9ro \u00ab 0 \u00bb tol\u00e9rance de CARE, assurer le<br>respect de la politique anti-fraude de CARE, par des formations et sensibilisations<br>\u2022 Conduire les investigations en toute confidentialit\u00e9 ou faciliter les enqu\u00eates men\u00e9es par des<br>experts externes ou le service audit risque contr\u00f4le du si\u00e8ge.<br>\u2022 Transmettre au si\u00e8ge les rapports d\u2019investigation<br>\u2022 Faire le suivi des mesures de mitigation propos\u00e9s dans le rapport d\u2019investigation<\/p>\n\n\n\n<p><br>Profil recherch\u00e9<br>Formation et Exp\u00e9riences :<br>\u2022 Titulaire d\u2019un dipl\u00f4me sup\u00e9rieur en audit, finance, gestion d\u2019entreprise, administration des<br>affaires ou \u00e9quivalent<br>\u2022 Exp\u00e9rience de 3 \u00e0 5 ans sur un poste similaire en cabinet d\u2019audit ou en coordination<br>financi\u00e8re\/administrative en ONG ; une exp\u00e9rience en ONG internationale est un atout<br>Comp\u00e9tences et qualit\u00e9s requises :<br>\u2022 Bonne maitrise des r\u00e8gles et proc\u00e9dures bailleurs (UE, USAID, Fonds mondial)<br>\u2022 Bonne ma\u00eetrise du pack Microsoft office<br>\u2022 \u00catre capable de maintenir des normes sociales, \u00e9thiques et organisationnelles<br>\u2022 Esprit d\u2019\u00e9quipe et de coop\u00e9ration, p\u00e9dagogue<br>\u2022 Capacit\u00e9 d\u2019adaptation, Flexibilit\u00e9 et sens de la diplomatie<br>\u2022 Tr\u00e8s bonne capacit\u00e9 d\u2019\u00e9coute et force de proposition<br>Langues : La ma\u00eetrise de l\u2019anglais est indispensable<\/p>\n\n\n\n<p><br>Conditions et modalit\u00e9s de candidature<br>Contrat : CDD d\u2019usage d\u2019un an renouvelable<br>Statut : Poste National ou Expatri\u00e9<br>Date de d\u00e9but : D\u00e8s que possible<br>Salaire : Selon le profil et la grille salariale de CARE + Avantages (mutuelle et logement)<br>Lieu de travail : Yaound\u00e9, Cameroun<\/p>\n\n\n\n<p><br>Comment postuler ?<br>Les candidat-e-s int\u00e9ress\u00e9-e-s doivent envoyer leur curriculum vitae et une lettre de motivation en<br>fran\u00e7ais \u00e0 l\u2019adresse : dnpsrecrutement@carefrance.org<br>Merci d\u2019indiquer la r\u00e9f\u00e9rence : \u00ab Responsable Audit Interne CMR \u00bb<br>Date-limite de candidature : 10\/10\/2021<\/p>\n\n\n\n<p>D\u00e9placement \u00e0 pr\u00e9voir dans les bureaux r\u00e9gionaux environ 30% du temps de travail.<br>CARE encourage la diversit\u00e9 dans ses recrutements. \u00c0 comp\u00e9tences \u00e9gales, CARE \u00e9tudie les<br>candidatures des femmes et des hommes de mani\u00e8re \u00e9quitable.<br>En raison d\u2019un grand nombre de candidatures, nous sommes dans l\u2019incapacit\u00e9 de r\u00e9pondre<br>individuellement \u00e0 chaque postulant. Seules les personnes s\u00e9lectionn\u00e9es seront contact\u00e9es<br>directement. Si vous n\u2019avez pas re\u00e7u de r\u00e9ponse de notre part dans les 4 semaines suivant l\u2019envoi de<br>vote candidature, veuillez consid\u00e9rer votre candidature comme non retenue.<br>Nous tenons \u00e9galement \u00e0 vous pr\u00e9ciser que : compte tenu de la RGPD (la R\u00e9glementation G\u00e9n\u00e9rale<br>sur la Protection des Donn\u00e9es), en cas de candidature non retenue, nous ne conserverons pas votre<br>dossier de candidature ni aucune information personnelle vous concernant. Tout dossier sera d\u00e9truit.<br>CARE France applique une tol\u00e9rance z\u00e9ro face \u00e0 l\u2019exploitation, aux abus sexuels et \u00e0 la maltraitance<br>des femmes et des enfants et mobilise tous ses employ\u00e9s dans la mise en \u0153uvre de sa politique<br>globale.<br>CARE France contactera les pr\u00e9c\u00e9dents employeurs des candidats \u00e0 ce poste pour d\u00e9terminer s\u2019ils ont<br>\u00e9t\u00e9 reconnus coupables d\u2019infraction aux codes de conduite en mati\u00e8re de harc\u00e8lement, d\u2019exploitation<br>ou d\u2019abus sexuel ou de fraude, ou bien si une enqu\u00eate \u00e9tait en cours au moment de la rupture du contrat de travail pr\u00e9c\u00e9dent, sur des faits de ce type. La transmission d\u2019une candidature sur ce poste entra\u00eene l\u2019acceptation de ce dispositif de recueil d\u2019informations aupr\u00e8s des pr\u00e9c\u00e9dents employeurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Care International recrute pour ses services au Cameroun un RESPONSABLE D\u2019AUDIT INTERNE. Postulez via dnpsrecrutement@carefrance.org<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[1594,23,1139],"tags":[53,3839,7],"villes":[136],"contrats":[236],"diplomes":[248,212,159],"louma_meta":{"emploi_title":"RESPONSABLE D\u2019AUDIT INTERNE","emplois_employeur":2916,"emplois_date_publication":"2021-09-24","emplois_heure_publication":"13:19","emplois_date_cloture":"2021-10-10","emplois_heure_cloture":"17:00","emplois_experience_min":"3","emplois_experience_max":"5","emploi_email":"dnpsrecrutement@carefrance.org"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22352"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22352"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2917"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22352"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22352"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22352"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}