{"id":22321,"date":"2021-09-24T03:34:23","date_gmt":"2021-09-24T01:34:23","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22321"},"modified":"2021-09-24T03:34:29","modified_gmt":"2021-09-24T01:34:29","slug":"05-profils-qualifies-en-marketing","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/05-profils-qualifies-en-marketing\/","title":{"rendered":"05 Profils Qualifi\u00e9s en Marketing"},"content":{"rendered":"\n<p>recherche des 05 profils qualifi\u00e9s aux postes suivants : <\/p>\n\n\n\n<p>\u2022 Community Manager\/Customer Service (01)<\/p>\n\n\n\n<p> \u2022 Customer Service\/Customer d\u00e9veloppement (03) <\/p>\n\n\n\n<p>\u2022 Google Ads\/SEO and Marketing Ninja (01) <\/p>\n\n\n\n<p>Les candidats id\u00e9aux seront responsables de la gestion et de l&rsquo;engagement avec la communaut\u00e9 en ligne et sur le terrain de l&rsquo;organisation d&rsquo;une mani\u00e8re qui renforce la notori\u00e9t\u00e9 de la marque. Ils ou elles travailleront de mani\u00e8re transversale avec les partenaires internes et externes pour comprendre les objectifs commerciaux afin de communiquer efficacement avec les clients. Entre autres, ils ou elles devront assurer les t\u00e2ches suivantes : <\/p>\n\n\n\n<p>Community Management :<\/p>\n\n\n\n<p> \u2022 D\u00e9velopper la strat\u00e9gie R\u00e9seaux Sociaux (Facebook, Instagram, Youtube, Twitter, TikTok, etc.) en collaboration avec l&rsquo;\u00e9quipe en d\u00e9finissant les objectifs de performance associ\u00e9s. <\/p>\n\n\n\n<p>\u2022 Concevoir la planification \u00e9ditoriale engageante (articles, posts, etc.) de sorte \u00e0 inciter les abonn\u00e9s de la page \u00e0 interagir sur les R\u00e9seaux Sociaux. <\/p>\n\n\n\n<p>\u2022 Mod\u00e9rer les commentaires, animer la communaut\u00e9 et g\u00e9rer l&rsquo;e-r\u00e9putation. <\/p>\n\n\n\n<p>\u2022 G\u00e9rer les prestataires de services et d\u00e9velopper des partenariats avec des influenceurs. <\/p>\n\n\n\n<p>Suivre et analyser les KPI sur tous les r\u00e9seaux sociaux, afin d&rsquo;\u00eatre porteur de solutions et d&rsquo;id\u00e9es.<\/p>\n\n\n\n<p> \u2022 Constituer et entretenir un r\u00e9seau d&rsquo;utilisateurs Super Fans ax\u00e9s sur l&rsquo;interaction sur nos r\u00e9seaux sociaux.<\/p>\n\n\n\n<p> \u2022 Sous la supervision du D\u00e9partement Marketing, participer \u00e0 une meilleure compr\u00e9hension du public cible en conduisant des recherches pour le march\u00e9 des pays ci-haut. <\/p>\n\n\n\n<p>\u2022 Rencontrer les utilisateurs volontaires qui aimeraient participer \u00e0 apporter des id\u00e9es pour de meilleurs services. <\/p>\n\n\n\n<p>Mener une veille concurrentielle, et proposer au top Management les actions \u00e0 mener pour une meilleure efficacit\u00e9 sur le terrain. <\/p>\n\n\n\n<p>\u2022 Pendant les rencontres ou \u00e0 toutes autres occasions : inciter<\/p>\n\n\n\n<p>Management les actions \u00e0 mener pour une meilleure efficacit\u00e9 sur le terrain.<\/p>\n\n\n\n<p> \u2022 Pendant les rencontres ou \u00e0 toutes autres occasions : inciter la communaut\u00e9 des utilisateurs du Cameroun, C\u00f4te d&rsquo;Ivoire, Gabon, S\u00e9n\u00e9gal, etc. \u00e0 faire un retour sur les changements souhait\u00e9s sur le service, et faire un rapport \u00e0 l&rsquo;\u00e9quipe pour la suite.<\/p>\n\n\n\n<p> \u2022 Sous la supervision de son sup\u00e9rieur, participer, animer, ou organiser au moins 2 panels de discussions Zoom\/Google Meet par mois, selon les canevas \u00e9tablis. Service \u00e0 la client\u00e8le : <\/p>\n\n\n\n<p>\u2022 Contacter les utilisateurs du Cameroun, C\u00f4te d&rsquo;Ivoire, Gabon, S\u00e9n\u00e9gal. \u00b7 Apporter des r\u00e9ponses rapides et pr\u00e9cises aux demandes de support client. <\/p>\n\n\n\n<p>\u2022 veille des probl\u00e8mes\/pr\u00e9occupations des clients publi\u00e9s via Facebook, Twitter, TikTok, Snapchat, LinkedIn, Instagram et d&rsquo;autres canaux sociaux ou examiner les sites Web. <\/p>\n\n\n\n<p>\u2022 R\u00e9pondre aux appels des utilisateurs pendant son quart de service, et reporter les probl\u00e8mes qu&rsquo;on ne peut pas r\u00e9soudre soi-m\u00eame \u00e0 la hi\u00e9rarchie.<\/p>\n\n\n\n<p> \u2022 Surveiller et rapporter r\u00e9guli\u00e8rement le trafic, les taux de r\u00e9ponse ; exploiter les donn\u00e9es pour identifier les tendances; aider les dirigeants \u00e0 affiner la strat\u00e9gie globale du service. <\/p>\n\n\n\n<p>Communication : \u00b7 En partenariat avec l&rsquo;\u00e9quipe manageriale, cr\u00e9er et diffuser des campagnes informatives et innovantes pour am\u00e9liorer la notori\u00e9t\u00e9 de la marque. <\/p>\n\n\n\n<p>\u2022 Identifier les lacunes dans les connaissances pour l&rsquo;am\u00e9lioration des processus, les opportunit\u00e9s de marketing et les id\u00e9es de produits et avoir leurs impressions sur les services et participer aux actions Marketing. <\/p>\n\n\n\n<p>\u2022 Participer \u00e0 la communication, r\u00e9dactions de contenus R\u00e9seaux Sociaux adapt\u00e9s aux groupes cibl\u00e9s. <\/p>\n\n\n\n<p>\u2022 Participer aux \u00e9v\u00e8nements organis\u00e9s par les Communaut\u00e9s vis\u00e9es afin de mieux parler de la soci\u00e9t\u00e9 et de sa mission.<\/p>\n\n\n\n<p> \u2022 R\u00e9pondre aux sollicitations\/ dol\u00e9ances des utilisateurs par mail, t\u00e9l\u00e9phone ou par autre forme de messagerie rapide. <\/p>\n\n\n\n<p>\u00b7 Bonne connaissance de son pays de r\u00e9sidence et des autres pays mentionn\u00e9s ci-haut. <\/p>\n\n\n\n<p>En tant que Community Manager\/Customer Service, il ou elle est au services et participer aux actions Marketing.<\/p>\n\n\n\n<p> Participer \u00e0 la communication, r\u00e9dactions de contenus R\u00e9seaux Sociaux adapt\u00e9s aux groupes cibl\u00e9s. <\/p>\n\n\n\n<p>Participer aux \u00e9v\u00e8nements organis\u00e9s par les Communaut\u00e9s vis\u00e9es afin de mieux parler de la soci\u00e9t\u00e9 et de sa mission. <\/p>\n\n\n\n<p>\u2022 R\u00e9pondre aux sollicitations\/ dol\u00e9ances des utilisateurs par mail, t\u00e9l\u00e9phone ou par autre forme de messagerie rapide.<\/p>\n\n\n\n<p> \u2022 Bonne connaissance de son pays de r\u00e9sidence et des autres pays mentionn\u00e9s ci-haut. En tant que Community Manager\/Customer Service, il ou elle devra :<\/p>\n\n\n\n<p> \u2022 Etre Camerounais.e, ou ressortissante de l&rsquo;un des pays suivants : C\u00f4te d&rsquo;Ivoire, Gabon, S\u00e9n\u00e9gal. \u00b7 \u00catre r\u00e9sident.e l\u00e9gal.e au Cameroun. <\/p>\n\n\n\n<p>\u2022 Poss\u00e9der un ordinateur portable et un smartphone pour les besoins de travail. \u00catre disponible pendant ses heures de travail.<\/p>\n\n\n\n<p> \u2022 Ce poste est pour du travail \u00e0 distance, mais le candidat id\u00e9al devra se mettre dans des dispositions professionelles de travail \u00e0 ses heures de service <\/p>\n\n\n\n<p>Qualit\u00e9s requises :<\/p>\n\n\n\n<p> Dynamique et proactive. <\/p>\n\n\n\n<p>Capacit\u00e9 d&rsquo;adaptation et flexibilit\u00e9 des heures de travail. <\/p>\n\n\n\n<p>\u2022 Capacit\u00e9 de travailler sous un minimum de supervision <\/p>\n\n\n\n<p>\u2022 Connaissance de Google Ads, SEO<\/p>\n\n\n\n<p> \u2022 Connaissance de Trello, Slack, Notions, Canva, etc. <\/p>\n\n\n\n<p>Qualifications : <\/p>\n\n\n\n<p>\u2022 Niveau Bac+2 minimum ou Sp\u00e9cialisation en Marketing \/ Communication. <\/p>\n\n\n\n<p>Mais pas obligatoire. Une exp\u00e9rience de plus de 2 ans pourrait valoir de qualification.<\/p>\n\n\n\n<p> \u2022 +2 an d&rsquo;exp\u00e9rience en marketing\/Comm\/Service Client souhait\u00e9, mais pas obligatoire <\/p>\n\n\n\n<p>\u2022 Forte capacit\u00e9 d&rsquo;analyse et de r\u00e9daction <\/p>\n\n\n\n<p>\u2022 Capacit\u00e9 de travailler sous un minimum de supervision Int\u00e9ress\u00e9.e de travailler dans un cadre inclusif o\u00f9 vos avis sont pris en consid\u00e9ration, r\u00e9pondre \u00e0 cette offre, ou envoyer un mail \u00e0 sbeyoun@gmail.com (CV avec au moins 02 REF\u00c9RENCES + Lettre de motivation) au plus tard Vendredi 24 Septembre 2021 \u00e0 23h GMT. <\/p>\n\n\n\n<p>Les candidatures f\u00e9minines sont encourag\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>recherche des 05 profils qualifi\u00e9s aux postes suivants : \u2022 Community Manager\/Customer Service (01) \u2022 Customer Service\/Customer d\u00e9veloppement (03) \u2022 Google Ads\/SEO and Marketing Ninja&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[24,300],"tags":[],"villes":[135],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"05 Profils Qualifi\u00e9s en Marketing","emplois_employeur":3046,"emplois_date_publication":"2021-09-24","emplois_heure_publication":"","emplois_date_cloture":"2021-09-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"sbeyoun@gmail.com "},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22321"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22321"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22321\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22321"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22321"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22321"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}