{"id":22177,"date":"2021-09-22T02:12:05","date_gmt":"2021-09-22T00:12:05","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=22177"},"modified":"2021-09-22T14:18:25","modified_gmt":"2021-09-22T12:18:25","slug":"stagiaire-pour-le-volet-education-plan-international","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/stagiaire-pour-le-volet-education-plan-international\/","title":{"rendered":"STAGIAIRE POUR LE VOLET EDUCATION-PLAN INTERNATIONAL"},"content":{"rendered":"\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Poste<\/strong><\/td><td><strong>STAGIAIRE POUR LE VOLET EDUCATION<\/strong><\/td><td><strong>Grade<\/strong><\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>Service et site<\/strong><\/td><td><strong>UNHCR \u2013 Yaounde et Douala<\/strong><\/td><td><strong>Date<\/strong><\/td><td>&nbsp;<\/td><\/tr><tr><td><strong>Superviseur&nbsp;<\/strong>(poste)&nbsp;:<\/td><td>Coordonnateur DAFI&nbsp;<\/td><\/tr><tr><td><strong>Objectif&nbsp;:&nbsp;<\/strong><\/td><td><em>Comment ce poste soutient-il la strat\u00e9gie et la mission de Plan&nbsp;? Illustrer comment il s\u2019inscrit dans la strat\u00e9gie globale.&nbsp;<\/em>&nbsp;&nbsp;Sous la supervision&nbsp;g\u00e9n\u00e9rale du Project Manager et directe de la Coordinatrice DAFI, le stagiaire en \u00e9ducation&nbsp;assurera,&nbsp;dans le cadre de la mise en \u0153uvre du Programme DAFI a Yaounde et Douala,&nbsp;la mise en \u0153uvre des diff\u00e9rentes t\u00e2ches li\u00e9es a l\u2019\u00e9ducation des enfants refugies scolaris\u00e9s de l\u2019enseignement sup\u00e9rieur et des formations professionnelles.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Dimensions du poste&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p>C\u2019est un stage d\u2019impr\u00e9gnation.<\/p>\n\n\n\n<p><strong>R\u00e9sultats finaux cl\u00e9s et responsabilit\u00e9s typiques&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p><em>\u00ab&nbsp;Travaux<\/em>&nbsp;\u00bb r\u00e9alis\u00e9s (<em>quoi<\/em>) et \u00ab&nbsp;<em>raisons<\/em>&nbsp;\u00bb (<em>pourquoi<\/em>), mais pas les \u00ab&nbsp;<em>actions<\/em>&nbsp;\u00bb ni la \u00ab&nbsp;<em>mani\u00e8re<\/em>&nbsp;\u00bb (<em>comment<\/em>)&nbsp;; inclure les indicateurs de succ\u00e8s.<\/p>\n\n\n\n<ul><li>Assurer l\u2019accueil des usagers r\u00e9fugi\u00e9s ayant des besoins dans le domaine de l\u2019\u00e9ducation et les r\u00e9f\u00e9rer \u00e0 l\u2019Assistant DAFI pour actions ad\u00e9quates&nbsp;;<\/li><li>Assister l\u2019Assistant DAFI par les descentes \u00e0 effectuer dans les \u00e9tablissements scolaires du tertiaire et des institutions de formation professionnelle accueillant les r\u00e9fugi\u00e9s et assurer le suivi et l\u2019effectivit\u00e9 de la cible;<\/li><li>Assister l\u2019Assistant DAFI dans les descentes \u00e9ventuelles \u00e0 domicile pour le suivi des \u00e9tudiants r\u00e9fugi\u00e9s ayant des pr\u00e9occupations dans leur \u00e9ducation&nbsp;;<\/li><li>Assister l\u2019Assistant DAFI dans l\u2019organisation d\u2019une op\u00e9ration des cours de soutien scolaire en faveur des enfants\/\u00e9l\u00e8ves r\u00e9fugi\u00e9s cibl\u00e9s, en classe d\u2019examen, \u00e0 faibles r\u00e9sultats en collaboration avec l\u2019Assistant \u00e9ducation du projet social&nbsp;;&nbsp;<\/li><li>Appuyer et accompagner l\u2019Assistant DAFI dans la collecte et enregistrement des r\u00e9sultats scolaires pour le compte de l\u2019ann\u00e9e 2020\/2021ainsi que l\u2019organisation de la s\u00e9lection des nouveaux boursiers&nbsp;;<\/li><li>Participer \u00e0 toutes autres activit\u00e9s en fonction de la n\u00e9cessit\u00e9.<\/li><\/ul>\n\n\n\n<p><strong>G\u00e9rer les probl\u00e8mes&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p><em>Application des connaissances requises pour le poste, complexit\u00e9 des probl\u00e8mes g\u00e9r\u00e9s et le degr\u00e9 d\u2019investigation, d\u2019analyse et de r\u00e9flexion cr\u00e9ative requis pour les r\u00e9soudre.<\/em><\/p>\n\n\n\n<ul><li>Etre capable d\u2019anticiper sur les conflits, les analyser et proposer des solutions;<\/li><\/ul>\n\n\n\n<p><strong>Communication et relations de travail&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p><em>Contacts de travail \u00e0 l\u2019int\u00e9rieur et \u00e0 l\u2019ext\u00e9rieur de l\u2019organisation&nbsp;; inclut l\u2019objectif et le niveau (\u00e9lev\u00e9, moyen, faible) de contact.<\/em><\/p>\n\n\n\n<p><strong>Connaissances, comp\u00e9tences et comportements requis pour r\u00e9aliser les objectifs du poste&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p>Connaissances&nbsp;<\/p>\n\n\n\n<ul><li>Dipl\u00f4me universitaire ou dipl\u00f4me&nbsp;BAC+3 en Sciences de l\u2019Education, Sciences Sociales, Sociologie, Droit, ou en Planification des Projets.<\/li><\/ul>\n\n\n\n<p>Comp\u00e9tences<\/p>\n\n\n\n<ul><li>Bonne communication et comp\u00e9tences en TIC&nbsp;(Word, Excel, PowerPoint).<\/li><\/ul>\n\n\n\n<ul><li>Avoir de grandes capacit\u00e9s r\u00e9dactionnelles&nbsp;(anglais et fran\u00e7ais) ;<\/li><li>Bonnes capacit\u00e9s de Planification et d\u2019organisation<\/li><\/ul>\n\n\n\n<p>Comportements<\/p>\n\n\n\n<ul><li>Bonnes capacit\u00e9s d&rsquo;\u00e9coute<\/li><li>Bonnes relations interpersonnelles<\/li><li>Ouvert aux feedbacks et la volont\u00e9 d&rsquo;adopter de nouvelles approches et processus<\/li><li>Bon membre d\u2019\u00e9quipe<\/li><li>Soucieux de la s\u00e9curit\u00e9<\/li><li>Bonne pr\u00e9sentation et l&rsquo;attention aux d\u00e9tails<br>&nbsp;<\/li><\/ul>\n\n\n\n<p><strong>Environnement et exigences&nbsp;physiques :&nbsp;<\/strong><\/p>\n\n\n\n<p><em>Il peut s\u2019agir d\u2019un \u00ab&nbsp;environnement administratif typique&nbsp;\u00bb&nbsp;; noter si le poste inclut le port de charges lourdes, de l\u2019escalade, de nombreux d\u00e9placements, etc.<\/em><\/p>\n\n\n\n<p>D\u00e9placement fr\u00e9quent dans les \u00e9tablissements scolaires et dans les familles.<\/p>\n\n\n\n<p><strong>Veuillez joindre un organigramme de votre service&nbsp;:&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>Location: Yaounde et Douala<\/strong><\/p>\n\n\n\n<p><strong>Closing Date: 30 septembre 2021<\/strong><\/p>\n\n\n\n<p><em>Equality, diversity and inclusion is at the very heart of everything that Plan International stands for.<\/em><\/p>\n\n\n\n<p><em>We want Plan International to reflect the diversity of the communities we work with, offering equal opportunities to everyone regardless of age, disability, gender reassignment, marriage and civil partnership, pregnancy and maternity, race, religion or belief, sex or sexual orientation.<\/em><\/p>\n\n\n\n<p><em>Plan International is based on a culture of inclusivity and we strive to create a workplace environment that ensures every team, in every office, in every country, is rich in diverse people, thoughts, and ideas.<\/em><\/p>\n\n\n\n<p><em>We foster an organisational culture that embraces our commitment to racial justice, gender equality, girls\u2019 rights and inclusion.<\/em><\/p>\n\n\n\n<p><em>Plan International believes that in a world where children face so many threats of harm, it is our duty to ensure that we, as an organisation, do everything we can to keep children safe. This means that we have particular responsibilities to children that we come into contact with and we must not contribute in any way to harming or placing children at risk.&nbsp;<\/em><\/p>\n\n\n\n<p><em>A range of pre-employment checks will be undertaken in conformity with Plan International&rsquo;s Safeguarding Children and Young People policy. Plan International also participates in the&nbsp;<a href=\"https:\/\/www.schr.info\/the-misconduct-disclosure-scheme\">Inter Agency Misconduct Disclosure Scheme.<\/a>&nbsp;In line with this scheme we will request information from applicants previous employers about any findings of sexual exploitation, sexual abuse and\/or sexual harassment during employment, or incidents under investigation when the applicant left employment. By submitting an application, the job applicant confirms their understanding of these recruitment procedures.&nbsp;<\/em><a href=\"https:\/\/jobs.plan-international.org\/talentcommunity\/apply\/715011101\/?locale=en_GB\">Apply now \u00bb<\/a>Find similar jobs:&nbsp;<a href=\"https:\/\/jobs.plan-international.org\/go\/Programmes-%28fr_FR%29\/1415201\/\">Programmes (fr_FR),<\/a><a href=\"https:\/\/jobs.plan-international.org\/go\/Programmes-%28es_ES%29\/1415101\/\">Programmes (es_ES),<\/a><a href=\"https:\/\/jobs.plan-international.org\/go\/Programmes-%28en_US%29\/1415001\/\">Programmes (en_US),<\/a><a href=\"https:\/\/jobs.plan-international.org\/go\/Programmes-%28en_GB%29\/1414901\/\">Programmes (en_GB)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poste STAGIAIRE POUR LE VOLET EDUCATION Grade &nbsp; Service et site UNHCR \u2013 Yaounde et Douala Date &nbsp; Superviseur&nbsp;(poste)&nbsp;: Coordonnateur DAFI&nbsp; Objectif&nbsp;:&nbsp; Comment ce poste&#8230;<\/p>\n","protected":false},"author":4,"comment_status":"open","ping_status":"closed","template":"","categories":[252,402],"tags":[],"villes":[135,136],"contrats":[234],"diplomes":[212,159],"louma_meta":{"emploi_title":"STAGIAIRE POUR LE VOLET EDUCATION-PLAN INTERNATIONAL ","emplois_employeur":2828,"emplois_date_publication":"2021-09-22","emplois_heure_publication":"","emplois_date_cloture":"2021-09-30","emplois_heure_cloture":"","emplois_experience_min":"1","emplois_experience_max":"2","emploi_email":"https:\/\/jobs.plan-international.org\/talentcommunity\/apply\/715011101\/?locale=en_GB"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22177"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=22177"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/22177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/1432"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=22177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=22177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=22177"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=22177"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=22177"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=22177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}