{"id":21786,"date":"2021-09-15T23:17:12","date_gmt":"2021-09-15T21:17:12","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=21786"},"modified":"2021-09-15T23:17:19","modified_gmt":"2021-09-15T21:17:19","slug":"assistante-pilier-3","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/assistante-pilier-3\/","title":{"rendered":"ASSISTANT(E) PILIER 3"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">PROFIL DE POSTE<\/h3>\n\n\n\n<p><strong>Titre du Poste :<\/strong>ASSISTANT(E) PILIER 3 : RENFORCEMENT INSTITUTIONNEL<br>D\u00e9partement&nbsp;&nbsp;&nbsp; Programme<br><strong>Projet&nbsp;<\/strong>: Redressement Economique et Social Inclusif du Lac Tchad \u2014 RESILAC<br><br>Partenariats&nbsp; : En consortium sous le lead de ACF avec CARE et le groupe URD.<br>Les partenaires de mise en \u0153uvre op\u00e9rationnelle sont le CCFD repr\u00e9sent\u00e9 par le comit\u00e9 dioc\u00e9sain de d\u00e9veloppement (CDD), ALDEPA et AJED-MR.<br>Nationalit\u00e9&nbsp;&nbsp;&nbsp; Camerounaise.<br><br><strong>Comp\u00e9tences requises&nbsp;&nbsp;&nbsp;<\/strong><br>&nbsp;&nbsp; &nbsp;<br>Niveau d&rsquo;\u00e9tude : Minimum BAC + 3 (Licence) en Comptabilit\u00e9, sociologie, \u00e9tudes de d\u00e9veloppement ou domaine connexes.<br>Bonne ma\u00eetrise de la comptabilit\u00e9, Gestion, administration d&rsquo;entreprise ou domaine connexe.<br>Gestion de sous-subventions ou sous-contrats.<br><br>Techniques et outils de renforcement institutionnel\/organisationnel (OSC\/Communes).<br>Bonne ma\u00eetrise des outils de diagnostic et planification participative.<br>Bonne capacit\u00e9 de supervision formative et coaching d&rsquo;acteurs locaux. Forte capacit\u00e9 d&rsquo;adaptabilit\u00e9 \u00e0 un contexte avec des contraintes s\u00e9curitaires.<br>Bonne Capacit\u00e9 de gestion de stress.<br><br>Parlant le fran\u00e7ais, le Fulfuld\u00e9 et autres langues locales.<br>Parfaite connaissance de la zone d&rsquo;intervention de la r\u00e9gion de l&rsquo;Extr\u00eame Nord et d&rsquo;au moins deux zones d&rsquo;intervention du projet.<br>Localisation: L&rsquo;Assistant(e) pilier 3 sera bas\u00e9 (e) \u00e0 Maroua avec comme zone d&rsquo;intervention les sites du projet dans la R\u00e9gion de I &lsquo;Extr\u00eame Nord. Le projet est r\u00e9gional pour le Bassin du Lac Tchad \u2014 Tchad, Niger, Nigeria et Cameroun \u2014 avec une coordination r\u00e9gionale bas\u00e9 \u00e0 Ndjamena.<br>Lien hi\u00e9rarchique:L&rsquo; Assistant(e) sera plac\u00e9 (e) sous la Supervision hi\u00e9rarchique de la Responsable Pilier<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp; Le Gestionnaire de projet de CARE.<br>Les RP2A et 2B.<br>Les Animateurs Communaux de D\u00e9veloppement Economique et Social (ACDES).<br>Les Animateurs Cha\u00eene de valeurs.<br>Les Charg\u00e9s de projet des OSC.<br>Les Superviseurs terrain.<br>Les teclmiciens TICOM et SAME.<br><br><strong>Temps<\/strong><br>Travail :&nbsp;&nbsp;&nbsp;&nbsp; 40 heures par semaine<br><br><strong>RAISON D&rsquo;ETRE DU POSTE<\/strong><br>En appui direct \u00e0 la Responsable du pilier 3 : renforcement institutionnel, I &lsquo; Assistant \/te contribuera \u00e0 la r\u00e9alisation des objectifs suivants :<br><strong>I.&nbsp;<\/strong>Accroitre la capacit\u00e9 organisationnelle \/ institutionnelle des Communes (Mora, Dargala, Koza et Mindif) ;<br><strong>2.&nbsp;<\/strong>Accroitre la capacit\u00e9 organisationnelle \/ institutionnelle des OSC (ALDEPA et AJED-MR).<br>TACHES PRINCIPALES<br><br><strong>\u2022 T\u00e2che I&nbsp;<\/strong>: Accroitre la capacit\u00e9 organisationnelle et institutionnelle des Communes. Accompagner les communes et les OSC dans l&rsquo;\u00e9laboration des plans d&rsquo;action mensuels en lien avec leurs cadres de performance ;<br>Accompagner les communes dans l&rsquo;\u00e9laboration et la production dans les d\u00e9lais des rapports financiers ;<br>Assurer le suivi de la mise en \u0153uvre des plans de renforcement des capacit\u00e9s ; Effectuer des s\u00e9ances de coaching (Gestion administrative et financi\u00e8re de la subvention, CCODES, \u00e9tats de paiement, etc.) et de supervision formative mensuelles sur les outils transf\u00e9r\u00e9s afin d&rsquo;assurer la remont\u00e9e des donn\u00e9es suivant les d\u00e9lais de rapportage ;<br>&nbsp; Appuyer les ACDES dans l&rsquo;organisation des r\u00e9unions de cadres de Concertation de D\u00e9veloppement Economique et Social (CCODES) et la mise en relation des actions de d\u00e9veloppement et humanitaires ;<br>&nbsp; Participer aux r\u00e9unions terrain afin d&rsquo;assurer la coordination des activit\u00e9s entres les OSC et les communes.<br><br>\u2022&nbsp;&nbsp;<strong>&nbsp; T\u00e2che 2&nbsp;<\/strong>: Accroitre la capacit\u00e9 organisationnelle et institutionnelle des OSC<br>Accompagner les communes dans l&rsquo;\u00e9laboration et la production dans les d\u00e9lais des rapports financiers ;<br>Assurer le suivi de la mise en \u0153uvre des plans de renforcement des capacit\u00e9s ;<br>Effectuer des s\u00e9ances de coaching et de supervision formative mensuelles aux sur la gestion administrative et financi\u00e8re de la subvention et sur les outils transf\u00e9r\u00e9s \u2022&nbsp;&nbsp; Amener les OSC \u00e0 accompagner des OBC ;<br>&nbsp; Apporter un appui aux OSC dans la pr\u00e9paration et la conduite des actions de plaidoyer.<br><br><strong>\u2022&nbsp;&nbsp;&nbsp; T\u00e2che 3&nbsp;<\/strong>: Autres t\u00e2ches transversales et\/ou connexes<br>Apporter un soutien au Subgrant Officer dans l&rsquo;analyse des rapports financiers des communes et OSC \u2022<br>&nbsp; Elaborer et soumettre \u00e0 la RP3 un rapport mensuel d&rsquo;activit\u00e9s et un plan d&rsquo;action du mois suivant ;<br>&nbsp; Repr\u00e9senter la RP3 en cas d&rsquo;absence dans la zone du projet si dument mandat\u00e9 ;&nbsp;&nbsp; Travailler en bonne collaboration avec l&rsquo;\u00e9quipe du projet, du programme et des organisations partenaires ;<br>&nbsp; Assister aux r\u00e9unions de l&rsquo;\u00e9quipe du projet ;<br><br><strong>&nbsp; Contribuer \u00e0 la capitalisation du processus de renforcement de capacit\u00e9s et de gestion des subventions par les OSC et communes.<\/strong><br><strong>LIVRABLES ATTENDUS<\/strong><br>Les livrables attendus sont les suivants :<br>\u2022&nbsp;&nbsp;&nbsp; Un (01) rapport mensuel d&rsquo;activit\u00e9s + un (01) planning mensuel avec en annexes<br>&nbsp; Les fiches de coaching + feuilles de pr\u00e9sence ;<br>&nbsp; Le rapport de suivi du progr\u00e8s du d\u00e9veloppement organisationnel de chaque commune ;<br>&nbsp; Le rapport de suivi du progr\u00e8s du d\u00e9veloppement organisationnel de chaque OSC.<br>\u2022&nbsp;&nbsp;&nbsp; Des rapports de mission ;<br>\u2022&nbsp;&nbsp;&nbsp; Les compte-rendus des r\u00e9unions auxquelles l&rsquo;Assistant (e) a pris part.<br><br>Le pr\u00e9sent appel \u00e0 candidature est restreint \u00e0 la zone de Maroua, il sera affich\u00e9 chez les partenaires locaux (OSC\/OBCs et communes).<br>Les dossiers de candidatures r\u00e9dig\u00e9s en fran\u00e7ais et\/ou en anglais seront transmis dans une enveloppe et devront porter la mention :&nbsp;<strong>RECRUTEMENT D&rsquo;UN(E) ASSISTANT(E) PILIER 3 : RENFORCEMENT INSTITUTIONNEL &#8211; PROJET RESILAC.<\/strong><\/p>\n\n\n\n<p>La date limite de transmission des dossiers de candidatures est ar\u00eat\u00e9e \u00e0 dix (10) jours ouvrables (06 jours de la semaine sans le dimanche) \u00e0 15h00, \u00e0 compter de la date de publication du poste.<br>date limite 18 septembre 15h<br><br><strong>NB:&nbsp; Les candidatures f\u00e9minines sont vivement encourag\u00e9es<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Care recrute dans le cadre d&rsquo;un projet avec des partenaires, un(e) ASSISTANT(E) PILIER 3. Les dossiers de candidatures r\u00e9dig\u00e9s en fran\u00e7ais et\/ou en anglais seront transmis dans une enveloppe et devront porter la mention : RECRUTEMENT D&rsquo;UN(E) ASSISTANT(E) PILIER 3 : RENFORCEMENT INSTITUTIONNEL &#8211; PROJET RESILAC.<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[21,282,1139],"tags":[3750,53,8],"villes":[141],"contrats":[148],"diplomes":[212,159],"louma_meta":{"emploi_title":"ASSISTANT(E) PILIER 3","emplois_employeur":2916,"emplois_date_publication":"2021-09-15","emplois_heure_publication":"22:13","emplois_date_cloture":"2021-09-18","emplois_heure_cloture":"15:00","emplois_experience_min":"","emplois_experience_max":"","emploi_email":""},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/21786"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=21786"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/21786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/2917"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=21786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=21786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=21786"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=21786"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=21786"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=21786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}