{"id":21518,"date":"2021-09-10T11:57:38","date_gmt":"2021-09-10T09:57:38","guid":{"rendered":"https:\/\/louma-jobs.com\/cameroun\/?post_type=emplois&#038;p=21518"},"modified":"2021-09-10T11:57:44","modified_gmt":"2021-09-10T09:57:44","slug":"gestionnaire-secretariat-bureautique","status":"publish","type":"emplois","link":"https:\/\/louma-jobs.com\/cameroun\/recrutements-emplois-stages\/2021\/gestionnaire-secretariat-bureautique\/","title":{"rendered":"Gestionnaire Secr\u00e9tariat Bureautique"},"content":{"rendered":"\n<p><strong>Description<\/strong><\/p>\n\n\n\n<p>Entreprise:\u00a0<a href=\"http:\/\/hector.net\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hector.net<\/a><\/p>\n\n\n\n<p>Categories: emploi et stage<br>L\u2019employ\u00e9 (e) recrut\u00e9(e) sera charg\u00e9 (e) de travailler comme secr\u00e9taire dans un cyber caf\u00e9\u00a0<\/p>\n\n\n\n<p><strong>Missions \/ Responsabilit\u00e9s \/ Activit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Effectuer des travaux de saisie, faire des impressions, faire des photocopies, scannage des documents, nettoyage du secretariat<\/li><li>G\u00e9rer la connexion internet<\/li><li>Pr\u00e9parer des comptes rendus journaliers, hebdomadaires.<\/li><li>faire l\u2019 inventaire des consommables<\/li><\/ul>\n\n\n\n<p><strong>Comp\u00e9tences \/ Exigences \/ Qualit\u00e9s<\/strong><\/p>\n\n\n\n<ul><li>Avoir la ma\u00eetrise de l\u2019outil informatique et des logiciels bureautique<\/li><li>Avoir au moins 01 an d\u2019exp\u00e9rience en mati\u00e8re de travaux de secr\u00e9tariat ou de gestion d\u2019un cyber caf\u00e9.<\/li><li>savoir mettre en forme les memoires et rapport des etudiants<\/li><li>avoir l\u2019 experience dans l\u2019utilisation des photocopieurs et imprimante ricoh<\/li><li>avoir les connaissance basique dans le depannage d\u2019un copieur (retirer un bourrage, charger l\u2019encre)<\/li><li>savoir travailler de maniere autonomme<\/li><li>Trait de personalite<\/li><li>Humble, courtoix, accueillant, honnete<\/li><\/ul>\n\n\n\n<p><strong>Profil du candidat<\/strong><\/p>\n\n\n\n<p>\u00bb Niveau d&rsquo;exp\u00e9rience: Junior \/ D\u00e9butant<br>\u00bb Ann\u00e9es d&rsquo;exp\u00e9rience: 1 an <br><strong>Documents de candidature<\/strong><\/p>\n\n\n\n<p>\u00bb Curriculum Vitae<br><strong>NOTE: LES ARNAQUEURS SONT DE PLUS EN PLUS ASTUCIEUX! N&rsquo;envoyez jamais de l&rsquo;argent \u00e0 un inconnu au cours d&rsquo;un recrutement quelle que soit la raison! Et Si vous devriez le faire, que ce soit \u00e0 vos PROPRES RISQUES!Instructions de candidature<\/strong><\/p>\n\n\n\n<p>Envoyer votre CV \u00e0 l\u2019adresse suivante :\u00a0<a href=\"mailto:jiegouenkande@gmail.com\" target=\"_blank\" rel=\"noreferrer noopener\">jiegouenkande@gmail.com<\/a><br>WhatsApp:\u00a06 75 29 74 43<br>Tel\u00a0: 6 75 29 74 43\/ 690 17 92 33<\/p>\n","protected":false},"excerpt":{"rendered":"<p> ETS Hector.net recrute pour les besoins de ses services un Gestionnaire Secr\u00e9tariat Bureautique. Postulez via l&rsquo;adresse \u00e9lectronique  jiegouenkande@gmail.com<\/p>\n","protected":false},"author":8,"comment_status":"open","ping_status":"closed","template":"","categories":[22,2519],"tags":[3721,245,7],"villes":[136],"contrats":[234],"diplomes":[248,278],"louma_meta":{"emploi_title":"Gestionnaire Secr\u00e9tariat Bureautique ","emplois_employeur":3046,"emplois_date_publication":"2021-09-10","emplois_heure_publication":"10:53","emplois_date_cloture":"2021-10-05","emplois_heure_cloture":"17:00","emplois_experience_min":"","emplois_experience_max":"1","emploi_email":"jiegouenkande@gmail.com"},"_links":{"self":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/21518"}],"collection":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois"}],"about":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/types\/emplois"}],"author":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/comments?post=21518"}],"version-history":[{"count":0,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/emplois\/21518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media\/9483"}],"wp:attachment":[{"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/media?parent=21518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/categories?post=21518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/tags?post=21518"},{"taxonomy":"villes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/villes?post=21518"},{"taxonomy":"contrats","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/contrats?post=21518"},{"taxonomy":"diplomes","embeddable":true,"href":"https:\/\/louma-jobs.com\/cameroun\/wp-json\/wp\/v2\/diplomes?post=21518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}